{"id":6200,"date":"2017-05-12T09:14:53","date_gmt":"2017-05-12T07:14:53","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=6200"},"modified":"2024-06-11T14:03:43","modified_gmt":"2024-06-11T12:03:43","slug":"zahl-der-voegel-geht-zurueck","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/","title":{"rendered":"Zahl der V\u00f6gel geht zur\u00fcck"},"content":{"rendered":"<div id=\"pl-6200\" class=\"panel-layout\">\n<div id=\"pg-6200-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-6200-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-6200-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6187\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg\" alt=\"Kiebitz\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/a><\/p>\n<p>Wenn man vor knapp 30 Jahren aus dem Fenster geblickt hat, war die Landschaft in Deutschland gepr&auml;gt von viel Natur, Waldfl&auml;chen, Ackerbau auf Kleinfl&auml;chen und nicht sonderlich gro&szlig;en St&auml;dten: der ideale Nist- und Brutplatz f&uuml;r eine Vielzahl an V&ouml;geln. Deutschland ist reich gesegnet mit einer hohen Anzahl an Vogelarten. Insgesamt br&uuml;ten, nisten und leben hier in etwa 250 bis 300 Vogelarten. Dabei nicht mit eingerechnet sind V&ouml;gel, die als Zugv&ouml;gel Deutschland queren und sich nicht f&uuml;r eine l&auml;ngere Zeit aufhalten.<\/p>\n<p>In den letzten Jahrzehnten sind nur wenige Vogelarten in Deutschland ausgestorben, wie zum Beispiel die Doppelschnepfe oder der imposante Schlangenadler. Andere Vogelarten sind durch den Klimawandel vom S&uuml;den nach Deutschland gekommen. Das alles klingt nun nicht sonderlich besorgniserregend. Dennoch schlagen die Natursch&uuml;tzer Alarm: Die Anzahl an Brutpaaren in landwirtschaftlichen Gebieten Europas ist den letzten 30 Jahren um 300 Millionen geschrumpft &#8211; ein R&uuml;ckgang von 57 Prozent!<\/p>\n<h2 id=\"manche-vogelarten-sind-besonders-betroffen\">Manche Vogelarten sind besonders betroffen<\/h2>\n<p>Durch den radikalen Wandel der Landwirtschaft von kleinen Fl&auml;chen zu Gro&szlig;betrieben und der hochgradig maschinellen Bearbeitung der &Auml;cker hat sich das Leben einiger V&ouml;gel dramatisch ver&auml;ndert. Zus&auml;tzlich sind die deutschen St&auml;dte stark gewachsen, was den Lebensraum mancher Feld- und Sumpfv&ouml;gel ebenfalls beengt hat. So zeigt ein Drittel aller deutschen Vogelarten signifikante Bestandsabnahmen. Seit Jahren ist das Rebhuhn schon auf der &#8222;Roten Liste&#8220; gef&auml;hrdeter Tierarten in Deutschland und wird aus Artenschutzgr&uuml;nden kaum gejagt. Eine Verringerung des Bestandes von &uuml;ber 84 Prozent in 25 Jahren spricht dabei B&auml;nde. &Auml;hnlich geht es dem Kiebitz, dem Braunkehlchen oder der Uferschnepfe. Die Liste l&auml;sst sich beliebig fortsetzen.<\/p>\n<h2 id=\"grnde-fr-den-rckgang\">Gr&uuml;nde f&uuml;r den R&uuml;ckgang<\/h2>\n<p>Neben der Ver&auml;nderung der Bearbeitung landwirtschaftlicher Fl&auml;chen und der Maximierung von Ackerfl&auml;chen und Produktion gibt es eine Vielzahl an weiteren Gr&uuml;nden f&uuml;r den R&uuml;ckgang ganzer Brutkolonien. Einer dieser Gr&uuml;nde wird dir auf den ersten Blick als gar nicht so unangenehm vorkommen: Es gibt einen signifikanten R&uuml;ckgang in der Verbreitung und in der Anzahl von Insekten.<\/p>\n<p>Durch Pestizide und Insektengifte wurden so manche Insektenarten um bis zu 90 Prozent dezimiert. Solch ein tiefgreifender R&uuml;ckgang der Hauptnahrungsquelle mancher Vogelarten geht nicht spurlos an deren Population vor&uuml;ber. Ohne Nahrung wird automatisch weniger gebr&uuml;tet, um die eigenen Energiereserven nicht zu verzehren. Schwacher und kranker Nachwuchs kann dann nicht ausreichend versorgt werden. Das ist ein Teufelskreislauf, der schleichend in den letzten Jahren an der Anzahl vieler deutscher Vogelarten genagt hat.<br \/>\nLeider steht Deutschland in dieser Hinsicht nicht alleine da. Andere europ&auml;ische L&auml;nder beobachten eine &auml;hnliche Entwicklung und auch weltweit ist eine Abnahme von Vogelbest&auml;nden kaum noch aufzuhalten. An dieser Stelle stellt sich die Frage, was du tun kannst, um den bedrohten Vogelarten zu helfen.<\/p>\n<h2 id=\"brutsttte-garten-und-futter-fr-den-seltenen-zaungast\">Brutst&auml;tte Garten und Futter f&uuml;r den seltenen Zaungast<\/h2>\n<p>V&ouml;gel suchen einen sicheren Unterschlupf f&uuml;r ihren Nachwuchs. Egal ob Hochbr&uuml;ter, die hohe B&auml;ume und Felsvorspr&uuml;nge bevorzugen, oder Bodenbr&uuml;ter, die ihr Nest auf dem Boden bauen &#8211; eine unber&uuml;hrte, ruhige Ecke wirkt Wunder. Solltest du in deinem Garten einen Platz haben, an den du sowieso nur selten gehst, weil er vielleicht zu abgelegen oder ungenutzt ist, dann ist dort der ideale Punkt, um mit deinem Rettungseinsatz zu starten. Nistk&auml;sten in hoher und mittelhoher H&ouml;he gibt es f&uuml;r die verschiedensten Vogelarten und diese lassen sich an B&auml;umen, frei h&auml;ngend oder an einem Pfosten sicher befestigen.<\/p>\n<p>Achte darauf, ob es in deiner Nachbarschaft viele <a href=\"\/magazin\/katzen\/rund-um-den-freigang\/\">Freig&auml;nger-Katzen<\/a> gibt. Dementsprechend sind die Nistpl&auml;tze gegen den Zugriff der Katzen abzusichern. &Auml;ste vom letzten Garteneinsatz k&ouml;nnen dort auch gerne liegen bleiben und bilden mit einem dichten Gestr&uuml;pp den perfekten Ansatzpunkt f&uuml;r den Nestbau manches Bodenbr&uuml;ters. Auch Nistmaterial, wie Stroh und feine &Auml;ste, sollte einfach einmal nicht so schnell entsorgt werden. Zur Brutzeit werden die feinen &Auml;ste wie von Geisterhand verschwinden und kunstvoll in das n&auml;chste Nest eingebaut. Ein paar nicht abgeschnittene Disteln und Altgras im Herbst locken zudem Insekten zum &Uuml;berwintern an: ein Festmahl f&uuml;r V&ouml;gel.<\/p>\n<p>Neben dem gesch&uuml;tzten Brutplatz mangelt es den meisten bedrohten Vogelarten an ausreichend Nahrung. Auch hier kannst du Abhilfe schaffen. Wenn du statt Nadelholz und Zierbaum lieber Wei&szlig;dorn (Crateagus monogyna) und Schwarzen Holunder (Sambucus nigra) pflanzt. So f&uuml;hlen sich der Dompfaff und die Singdrossel bei dir wohl. Die B&uuml;sche eignen sich ideal f&uuml;r den Nestbau und bieten zudem Beeren und Fr&uuml;chte f&uuml;r die V&ouml;gel. &Auml;hnlich gut eignen sich die dornigen Berberitzen. Auch hier ist die Kombination aus Schutz und Nahrung ideal, da sich in dieses Geb&uuml;sch sicherlich keine Katze wagt. Wenn du nun glaubst, dass sich nur wilde, ungeschnittene B&uuml;sche f&uuml;r Heckenbr&uuml;ter eignen, irrst du dich. Auch eine dichte, fein getrimmte Hecke kann das bieten, was der kleine Vogel zur Aufbrut ben&ouml;tigt: ein enges, undurchdringliches Dickicht.<\/p>\n<h2 id=\"fttern-nicht-nur-im-kalten-winter\">F&uuml;ttern nicht nur im kalten Winter<\/h2>\n<p>Leider finden nur wenige bedrohte Vogelarten den Weg zu deinem winterlichen Futterplatz. Meist sind es die noch eher weit verbreiteten Amseln oder Meisen, die sich dort tummeln. Doch auch ihnen hilft im harten Winter das ein oder andere Samenkorn. Die aufgez&auml;hlten Fakten sprechen jedoch nicht nur f&uuml;r eine F&uuml;tterung im Winter, sondern vielmehr auch f&uuml;r eine <a href=\"\/magazin\/vogel\/wildvoegel-ganzjahresfuetterung-sinnvoll\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ganzjahresf&uuml;tterung<\/a>. Folgendes ist jedoch bei der Vogelf&uuml;tterung zu beachten:<\/p>\n<ul>\n<li>Kein Futter auf den Boden werfen. Dort vermischt es sich mit dem Kot der V&ouml;gel und kann zu Krankheiten f&uuml;hren.<\/li>\n<li>Das Vogelhaus immer sauber halten und regelm&auml;&szlig;ig altes, schon vergammeltes Futter entsorgen.<\/li>\n<li>M&ouml;glichst f&uuml;r ein <a href=\"\/vogel\/vogelfutter\/wildvogelfutter\/\" target=\"_blank\" rel=\"noopener noreferrer\">breites Angebot an Futter<\/a> sorgen. Dazu geh&ouml;ren Sonnenblumenkerne, Getreidek&ouml;rner, Haferflocken, aber auch Obst und Rosinen. Nat&uuml;rlich kann auch der ein oder andere Futterring oder Futterkn&ouml;del aufgeh&auml;ngt werden.<\/li>\n<\/ul>\n<p>Von der Gestaltung des Gartens, &uuml;ber Nistpl&auml;tze bis hin zum Anf&uuml;ttern im Winter und zur Ganzjahresf&uuml;tterung &#8211; wenn du diese Empfehlungen ber&uuml;cksichtigst, kannst du einigen bedrohten Vogelarten wirklich helfen. Denke einfach einmal dar&uuml;ber nach. Die V&ouml;gel in Deutschland werden es dir danken.<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-6200-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-6200-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-6200-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-natural-living-nistkasten-fuer-sittiche-30-x-20-x-20-cm\/1000033212\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" class=\"article__wrapper--productimage\" title=\"Trixie Natural Living Nistkasten f\u00fcr Sittiche 30 x 20 x 20 cm\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/wexn6k-w7QgKt5X.jpg?host=ct\"\n                alt=\"Trixie Natural Living Nistkasten f\u00fcr Sittiche 30 x 20 x 20 cm\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Natural Living Nistkasten f\u00fcr Sittiche 30 x 20 x 20 cm<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    16.19 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-natural-living-nistkasten-fuer-sittiche-30-x-20-x-20-cm\/1000033212\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-futterhaus-zum-aufhaengen-rindenholz\/1000076885\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" class=\"article__wrapper--productimage\" title=\"Trixie Futterhaus zum Aufh\u00e4ngen Rindenholz\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/pd0501-gjkZkQNd.jpg?host=ct\"\n                alt=\"Trixie Futterhaus zum Aufh\u00e4ngen Rindenholz\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Futterhaus zum Aufh\u00e4ngen Rindenholz<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    13.49 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-futterhaus-zum-aufhaengen-rindenholz\/1000076885\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-meisenring-xxl-2x250g\/1000075596\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" class=\"article__wrapper--productimage\" title=\"Erdtmann&#039;s Meisenring XXL 2x250g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/otkih5-UL1SBFNW.jpg?host=ct\"\n                alt=\"Erdtmann&#039;s Meisenring XXL 2x250g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Erdtmann&#039;s                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Erdtmann&#039;s Meisenring XXL 2x250g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    3.49 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        6.98 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-meisenring-xxl-2x250g\/1000075596\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a03e22ef414f\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-natural-living-nistkasten-fuer-sittiche-30-x-20-x-20-cm\/1000033212\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" class=\"article__wrapper--productimage\" title=\"Trixie Natural Living Nistkasten f\u00fcr Sittiche 30 x 20 x 20 cm\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/wexn6k-w7QgKt5X.jpg?host=ct\"\n                                    alt=\"Trixie Natural Living Nistkasten f\u00fcr Sittiche 30 x 20 x 20 cm\">\n\n                            <div id=\"swiper-button-next6a03e22ef414f\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03e22ef414f\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Natural Living Nistkasten f\u00fcr Sittiche 30 x 20 x 20 cm<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                16.19 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-natural-living-nistkasten-fuer-sittiche-30-x-20-x-20-cm\/1000033212\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-futterhaus-zum-aufhaengen-rindenholz\/1000076885\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" class=\"article__wrapper--productimage\" title=\"Trixie Futterhaus zum Aufh\u00e4ngen Rindenholz\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/pd0501-gjkZkQNd.jpg?host=ct\"\n                                    alt=\"Trixie Futterhaus zum Aufh\u00e4ngen Rindenholz\">\n\n                            <div id=\"swiper-button-next6a03e22ef414f\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03e22ef414f\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Futterhaus zum Aufh\u00e4ngen Rindenholz<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                13.49 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-futterhaus-zum-aufhaengen-rindenholz\/1000076885\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-meisenring-xxl-2x250g\/1000075596\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" class=\"article__wrapper--productimage\" title=\"Erdtmann&#039;s Meisenring XXL 2x250g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/otkih5-UL1SBFNW.jpg?host=ct\"\n                                    alt=\"Erdtmann&#039;s Meisenring XXL 2x250g\">\n\n                            <div id=\"swiper-button-next6a03e22ef414f\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03e22ef414f\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Erdtmann&#039;s                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Erdtmann&#039;s Meisenring XXL 2x250g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                3.49 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    6.98 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-meisenring-xxl-2x250g\/1000075596\/?icid=magproteaser_vogel_zahl-der-voegel-geht-zurueck_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a03e22ef414f\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a03e22ef414f\",\n                prevEl: \"#swiper-button-prev6a03e22ef414f\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wenn man vor knapp 30 Jahren aus dem Fenster geblickt hat, war die Landschaft in Deutschland gepr&auml;gt von viel Natur, Waldfl&auml;chen, Ackerbau auf Kleinfl&auml;chen und nicht sonderlich gro&szlig;en St&auml;dten: der&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":34,"featured_media":6187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,50],"tags":[1355,1358,1357,1356],"class_list":["post-6200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vogel","category-wildvoegel","tag-vogelbestand-geht-zurueck","tag-vogelsterben","tag-weniger-wildvoegel","tag-zahl-der-voegel-geht-zurueck"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zahl der V\u00f6gel geht zur\u00fcck | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Erfahre hier, warum die Zahl der V\u00f6gel immer weiter zur\u00fcck geht und was auch du dagegen unternehmen kannst.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zahl der V\u00f6gel geht zur\u00fcck\" \/>\n<meta property=\"og:description\" content=\"Erfahre hier, warum die Zahl der V\u00f6gel immer weiter zur\u00fcck geht und was auch du dagegen unternehmen kannst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-12T07:14:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T12:03:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/1deaa2bc786ab771a842e88bfeed5b06\"},\"headline\":\"Zahl der V\u00f6gel geht zur\u00fcck\",\"datePublished\":\"2017-05-12T07:14:53+00:00\",\"dateModified\":\"2024-06-11T12:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/\"},\"wordCount\":1146,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/kiebitz-760x560.jpg\",\"keywords\":[\"vogelbestand geht zur\u00fcck\",\"vogelsterben\",\"weniger wildv\u00f6gel\",\"zahl der v\u00f6gel geht zur\u00fcck\"],\"articleSection\":[\"Vogel Magazin\",\"Wildv\u00f6gel\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/\",\"name\":\"Zahl der V\u00f6gel geht zur\u00fcck | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/kiebitz-760x560.jpg\",\"datePublished\":\"2017-05-12T07:14:53+00:00\",\"dateModified\":\"2024-06-11T12:03:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/1deaa2bc786ab771a842e88bfeed5b06\"},\"description\":\"Erfahre hier, warum die Zahl der V\u00f6gel immer weiter zur\u00fcck geht und was auch du dagegen unternehmen kannst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/kiebitz-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/kiebitz-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"Kiebitz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/zahl-der-voegel-geht-zurueck\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zahl der V\u00f6gel geht zur\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/1deaa2bc786ab771a842e88bfeed5b06\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_34_1558596368-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_34_1558596368-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_34_1558596368-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.zooroyal.de\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zahl der V\u00f6gel geht zur\u00fcck | ZooRoyal Magazin","description":"Erfahre hier, warum die Zahl der V\u00f6gel immer weiter zur\u00fcck geht und was auch du dagegen unternehmen kannst.","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Zahl der V\u00f6gel geht zur\u00fcck","og_description":"Erfahre hier, warum die Zahl der V\u00f6gel immer weiter zur\u00fcck geht und was auch du dagegen unternehmen kannst.","og_url":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2017-05-12T07:14:53+00:00","article_modified_time":"2024-06-11T12:03:43+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/1deaa2bc786ab771a842e88bfeed5b06"},"headline":"Zahl der V\u00f6gel geht zur\u00fcck","datePublished":"2017-05-12T07:14:53+00:00","dateModified":"2024-06-11T12:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/"},"wordCount":1146,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg","keywords":["vogelbestand geht zur\u00fcck","vogelsterben","weniger wildv\u00f6gel","zahl der v\u00f6gel geht zur\u00fcck"],"articleSection":["Vogel Magazin","Wildv\u00f6gel"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/","url":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/","name":"Zahl der V\u00f6gel geht zur\u00fcck | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg","datePublished":"2017-05-12T07:14:53+00:00","dateModified":"2024-06-11T12:03:43+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/1deaa2bc786ab771a842e88bfeed5b06"},"description":"Erfahre hier, warum die Zahl der V\u00f6gel immer weiter zur\u00fcck geht und was auch du dagegen unternehmen kannst.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/05\/kiebitz-760x560.jpg","width":760,"height":560,"caption":"Kiebitz"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Zahl der V\u00f6gel geht zur\u00fcck"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/1deaa2bc786ab771a842e88bfeed5b06","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_34_1558596368-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_34_1558596368-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_34_1558596368-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.zooroyal.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/6200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=6200"}],"version-history":[{"count":7,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/6200\/revisions"}],"predecessor-version":[{"id":11316,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/6200\/revisions\/11316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/6187"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=6200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=6200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=6200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}