{"id":5780,"date":"2017-04-25T14:15:01","date_gmt":"2017-04-25T12:15:01","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=5780"},"modified":"2017-04-25T16:21:39","modified_gmt":"2017-04-25T14:21:39","slug":"adelheid-sucht-ein-zuhause","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/","title":{"rendered":"Adelheid sucht ein Zuhause"},"content":{"rendered":"<div id=\"pl-5780\" class=\"panel-layout\">\n<div id=\"pg-5780-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-5780-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-5780-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <strong><a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5781\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg\" alt=\"Tierheim Detmold Katze Adelheid\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/a>Name: <\/strong>Adelheid<\/p>\n<p><strong>Alter: <\/strong>Geb. ca. 2006<\/p>\n<p><strong>Geschlecht: <\/strong>Weiblich<\/p>\n<p><strong>Farbe:&nbsp;<\/strong>Schwarz-wei&szlig;<\/p>\n<p><strong>Im Tierheim seit:<\/strong> Dezember 2016<\/p>\n<p><strong>Abgabegrund:<\/strong> Fundtier<\/p>\n<p><strong>Gesundheitszustand: <\/strong>Kastriert, geimpft, entwurmt, t&auml;towiert<\/p>\n<p><strong>Wunschzuhause:&nbsp;<\/strong>Einzelhaltung und Freigang<\/p>\n<hr>\n<p>Die Katze Adelheid wurde im Dezember 2016 in Detmold-Remmighausen gefunden und ins Tierheim Detmold gebracht. Leider war sie nicht kastriert und wurde auch nirgendwo vermisst. Bestimmt hatte die ungef&auml;hr zehn bis elf Jahre alte Katzendame mit dem markanten Fleck auf der Nase aber schon einmal ein Zuhause, denn sie ist deutlich an Menschen gew&ouml;hnt und sehr freundlich. Adelheid hatte aber sicherlich einige Strapazen hinter sich, denn sie war deutlich entkr&auml;ftet und schwach und musste erst einmal aufgep&auml;ppelt werden. Inzwischen hat sie sich gut erholt und sehnt sich nach einem kuscheligen Zuhause, in dem sie als Einzelkatze verw&ouml;hnt werden m&ouml;chte, denn auf andere Katze im gleichen Haushalt w&uuml;rde sie lieber verzichten. Menschen gegen&uuml;ber ist Adelheid sehr anlehnungsbed&uuml;rftig und anh&auml;nglich. Die liebe und eher ruhige Adelheid mag es gem&uuml;tlich, und sie sucht eine nette Familie, bei der sie ein sch&ouml;nes Leben als Freig&auml;ngerin f&uuml;hren darf. Ihre neue Wohnumgebung sollte m&ouml;glichst verkehrsarm sein.<\/p>\n<hr>\n<p>Wenn du Adelheid ein neues Zuhause bieten m&ouml;chtest, melde dich bitte beim Tierheim Detmold:<\/p>\n<p>Tierheim Detmold<br \/>\nZum Dicken Holz 19<br \/>\n32758 Detmold<\/p>\n<p>Tel.:&nbsp;<span data-sheets-value='{\"1\":2,\"2\":\"05231 24468\"}' data-sheets-userformat='{\"2\":513,\"3\":{\"1\":0},\"12\":0}'>05231 24468<\/span><\/p>\n<p><em>Hinweis: Wir bitten um Verst&auml;ndnis, dass einzelne Tiere bei Kontaktaufnahme bereits vermittelt sind.<\/em><\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-5780-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-5780-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-5780-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\">\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Name: Adelheid Alter: Geb. ca. 2006 Geschlecht: Weiblich Farbe:&nbsp;Schwarz-wei&szlig; Im Tierheim seit: Dezember 2016 Abgabegrund: Fundtier Gesundheitszustand: Kastriert, geimpft, entwurmt, t&auml;towiert Wunschzuhause:&nbsp;Einzelhaltung und Freigang Die Katze Adelheid wurde im Dezember&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":15,"featured_media":5781,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1253,1252],"tags":[412,1248,1250],"class_list":["post-5780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tierheim-detmold","category-tierheime","tag-tierheim","tag-tierheim-detmold","tag-tiervermittlung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Katze Adelheid sucht ein neues Zuhause | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Lerne hier die Katze Adelheid kennen und helfe dabei mit f\u00fcr die verschmuste Freig\u00e4ngerin ein neues und liebevolles Zuhause zu finden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adelheid sucht ein Zuhause\" \/>\n<meta property=\"og:description\" content=\"Lerne hier die Katze Adelheid kennen und helfe dabei mit f\u00fcr die verschmuste Freig\u00e4ngerin ein neues und liebevolles Zuhause zu finden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-25T12:15:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-25T14:21:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"headline\":\"Adelheid sucht ein Zuhause\",\"datePublished\":\"2017-04-25T12:15:01+00:00\",\"dateModified\":\"2017-04-25T14:21:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/\"},\"wordCount\":261,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/tierheim-detmold-adelheid-760x560.jpg\",\"keywords\":[\"Tierheim\",\"Tierheim Detmold\",\"Tiervermittlung\"],\"articleSection\":[\"Tierheim Detmold\",\"Tierheime\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/\",\"name\":\"Katze Adelheid sucht ein neues Zuhause | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/tierheim-detmold-adelheid-760x560.jpg\",\"datePublished\":\"2017-04-25T12:15:01+00:00\",\"dateModified\":\"2017-04-25T14:21:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"description\":\"Lerne hier die Katze Adelheid kennen und helfe dabei mit f\u00fcr die verschmuste Freig\u00e4ngerin ein neues und liebevolles Zuhause zu finden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/tierheim-detmold-adelheid-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/tierheim-detmold-adelheid-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"Tierheim Detmold Katze Adelheid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/tierheime\\\/tierheim-detmold\\\/adelheid-sucht-ein-zuhause\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adelheid sucht ein Zuhause\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZooRoyalDE\",\"https:\\\/\\\/x.com\\\/zooroyal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Katze Adelheid sucht ein neues Zuhause | ZooRoyal Magazin","description":"Lerne hier die Katze Adelheid kennen und helfe dabei mit f\u00fcr die verschmuste Freig\u00e4ngerin ein neues und liebevolles Zuhause zu finden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/","og_locale":"de_DE","og_type":"article","og_title":"Adelheid sucht ein Zuhause","og_description":"Lerne hier die Katze Adelheid kennen und helfe dabei mit f\u00fcr die verschmuste Freig\u00e4ngerin ein neues und liebevolles Zuhause zu finden.","og_url":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_author":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2017-04-25T12:15:01+00:00","article_modified_time":"2017-04-25T14:21:39+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"headline":"Adelheid sucht ein Zuhause","datePublished":"2017-04-25T12:15:01+00:00","dateModified":"2017-04-25T14:21:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/"},"wordCount":261,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg","keywords":["Tierheim","Tierheim Detmold","Tiervermittlung"],"articleSection":["Tierheim Detmold","Tierheime"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/","url":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/","name":"Katze Adelheid sucht ein neues Zuhause | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg","datePublished":"2017-04-25T12:15:01+00:00","dateModified":"2017-04-25T14:21:39+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"description":"Lerne hier die Katze Adelheid kennen und helfe dabei mit f\u00fcr die verschmuste Freig\u00e4ngerin ein neues und liebevolles Zuhause zu finden.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/04\/tierheim-detmold-adelheid-760x560.jpg","width":760,"height":560,"caption":"Tierheim Detmold Katze Adelheid"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/tierheime\/tierheim-detmold\/adelheid-sucht-ein-zuhause\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Adelheid sucht ein Zuhause"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.facebook.com\/ZooRoyalDE","https:\/\/x.com\/zooroyal"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/5780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=5780"}],"version-history":[{"count":8,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/5780\/revisions"}],"predecessor-version":[{"id":5789,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/5780\/revisions\/5789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/5781"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=5780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=5780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=5780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}