{"id":5060,"date":"2017-03-03T13:32:33","date_gmt":"2017-03-03T12:32:33","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=5060"},"modified":"2025-06-26T12:56:47","modified_gmt":"2025-06-26T10:56:47","slug":"cocker-spaniel","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderassen\/cocker-spaniel\/","title":{"rendered":"Cocker Spaniel"},"content":{"rendered":"<div id=\"pl-5060\"  class=\"panel-layout\" >\n<div id=\"pg-5060-0\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-5060-0-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-5060-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" >\n<div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><\/p>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5061 size-full\" title=\"Cocker Spaniel\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg\" alt=\"Cocker Spaniel\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/a>\n<style>\n    .characterGrid {\n        display: grid;\n        grid-template-columns: auto auto auto auto;\n    }\n\n    .characterGrid div {\n        padding: 0.25em;\n    }\n<\/style>\n\n<div class=\"characteristics\">\n    <div class=\"header\">\n        <h2>Cocker Spaniel Steckbrief<\/h2>\n        <div class=\"badge\">\n            <i class=\"halflings halflings-ok\"><\/i>         <\/div>\n    <\/div>\n\n    <div width=\"100%\" class=\"characterGrid\">\n\t\t            <div><strong>Name<\/strong><\/div>\n            <div>Cocker Spaniel Steckbrief<\/div>\n\t\t            <div><strong>Herkunft<\/strong><\/div>\n            <div>UK<\/div>\n\t\t            <div><strong>Lebenserwartung<\/strong><\/div>\n            <div>12-14 Jahre<\/div>\n\t\t            <div><strong>FCI-Standard<\/strong><\/div>\n            <div><a href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderassen\/fci-gruppen\/fci-gruppe-8\/\">Gruppe 8: Apportierhunde - St\u00f6berhunde - Wasserhunde<\/a><\/div>\n\t\t            <div><strong>Funktion<\/strong><\/div>\n            <div><a href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderassen\/jagdhunde\/\">Jagdhund<\/a><\/div>\n\t\t            <div><strong>Gr\u00f6\u00dfe<\/strong><\/div>\n            <div><a href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderassen\/kleine-hunderassen\/\">Kleine Hunderassen<\/a><\/div>\n\t\t            <div><strong>Gewicht<\/strong><\/div>\n            <div>12-16 kg<\/div>\n\t\t            <div><strong>H\u00e4ufige Krankheiten<\/strong><\/div>\n            <div>Entz\u00fcndungen des Geh\u00f6rgangs, Augenerkrankungen ,Nierenleiden<\/div>\n\t\t            <div><strong>Felll\u00e4nge<\/strong><\/div>\n            <div>mittellang<\/div>\n\t\t            <div><strong>Charakter\/Wesen<\/strong><\/div>\n            <div>fr\u00f6hlich, anh\u00e4nglich, verspielt, intelligent, agil, gutm\u00fctig<\/div>\n\t\t            <div><strong>Fellfarbe<\/strong><\/div>\n            <div>Einfarbig: schwarz, rot, leber (schokobraun), schwarz mit loh, braun mit loh; zweifarbig: schwarz-wei\u00df, orange-wei\u00df, braun-wei\u00df, lemon-wei\u00df; dreifarbig: schwarz, wei\u00df mit loh und braun, wei\u00df mit loh<\/div>\n\t\t    <\/div>\n\n            <div><strong>Besonderheiten<\/strong><\/div>\n        <div><p>Anf\u00e4ngerhund, beliebte Hunderasse<\/p>\n<\/div>\n    <\/div>\n<!-- \/characteristics --><div class=\"mobile-toc\"><\/div>\n<\/p>\n<h2 id=\"rassenmerkmale-und-erscheinungsbild\">Rassenmerkmale und Erscheinungsbild<\/h2>\n<h3 id=\"wie-sieht-ein-cocker-spaniel-aus\">Wie sieht ein Cocker Spaniel aus?<\/h3>\n<p>Der Cocker Spaniel ist mit seinem mittellangen Fell, seiner <strong>freundlichen Erscheinung<\/strong> und seinen Schlappohren unverwechselbar. Er ist ein <a href=\"\/magazin\/hunde\/hunderassen\/kleine-hunderassen\/\" target=\"_blank\" rel=\"noopener noreferrer\">kleiner<\/a> bis eher <a href=\"\/magazin\/hunde\/hunderassen\/mittelgrosse-hunderassen\/\" target=\"_blank\" rel=\"noopener noreferrer\">mittelgro\u00dfer<\/a> Vertreter der Hund mit etwa 40 cm Widerristh\u00f6he und um die 14 KG Gewicht. Diese handlichen Ma\u00dfe verbindet er mit dieser fr\u00f6hlichen Ausstrahlung, die insbesondere von den gro\u00dfen, leuchtenden Augen unterstrichen wird. Mit seinem markant geschnittenen Kopf, den langen herunterh\u00e4ngenden Ohren und den kompakten K\u00f6rper mit seinem mittellangem Haar ist er unverwechselbar.<\/p>\n<p>Wie kaum eine andere Hunderasse hat der Cocker den Spagat geschafft,<strong> zugleich J\u00e4ger und Begleiter<\/strong> zu sein. Das macht ein St\u00fcck seiner Faszination. Nur selten hat sich das keineswegs selbstverst\u00e4ndliche Nebeneinander von <a href=\"\/magazin\/hunde\/familienhund\/\" target=\"_blank\" rel=\"noopener noreferrer\">Familienhund<\/a> einerseits und passioniertem <a href=\"\/magazin\/hunde\/jagdhunde\/\" target=\"_blank\" rel=\"noopener noreferrer\">Jagdhund<\/a> andererseits so problemlos entwickelt wie beim Cocker &#8211; vorausgesetzt er ist nicht mit \u00fcberlangem, seidigem Fell \u00fcberz\u00fcchtet. Die heutigen <strong>\u00dcbertreibungen der Show-Zucht<\/strong> lassen ihn sein Sportler- und J\u00e4gerherz nicht mehr ausleben.<\/p>\n<p>So wird der J\u00e4ger in ein Abendkleid gesteckt, in dem er seinen elementaren Bed\u00fcrfnissen nicht mehr nachkommen kann. Mit fast bis zum Boden reichender, \u00fcppiger Behaarung und extrem langen Ohren kann man nicht st\u00f6bern, ja selbst <a href=\"\/magazin\/hunde\/die-beliebtesten-hundesportarten\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hundesport\u00a0<\/a> ist kaum noch machbar. Trotzdem erhalten solche extremen Exemplare regelm\u00e4\u00dfig Championate auf den Hundeausstellungen. F\u00fcr das Haarkleid des English Cockers wird anliegend und seidig gefordert. Eine breite Palette an Farben ist zugelassen. Einfarbig: schwarz, rot, leber (schokobraun), schwarz mit loh, braun mit loh. Zweifarbig: schwarz-wei\u00df, orange-wei\u00df, braun-wei\u00df, lemon-wei\u00df. Dreifarbig: schwarz, wei\u00df mit loh und braun, wei\u00df mit loh.<\/p>\n<h3 id=\"wie-alt-wird-ein-cocker-spaniel\">Wie alt wird ein Cocker Spaniel?<\/h3>\n<p>Der Cocker ist robust und hat eine Lebenserwartung von<strong> 12 &#8211; 14 Jahren<\/strong>, sofern er aus einer seri\u00f6sen Zucht stammt.<br \/>\n<iframe\n  src=\"https:\/\/live.brame-gamification.com\/41c71914-d4b9-11ef-b000-9dba33869fd9\/?lang=de\"\n  style=\"width:100%; height:790px; border:0;\"\n  frameborder=\"0\"\n  scrolling=\"no\"><br \/>\n<\/iframe><\/p>\n<h2 id=\"wesenszuege-und-charaktereigenschaften\">Wesensz\u00fcge und Charaktereigenschaften<\/h2>\n<h3 id=\"welche-eigenschaften-hat-ein-cocker-spaniel\">Welche Eigenschaften hat ein Cocker Spaniel?<\/h3>\n<p>Die seit vielen Jahren stabil gro\u00dfe Beliebtheit dieses Spaniels hat gute Gr\u00fcnde. Er ist ein idealer Begleiter und Familienhund. Er hat ein <strong>ausgesprochen freundliches, den Menschen zugewandtes Wesen ohne Macken<\/strong>. Er ist verspielt und hat auch die richtige Gr\u00f6\u00dfe, um selbst bei robusteren Spielereien nicht verletzt zu werden. Zugleich ist er ein <strong>passionierter und intelligenter J\u00e4ger<\/strong>. Hier zeigt er viele spannende Seiten seiner Kunst.<\/p>\n<p>Allerdings k\u00f6nnen nur weniger als 20% aller Cocker dieses K\u00f6nnen unter jagdlicher F\u00fchrung ausleben. Als Begleithund bleiben ihm jedoch ausgedehnte Spazierg\u00e4nge durch die Natur. Ist er gut erzogen &#8211; gegebenfalls auch an der Schleppleine &#8211; kann man ihn seiner Passion nachgehen lassen, dem St\u00f6bern. Jede Hecke und jedes Geb\u00fcsch muss durchst\u00f6bert werden, um eine Spur aufzunehmen und gegebenenfalls zu verfolgen. Da durchquert er unerschrocken jedes Dickicht. Gerne geht er auch ins Wasser. Er hat einen enormen Bewegungsdrang.<\/p>\n<p>Cocker sind begierig zu lernen und immer daran interessiert, Neues zu erkunden. Der Cocker muss sich austoben k\u00f6nnen, um dann auf der anderen Seite ein ausgesprochen angenehmes, liebevolles und sehr gut f\u00fchrbares Familienmitglied zu sein. Hier strahlt er <strong>Lebensfreude und gute Laune<\/strong> aus. Er ist durchaus f\u00fcr Anf\u00e4nger geeignet, die etwas Hundeverstand haben und sich gerne mit ihm in der Natur austoben.<\/p>\n<h2 id=\"herkunft-geschichte\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18520 size-featured-whatever\" title=\"Cocker Spaniel\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/02\/brauner-cocker-spaniel-760x570.jpg\" alt=\"cocker spaniel\" width=\"760\" height=\"570\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/02\/brauner-cocker-spaniel-760x570.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/02\/brauner-cocker-spaniel-700x525.jpg 700w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/02\/brauner-cocker-spaniel-233x175.jpg 233w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/02\/brauner-cocker-spaniel-175x131.jpg 175w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/02\/brauner-cocker-spaniel-323x242.jpg 323w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/>Herkunft &amp; Geschichte<\/h2>\n<h3 id=\"wo-kommt-der-cocker-spaniel-urspruenglich-her\">Wo kommt der Cocker Spaniel urspr\u00fcnglich her?<\/h3>\n<p>Der Cocker Spaniel hei\u00dft heute offiziell &#8222;English Cocker Spaniel&#8220;. Es gibt noch den &#8222;<a href=\"\/magazin\/hunde\/american-cocker-spaniel\/\" target=\"_blank\" rel=\"noopener noreferrer\">American Cocker Spaniel<\/a>&#8222;, der in den USA als Show-Hund aus seinem europ\u00e4ischen Bruder herausgez\u00fcchtet wurde. Das machte den Zusatz &#8222;English&#8220; n\u00f6tig. Der English Cocker Spaniel ist mehr der alte Jagdhund geblieben als der American. Wenn in Deutschland vom Cocker gesprochen wird, so meint man den Englischen Cocker Spaniel. Spaniels sind ein Urtyp der Jagdhunde, genauer <strong>St\u00f6berhunde<\/strong>. Diese m\u00fcssen vor dem J\u00e4ger das Wild aufst\u00f6bern und auffliegen lassen oder zum Weglaufen bringen. Das muss in einer bestimmten Entfernung vom J\u00e4ger passieren, damit dieser gut zum Schuss kommt.<\/p>\n<p>Der Hund darf dem Wild nicht nachhetzen. Nach dem Schuss muss er es dann apportieren. Dieses Verhalten ist recht komplex. Trotzdem hat es uralte, nachvollziehbare <strong>Wurzeln in der Antike<\/strong>, bei Kelten und Germanen. Den Begriff &#8222;Spaniel&#8220; finden wir bereits bei William Shakespeare in seiner Trag\u00f6die &#8222;K\u00f6nig Lear&#8220;. Die Spaniels, in der Form wie wir sie heute kennen, entstanden allerdings erst vor 200 Jahren. Der Zusatz Cocker wiederum kommt vom Englischen Woodcock f\u00fcr den Vogel &#8222;Waldschnepfe&#8220;.<\/p>\n<p>Das war zeitweilig die bevorzugte Jagdbeute. Der Cocker Spaniel z\u00e4hlte zu den ersten Hunderassen der modernen Rassehundezucht und wurde vom Kennel Club bereits 1873 anerkannt. Seit dieser Zeit f\u00fchrt er den Standard des Cockers. Der erste kontinentale Zuchtverband entstand 1904, der Jagdspaniel-Klub 1907. Seit Jahren z\u00e4hlt der English Cocker Spaniel auch in Deutschland zu den beliebtesten Hunderassen.<\/p>\n<h2 id=\"beliebte-mixe\">Beliebte Mixe<\/h2>\n<p>Mixe von Cocker Spaniel mit anderen Hunderassen oder Mischlingen sind eher selten.<\/p>\n<h2 id=\"pflege-gesundheit-und-krankheiten\">Pflege, Gesundheit und Krankheiten<\/h2>\n<h3 id=\"wie-viel-pflege-braucht-ein-cocker-spaniel\">Wie viel Pflege braucht ein Cocker Spaniel?<\/h3>\n<p>Der Cocker sollte t\u00e4glich, <strong>mindestens jeden zweiten Tag geb\u00fcrstet<\/strong> werden. Die Ohren musst Du regelm\u00e4\u00dfig \u00fcberpr\u00fcfen und fachkundig pflegen. Um die standartgeforderte Form des Cockers zu zeigen, ist trimmen erforderlich. Hierzu werden \u00fcbersch\u00fcssige Haare auf dem R\u00fccken, unter den Ohren und dem Bauch verk\u00fcrzt. F\u00fcr deinen t\u00e4glichen Begleiter brauchst du diesen Aufwand nicht zu betreiben.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pg-5060-1\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-5060-1-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-5060-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Produkte f\u00fcr deinen Cocker Spaniel<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-pute-400g\/1000101594\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Rind + Pute 400g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/unow1r-gCrKkUom.jpg?host=ct\"\n                alt=\"ZooRoyal Rind + Pute 400g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Rind + Pute 400g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    1.59 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        3.98 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-pute-400g\/1000101594\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melamin-napf-l-700ml-2er-set-weiss-700ml\/1000000754\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Melamin-Napf L 700ml 2er Set wei\u00df 700ml\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/f2bvyv-d_zJlxl8.jpg?host=ct\"\n                alt=\"ZooRoyal Melamin-Napf L 700ml 2er Set wei\u00df 700ml\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Melamin-Napf L 700ml 2er Set wei\u00df 700ml<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    24.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melamin-napf-l-700ml-2er-set-weiss-700ml\/1000000754\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-hundespielzeug-kuscheltier-fuchs-mit-tau\/1000099495\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Hundespielzeug Kuscheltier Fuchs mit Tau\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/27bpjl-qdQg-V59.jpg?host=ct\"\n                alt=\"ZooRoyal Hundespielzeug Kuscheltier Fuchs mit Tau\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Hundespielzeug Kuscheltier Fuchs mit Tau<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    8.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-hundespielzeug-kuscheltier-fuchs-mit-tau\/1000099495\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Produkte f\u00fcr deinen Cocker Spaniel<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a03cbb3273eb\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-pute-400g\/1000101594\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Rind + Pute 400g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/unow1r-gCrKkUom.jpg?host=ct\"\n                                    alt=\"ZooRoyal Rind + Pute 400g\">\n\n                            <div id=\"swiper-button-next6a03cbb3273eb\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03cbb3273eb\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Rind + Pute 400g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                1.59 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    3.98 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-pute-400g\/1000101594\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melamin-napf-l-700ml-2er-set-weiss-700ml\/1000000754\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Melamin-Napf L 700ml 2er Set wei\u00df 700ml\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/f2bvyv-d_zJlxl8.jpg?host=ct\"\n                                    alt=\"ZooRoyal Melamin-Napf L 700ml 2er Set wei\u00df 700ml\">\n\n                            <div id=\"swiper-button-next6a03cbb3273eb\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03cbb3273eb\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Melamin-Napf L 700ml 2er Set wei\u00df 700ml<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                24.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melamin-napf-l-700ml-2er-set-weiss-700ml\/1000000754\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-hundespielzeug-kuscheltier-fuchs-mit-tau\/1000099495\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Hundespielzeug Kuscheltier Fuchs mit Tau\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/27bpjl-qdQg-V59.jpg?host=ct\"\n                                    alt=\"ZooRoyal Hundespielzeug Kuscheltier Fuchs mit Tau\">\n\n                            <div id=\"swiper-button-next6a03cbb3273eb\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03cbb3273eb\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Hundespielzeug Kuscheltier Fuchs mit Tau<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                8.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-hundespielzeug-kuscheltier-fuchs-mit-tau\/1000099495\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a03cbb3273eb\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a03cbb3273eb\",\n                prevEl: \"#swiper-button-prev6a03cbb3273eb\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div id=\"pg-5060-2\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-5060-2-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-5060-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" >\n<div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t><\/p>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<h3 id=\"gibt-es-beim-cocker-spaniel-rassetypische-krankheiten\">Gibt es beim Cocker Spaniel rassetypische Krankheiten?<\/h3>\n<p>In der Population des Cockers sind<strong> einige rassetypische Krankheiten<\/strong> verbreitet: Aufgrund teils \u00fcberm\u00e4\u00dfig gro\u00dfer, herunterh\u00e4ngender Ohren werden diese oft problematisch. Wir sehen Entz\u00fcndungen des \u00e4u\u00dferen Geh\u00f6rgangs, Ohrenzwang. Fernen sind Lefzen-Ekzemen bekannt. Erblich bedingt sehen wir Progressive Retina-Atrophie (Augenkrankheit) und famili\u00e4re Nephropathie (Nierenleiden). Nur noch selten tritt heute die Cockerwut auf, eine epilepsie-artige Nervenkrankheit. Zu langes Haar und zu lange Ohren behindern den Cocker beim Laufen und St\u00f6bern.<\/p>\n<h3 id=\"welches-futter-ist-fuer-einen-cocker-spaniel-am-besten\">Welches Futter ist f\u00fcr einen Cocker Spaniel am besten?<\/h3>\n<p>Da der Englische Cocker Spaniel gerne viel und schnell frisst und somit <strong>zu \u00dcbergewicht neigt<\/strong>, solltest Futterrationen und Leckerligaben streng im Auge behalten. Auch solltest du hochwertiges Di\u00e4tfutter ins Auge fassen. Wie die meisten Hunde mag er auch mal einen fleischigen Rinderknochen und frisches Fleisch. Der Cocker Spaniel eignet sich auch zum <a href=\"\/hund\/hundefutter\/barf-frostfutter\/\" target=\"_blank\" rel=\"noopener noreferrer\">Barfen<\/a>.<\/p>\n<h2 id=\"aktivitaeten\">Aktivit\u00e4ten<\/h2>\n<h3 id=\"wie-viel-bewegung-braucht-ein-cocker-spaniel\">Wie viel Bewegung braucht ein Cocker Spaniel?<\/h3>\n<p>Dein Cocker braucht viel Besch\u00e4ftigung. <a href=\"\/magazin\/hunde\/die-beliebtesten-hundesportarten\/\" target=\"_blank\" rel=\"noopener noreferrer\">Turnierhundesport<\/a>, Agility, Apportierspiele machen ihm Freude, wenn es nicht \u00fcbertrieben wird. Er braucht <strong>t\u00e4glich ein bis zwei Stunden lang intensive Bewegung<\/strong> und das bei jedem Wetter. Einmal kurz Gassi gehen um den Block reichen da nicht. Einen Cocker kann man allerdings durchaus zum Joggen mitnehmen. Besonders gerne st\u00f6bert er in der Natur und hier im Unterholz herum. Ideal ist es, wenn er hie und da seinen jagdlichen Ambitionen nachgehen kann. Hier bieten Cocker-Freunde entsprechende M\u00f6glichkeiten an.<\/p>\n<h2 id=\"ueberlegungen-vor-der-anschaffung\">\u00dcberlegungen vor der Anschaffung<\/h2>\n<h3 id=\"wo-kann-man-einen-cocker-spaniel-kaufen\">Wo kann man einen Cocker Spaniel kaufen?<\/h3>\n<p>Suchst du einen Cocker-Welpen solltest du dich <strong>vor Ort mit einem Z\u00fcchter<\/strong> in Verbindung setzen, der einem der drei VDH-Vereinen angeschlossen ist. Du kannst dich auch im Tierheim oder bei einer der Cocker-in-Not-Initiativen umschauen. Es sollte keine Inzucht vorliegen, was Du anhand des Stammbaums absch\u00e4tzen kannst, wenn dort kein Name doppelt auftaucht. Der Z\u00fcchter sollte seinen Wurf per Foto gut dokumentiert haben. Du solltest Dir den Wurf zusammen mit der Mutterh\u00fcndin, nach Absprache, vor Ort anschauen k\u00f6nnen. Bitte kaufe keinen &#8222;preisg\u00fcnstigen&#8220; Cocker Spaniel \u00fcbers Internet, da dort das Risiko sehr gro\u00df ist, dass der Welpe von einem &#8211; in aller Regel gut getarntem &#8211; Hundeh\u00e4ndler oder Vermehrer kommt.<\/p>\n<h2 id=\"erziehung-und-haltung\">Erziehung und Haltung<\/h2>\n<h3 id=\"passt-ein-cocker-spaniel-zu-mir\">Passt ein Cocker Spaniel zu mir?<\/h3>\n<p>Wenn wir hier den English Cocker Spaniel als auch &#8222;f\u00fcr Anf\u00e4nger geeignet&#8220; einstufen, so hei\u00dft das keineswegs, dass seine Haltung banal w\u00e4re und seine Erziehung im Selbstlauf erfolgen k\u00f6nne. Ganz im Gegenteil. Seine <strong>Haltung ist eher aufw\u00e4ndig<\/strong>, da man dem Bed\u00fcrfnis des Spaniels nach Bewegung in der Natur t\u00e4glich nachkommen muss. Seine Erziehung muss der Herausforderung gerecht werden, dass meinen einen Jagdhund als Begleiter hat. Es ist aber deshalb f\u00fcr einen engagierten Anf\u00e4nger machbar, da er keine versteckten T\u00fccken oder All\u00fcren hat. Ist man nicht gerade von der seltenen Krankheit &#8222;Cockerwut&#8220; betroffen, so muss man beim Cocker keine Sorge haben, dass er einmal aus dem Ruder geht oder F\u00fchrungsanspr\u00fcche hegt.<\/p>\n<p>Er ist<strong> umg\u00e4nglich gegen\u00fcber Artgenossen<\/strong>, gegen\u00fcber Menschen sowieso. Er ist ausgesprochen gelehrig und an einem harmonischen Verh\u00e4ltnis zu seinen Menschen interessiert. Besondere Anspr\u00fcche an die Wohnung hat er nicht. Bedacht werden sollte, dass sein Fell m\u00f6glichst t\u00e4glich gepflegt sein will und zudem einiges an Dreck mit ins Auto oder in die Wohnung kommen kann, wenn man bei Wind und Wetter mit ihm durch die Natur gezogen ist. Der English Cocker Spaniel ist ein zutiefst freundlicher und lernwilliger Bursche, der es dem Menschen leicht macht, ihn zu erziehen und auszubilden. Er will und braucht diese F\u00fchrung. <strong>A und O der Erziehung ist liebevolle Konsequenz<\/strong>.<\/p>\n<p>Es sollten Regeln aufgestellt werden, die dann eingehalten werden m\u00fcssen &#8211; auch von den Zweibeinern. Er lernt solche Regeln schnell, ist aber auch intelligent genug, jede \u00cdnkonsequenz zu erkennen und bei Bedarf auszunutzen. Konsequenz darf nie mit H\u00e4rte oder gar Brutalit\u00e4t verwechselt werden. Diese w\u00fcrden den Hund psychisch zerst\u00f6ren. Die F\u00fchrung muss auf der Basis inniger Bindung zwischen Hund und Halter erfolgen. So gelingt seine Erziehung sehr gut und ist auch f\u00fcr den Anf\u00e4nger problemlos machbar. Eine Herausforderung ist der J\u00e4ger im Herzen des Cockers. Will man ihn auch mal von der Leine lassen k\u00f6nnen, so muss man ihn vom Welpen an darauf trainieren, dass man ihn &#8222;jederzeit&#8220; abrufen und bei Fu\u00df kommen lassen kann. Jederzeit ist in Anf\u00fchrungsstrichen, da man selbst bei den gemeinsamen Wanderungen durch die Natur immer ein waches Auge haben und rechtzeitig abrufen muss. Ist erst einmal eine gewisse Schwelle \u00fcberschritten kann es schwer werden, das eigenst\u00e4ndige Jagen zu unterbinden.<\/p>\n<h2 id=\"interessantes-wissenswertes-extras\">Interessantes, Wissenswertes &amp; Extras<\/h2>\n<p>Der Cocker vereint viele Vorteile: Ein toller, auch f\u00fcr Kinder geeigneter Familienhund. Ein sportlicher Naturfreund sowie der professionelle Jagdhund. Er ist zwar f\u00fcr Anf\u00e4nger durchaus geeignet, stellt zugleich hohe Anspr\u00fcche f\u00fcr seine artgerechte Haltung.<\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/04\/christoph-jung-140x168.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5876 size-full alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/04\/christoph-jung-140x168.jpg\" alt=\"Christoph Jung\" width=\"140\" height=\"168\" \/><\/a><a href=\"\/magazin\/ueber-uns\/redaktion\/christoph-jung\/\"><strong>Christoph Jung<\/strong><\/a> Seit seiner Kindheit geh\u00f6ren Hunde zu den besten Freunden des Hundeforschers. Die Beziehung Mensch &#8211; Hund ist f\u00fcr ihn ein faszinierendes Thema, das ihn t\u00e4glich besch\u00e4ftigt und f\u00fcr das er sich auch \u00f6ffentlich engagiert. Aus seiner t\u00e4glichen Forschung entstand das Buch <em>&#8222;Tierisch beste Freunde&#8220;<\/em>. Jung lebt mit seiner Familie und seinen Hunden in der N\u00e4he von Halle.<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pg-5060-3\"  class=\"panel-grid panel-no-style\" >\n<div id=\"pgc-5060-3-0\"  class=\"panel-grid-cell\"  data-weight=\"1\" >\n<div id=\"panel-5060-3-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-hundesnack-premio-stripes-mit-huehnchen-und-seelachs-6x75g\/1000076679\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"Trixie Hundesnack PREMIO Stripes mit H\u00fchnchen und Seelachs 6x75g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/gk0hue-2a4FBoyR.jpg?host=ct\"\n                alt=\"Trixie Hundesnack PREMIO Stripes mit H\u00fchnchen und Seelachs 6x75g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Hundesnack PREMIO Stripes mit H\u00fchnchen und Seelachs 6x75g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    10.29 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        22.87 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-hundesnack-premio-stripes-mit-huehnchen-und-seelachs-6x75g\/1000076679\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/petstages-dogwood-stick-mittel\/1000107778\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"Petstages Dogwood Stick Mittel\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/fo6izn-D6C0tEcC.jpg?host=ct\"\n                alt=\"Petstages Dogwood Stick Mittel\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Petstages                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Petstages Dogwood Stick Mittel<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    12.19 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/petstages-dogwood-stick-mittel\/1000107778\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/designed-by-lotte-keramik-napf-jace-gruen-450-ml\/1000108163\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"Designed by Lotte Keramik Napf Jace gr\u00fcn 450 ml\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/lyk5ze-DWfTA4ze.jpg?host=ct\"\n                alt=\"Designed by Lotte Keramik Napf Jace gr\u00fcn 450 ml\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Designed by Lotte                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Designed by Lotte Keramik Napf Jace gr\u00fcn 450 ml<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    8.39 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/designed-by-lotte-keramik-napf-jace-gruen-450-ml\/1000108163\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a03cbb33294f\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-hundesnack-premio-stripes-mit-huehnchen-und-seelachs-6x75g\/1000076679\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"Trixie Hundesnack PREMIO Stripes mit H\u00fchnchen und Seelachs 6x75g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/gk0hue-2a4FBoyR.jpg?host=ct\"\n                                    alt=\"Trixie Hundesnack PREMIO Stripes mit H\u00fchnchen und Seelachs 6x75g\">\n\n                            <div id=\"swiper-button-next6a03cbb33294f\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03cbb33294f\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Hundesnack PREMIO Stripes mit H\u00fchnchen und Seelachs 6x75g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                10.29 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    22.87 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-hundesnack-premio-stripes-mit-huehnchen-und-seelachs-6x75g\/1000076679\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/petstages-dogwood-stick-mittel\/1000107778\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"Petstages Dogwood Stick Mittel\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/fo6izn-D6C0tEcC.jpg?host=ct\"\n                                    alt=\"Petstages Dogwood Stick Mittel\">\n\n                            <div id=\"swiper-button-next6a03cbb33294f\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03cbb33294f\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Petstages                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Petstages Dogwood Stick Mittel<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                12.19 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/petstages-dogwood-stick-mittel\/1000107778\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/designed-by-lotte-keramik-napf-jace-gruen-450-ml\/1000108163\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" class=\"article__wrapper--productimage\" title=\"Designed by Lotte Keramik Napf Jace gr\u00fcn 450 ml\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/lyk5ze-DWfTA4ze.jpg?host=ct\"\n                                    alt=\"Designed by Lotte Keramik Napf Jace gr\u00fcn 450 ml\">\n\n                            <div id=\"swiper-button-next6a03cbb33294f\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03cbb33294f\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Designed by Lotte                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Designed by Lotte Keramik Napf Jace gr\u00fcn 450 ml<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                8.39 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/designed-by-lotte-keramik-napf-jace-gruen-450-ml\/1000108163\/?icid=magproteaser_hunde_hunderassen_cocker-spaniel_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a03cbb33294f\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a03cbb33294f\",\n                prevEl: \"#swiper-button-prev6a03cbb33294f\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rassenmerkmale und Erscheinungsbild Wie sieht ein Cocker Spaniel aus? Der Cocker Spaniel ist mit seinem mittellangen Fell, seiner freundlichen Erscheinung und seinen Schlappohren unverwechselbar. Er ist ein kleiner bis eher&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderassen\/cocker-spaniel\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":15,"featured_media":5061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2040,2047,5,903,2051,2035,2037],"tags":[1143,4772,1144,1889,15,4550,320,406,1229,1834,788,1060,4551],"class_list":["post-5060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familienhunde","category-fci-gruppe-8","category-hunde","category-hunderassen","category-jagdhunde","category-kleine-hunderassen","category-mittelgrosse-hunderassen","tag-cocker-spaniel","tag-englische-rasse","tag-english-cocker-spaniel","tag-familienhund","tag-hund","tag-hunde-steckbrief","tag-hunderasse","tag-hunderassen","tag-jagdhund","tag-rasse","tag-rasseportrait","tag-rasseprofil","tag-steckbrief"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cocker Spaniel - Charakter, Gr\u00f6\u00dfe &amp; Erziehung | Steckbrief<\/title>\n<meta name=\"description\" content=\"Cocker Spaniel sind ideale Familienhunde und sehr beliebt. Erfahre hier bei uns alles \u00fcber die Herkunft, Haltung und Pflege dieser Hunderasse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderassen\/cocker-spaniel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cocker Spaniel\" \/>\n<meta property=\"og:description\" content=\"Cocker Spaniel sind ideale Familienhunde und sehr beliebt. Erfahre hier bei uns alles \u00fcber die Herkunft, Haltung und Pflege dieser Hunderasse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-03T12:32:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T10:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"headline\":\"Cocker Spaniel\",\"datePublished\":\"2017-03-03T12:32:33+00:00\",\"dateModified\":\"2025-06-26T10:56:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/\"},\"wordCount\":1763,\"commentCount\":14,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cocker-spaniel-hunderassen-760x560.jpg\",\"keywords\":[\"Cocker Spaniel\",\"englische Rasse\",\"English Cocker Spaniel\",\"familienhund\",\"Hund\",\"hunde steckbrief\",\"Hunderasse\",\"Hunderassen\",\"jagdhund\",\"Rasse\",\"Rasseportrait\",\"Rasseprofil\",\"steckbrief\"],\"articleSection\":[\"Familienhunde\",\"FCI Gruppe 8\",\"Hunde Magazin\",\"Hunderassen\",\"Jagdhunde\",\"Kleine Hunderassen\",\"Mittelgro\u00dfe Hunderassen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/\",\"name\":\"Cocker Spaniel - Charakter, Gr\u00f6\u00dfe & Erziehung | Steckbrief\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cocker-spaniel-hunderassen-760x560.jpg\",\"datePublished\":\"2017-03-03T12:32:33+00:00\",\"dateModified\":\"2025-06-26T10:56:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"description\":\"Cocker Spaniel sind ideale Familienhunde und sehr beliebt. Erfahre hier bei uns alles \u00fcber die Herkunft, Haltung und Pflege dieser Hunderasse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cocker-spaniel-hunderassen-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/cocker-spaniel-hunderassen-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"Cocker Spaniel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderassen\\\/cocker-spaniel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cocker Spaniel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZooRoyalDE\",\"https:\\\/\\\/x.com\\\/zooroyal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cocker Spaniel - Charakter, Gr\u00f6\u00dfe & Erziehung | Steckbrief","description":"Cocker Spaniel sind ideale Familienhunde und sehr beliebt. Erfahre hier bei uns alles \u00fcber die Herkunft, Haltung und Pflege dieser Hunderasse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderassen\/cocker-spaniel\/","og_locale":"de_DE","og_type":"article","og_title":"Cocker Spaniel","og_description":"Cocker Spaniel sind ideale Familienhunde und sehr beliebt. Erfahre hier bei uns alles \u00fcber die Herkunft, Haltung und Pflege dieser Hunderasse.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_author":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2017-03-03T12:32:33+00:00","article_modified_time":"2025-06-26T10:56:47+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"headline":"Cocker Spaniel","datePublished":"2017-03-03T12:32:33+00:00","dateModified":"2025-06-26T10:56:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/"},"wordCount":1763,"commentCount":14,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg","keywords":["Cocker Spaniel","englische Rasse","English Cocker Spaniel","familienhund","Hund","hunde steckbrief","Hunderasse","Hunderassen","jagdhund","Rasse","Rasseportrait","Rasseprofil","steckbrief"],"articleSection":["Familienhunde","FCI Gruppe 8","Hunde Magazin","Hunderassen","Jagdhunde","Kleine Hunderassen","Mittelgro\u00dfe Hunderassen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/","name":"Cocker Spaniel - Charakter, Gr\u00f6\u00dfe & Erziehung | Steckbrief","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg","datePublished":"2017-03-03T12:32:33+00:00","dateModified":"2025-06-26T10:56:47+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"description":"Cocker Spaniel sind ideale Familienhunde und sehr beliebt. Erfahre hier bei uns alles \u00fcber die Herkunft, Haltung und Pflege dieser Hunderasse.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2017\/03\/cocker-spaniel-hunderassen-760x560.jpg","width":760,"height":560,"caption":"Cocker Spaniel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/cocker-spaniel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Cocker Spaniel"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.facebook.com\/ZooRoyalDE","https:\/\/x.com\/zooroyal"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/5060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=5060"}],"version-history":[{"count":27,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/5060\/revisions"}],"predecessor-version":[{"id":35525,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/5060\/revisions\/35525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/5061"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=5060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=5060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=5060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}