{"id":38425,"date":"2026-05-13T09:47:57","date_gmt":"2026-05-13T07:47:57","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=38425"},"modified":"2026-05-13T09:49:01","modified_gmt":"2026-05-13T07:49:01","slug":"duerfen-hunde-himbeeren-essen","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/","title":{"rendered":"D\u00fcrfen Hunde Himbeeren essen?"},"content":{"rendered":"<div id=\"pl-38425\"  class=\"panel-layout\" ><div id=\"pg-38425-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-38425-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-38425-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-38431\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg\" alt=\"Hund schnuppert an frischen Himbeeren am Strauch \u2013 d\u00fcrfen Hunde Himbeeren essen?\" width=\"760\" height=\"570\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1-300x225.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1-747x560.jpg 747w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1-700x525.jpg 700w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1-233x175.jpg 233w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1-175x131.jpg 175w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1-323x242.jpg 323w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/p>\n<p>Ja, Hunde d\u00fcrfen Himbeeren essen. Die roten Beeren sind sehr gesund und gelten als gut vertr\u00e4glich. Dennoch sollten die Fr\u00fcchte <strong>nur gelegentlich als Snack<\/strong> dienen oder eine<strong> kleine Erg\u00e4nzung des Futterplans<\/strong> darstellen. Bei einer zu gro\u00dfen Menge an Himbeeren k\u00f6nnten <strong>Verdauungsprobleme<\/strong> entstehen.<\/p>\n<h2 id=\"sind-himbeeren-gut-fuer-hunde\">Sind Himbeeren gut f\u00fcr Hunde?<\/h2>\n<p>Himbeeren sind sehr <strong>n\u00e4hrstoffreiche Beeren<\/strong>, die nicht nur uns, sondern auch Hunde gesundheitlich unterst\u00fctzen k\u00f6nnen:<\/p>\n<ol style=\"background-color: #a6d5dd; padding: 20px;\">\n<li><strong>Vitamin C:<\/strong> St\u00e4rkt das Immunsystem<\/li>\n<li><strong>Vitamin E:<\/strong> Hat eine antioxidative Wirkung<\/li>\n<li><strong>Vitamin B:<\/strong> Wichtig f\u00fcr Stoffwechsel und Zellfunktionen<\/li>\n<li><strong>Vitamin A:<\/strong> Gut f\u00fcr die Augen, Haut und Schleimh\u00e4ute<\/li>\n<li><strong>Antioxidantien:<\/strong> Sch\u00fctzen die Zellen und wirken entz\u00fcndungshemmend<\/li>\n<li><strong>Ballaststoffe:<\/strong> Unterst\u00fctzen die Verdauung und Darmflora<\/li>\n<\/ol>\n<h2 id=\"wie-viele-himbeeren-darf-ein-hund-fressen\">Wie viele Himbeeren darf ein Hund fressen?<\/h2>\n<p>Auch wenn dein Hund Gefallen an Himbeeren gefunden hat, sollte die Menge begrenzt sein. Ausschlaggebend hierf\u00fcr ist zuerst einmal die <strong>Gr\u00f6\u00dfe des Hundes<\/strong>:<\/p>\n<ul>\n<li><strong>Kleine Hunde:<\/strong> 3 bis 4 Beeren<\/li>\n<li><strong>Mittelgro\u00dfe Hunde:<\/strong> 5 bis 8 Beeren<\/li>\n<li><strong>Gro\u00dfe Hunde:<\/strong> 12 bis 18 Beeren<\/li>\n<\/ul>\n<p>Neben der <strong>K\u00f6rpergr\u00f6\u00dfe<\/strong> ist auch die <strong>Vertr\u00e4glichkeit<\/strong> ein entscheidender Faktor. Die meisten Hunde vertragen Himbeeren sehr gut, dennoch solltest du sicherheitshalber auf <strong>Kotver\u00e4nderungen<\/strong> achten. Um Verdauungsproblemen entgegenzuwirken, sollten Hunde die Beeren <strong>nicht t\u00e4glich<\/strong> erhalten, sondern <strong>h\u00f6chstens dreimal pro Woche<\/strong>. Sie sind ein gesunder Snack, aber sie enthalten Fruchtzucker und Ballaststoffe, die bei einer zu gro\u00dfen Menge die Verdauung beeintr\u00e4chtigen k\u00f6nnen.<\/p>\n<h2 id=\"darf-ein-welpe-himbeeren-essen\">Darf ein Welpe Himbeeren essen?<\/h2>\n<p style=\"background-color: #fccf9f; padding: 20px;\"><strong>Welpen unter 10 Wochen sollten keine Himbeeren und auch sonst kein Obst essen.<\/strong><\/p>\n<p>Ihr <strong>Verdauungssystem<\/strong> ist noch sehr <strong>empfindlich<\/strong>, was sich erst im Laufe der n\u00e4chsten Lebensmonate zunehmend stabilisiert. Ab einem Alter von <strong>drei bis vier Monaten<\/strong> kannst du austesten, ob dein Welpe Himbeeren mag. Halbiere eine der Fr\u00fcchte und gib sie ihm aus der Hand oder lege sie in seinen Napf. Wenn er sie gerne frisst, kannst du ihm auch die andere H\u00e4lfte geben.<\/p>\n<p>Belasse es bei <strong>h\u00f6chstens zwei Himbeeren<\/strong>, da ungewiss ist, wie er auf eine gr\u00f6\u00dfere Menge reagieren k\u00f6nnte. F\u00fcttere ihn auch nicht t\u00e4glich mit Beeren, da zu viel Fruchtzucker eine Magen- Darm-Reizung ausl\u00f6sen kann. Halte dich bei der Ern\u00e4hrung in erster Linie an ein hochwertiges <a href=\"\/magazin\/hunde\/ernaehrung-hunde\/welpenfutter\/\">Welpenfutter<\/a> und hundegerechte Snacks.<\/p>\n<h2 id=\"welche-beeren-duerfen-hunde-nicht-essen\">Welche Beeren d\u00fcrfen Hunde nicht essen?<\/h2>\n<p>Nicht alle Beeren sind f\u00fcr Hunde gut vertr\u00e4glich. Dies gilt insbesondere f\u00fcr <strong>\u201erohe\u201c Holunderbeeren<\/strong>. Sie enthalten den giftigen Stoff Sambunigrin, der bei Hunden \u00dcbelkeit und Erbrechen ausl\u00f6sen kann. Verzichte au\u00dferdem auf <strong>gezuckerte Beeren<\/strong>, sowie <strong>Ebereschenbeeren<\/strong>, <strong>Mistelbeeren<\/strong> und <strong>Maigl\u00f6ckchen-Beeren<\/strong>.<\/p>\n<p>Halte dich an <strong>Himbeeren, Erdbeeren, Blaubeeren und Brombeeren<\/strong>. Diese sind f\u00fcr Hunde in der Regel gut vertr\u00e4glich \u2013 aber nur in einer begrenzten Menge.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-38425-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-38425-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-38425-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898-38425\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-4x100g\/1000080679\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Mini Burger reich an Rind 4x100g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/g9ibfl-xAM01HkF.jpg?host=ct\"\n                alt=\"ZooRoyal Mini Burger reich an Rind 4x100g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Mini Burger reich an Rind 4x100g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    7.59 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        18.97 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-4x100g\/1000080679\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melaminnapf-weiss-400ml\/1000074465\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Melaminnapf wei\u00df 400ml\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/4dwpyx-iRm5nuL-.jpg?host=ct\"\n                alt=\"ZooRoyal Melaminnapf wei\u00df 400ml\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Melaminnapf wei\u00df 400ml<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    9.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melaminnapf-weiss-400ml\/1000074465\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-entenherzen-6x400g\/1000101601\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Rind + Entenherzen 6x400g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/qgn0tf-3in4bL8c.jpg?host=ct\"\n                alt=\"ZooRoyal Rind + Entenherzen 6x400g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Rind + Entenherzen 6x400g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    9.49 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        3.95 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-entenherzen-6x400g\/1000101601\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a04a80eb86a7\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-4x100g\/1000080679\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Mini Burger reich an Rind 4x100g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/g9ibfl-xAM01HkF.jpg?host=ct\"\n                                    alt=\"ZooRoyal Mini Burger reich an Rind 4x100g\">\n\n                            <div id=\"swiper-button-next6a04a80eb86a7\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04a80eb86a7\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Mini Burger reich an Rind 4x100g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                7.59 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    18.97 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-4x100g\/1000080679\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melaminnapf-weiss-400ml\/1000074465\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Melaminnapf wei\u00df 400ml\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/4dwpyx-iRm5nuL-.jpg?host=ct\"\n                                    alt=\"ZooRoyal Melaminnapf wei\u00df 400ml\">\n\n                            <div id=\"swiper-button-next6a04a80eb86a7\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04a80eb86a7\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Melaminnapf wei\u00df 400ml<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                9.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-melaminnapf-weiss-400ml\/1000074465\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-entenherzen-6x400g\/1000101601\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Rind + Entenherzen 6x400g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/qgn0tf-3in4bL8c.jpg?host=ct\"\n                                    alt=\"ZooRoyal Rind + Entenherzen 6x400g\">\n\n                            <div id=\"swiper-button-next6a04a80eb86a7\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04a80eb86a7\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Rind + Entenherzen 6x400g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                9.49 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    3.95 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-entenherzen-6x400g\/1000101601\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a04a80eb86a7\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a04a80eb86a7\",\n                prevEl: \"#swiper-button-prev6a04a80eb86a7\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div><\/div><\/div><\/div><div id=\"pg-38425-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-38425-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-38425-2-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 id=\"koennen-himbeeren-giftig-fuer-hunde-sein\">K\u00f6nnen Himbeeren giftig f\u00fcr Hunde sein?<\/h2>\n<p>Himbeeren sind f\u00fcr Hunde nicht giftig. Vorsichtig solltest du mit <strong>unreifen Fr\u00fcchten<\/strong> sein, die zu einer Magenverstimmung f\u00fchren k\u00f6nnten. Ein Risiko besteht zudem bei <strong>wilden Waldhimbeeren<\/strong>. Bei ihnen ist nicht restlos auszuschlie\u00dfen, dass sie <strong>Bandwurmeier<\/strong> in sich tragen. Achte au\u00dferdem in jedem Fall darauf, dass die Himbeeren nicht verschimmelt sind und sei nicht zu gro\u00dfz\u00fcgig bei der Menge. Zum einen ist zu viel Fruchtzucker ungesund, zum anderen enthalten Himbeeren eine winzige Spur von Xylit, das bei \u00fcberm\u00e4\u00dfigem Konsum gesundheitliche Probleme ausl\u00f6sen k\u00f6nnte.<\/p>\n<h2 id=\"welches-obst-duerfen-hunde-essen\">Welches Obst d\u00fcrfen Hunde essen?<\/h2>\n<p>Als gelegentlichen Snack d\u00fcrfen Hunde viele Obstsorten essen \u2013\u00a0darunter folgende:<\/p>\n<ul style=\"background-color: #a6d5dd; padding: 20px;\">\n<li><a href=\"\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-bananen-essen\/\">Bananen<\/a><\/li>\n<li><a href=\"\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-aepfel-essen\/\">\u00c4pfel<\/a> (ohne Kerne)<\/li>\n<li><a href=\"\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-birnen-essen\/\">Birnen<\/a><\/li>\n<li><a href=\"\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-blaubeeren-essen\/\">Blaubeeren<\/a><\/li>\n<li><a href=\"\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-wassermelone-essen\/\">Wassermelone<\/a> (ohne Kerne)<\/li>\n<li><a href=\"\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-erdbeeren-essen\/\">Erdbeeren<\/a><\/li>\n<li>Papaya<\/li>\n<li>Brombeeren<\/li>\n<li>Mango<\/li>\n<li><a href=\"\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-ananas-essen\/\">Ananas<\/a><\/li>\n<\/ul>\n<p>Belasse es stets bei einer kleinen Menge. Obst sollte nur eine \u00fcberschaubare Erg\u00e4nzung des Speiseplans eines Hundes darstellen. Gemeinsam mit Leckerlis sollte der Anteil an der Tagesration bei unter<strong> 10 Prozent liegen<\/strong>.<\/p>\n<h2 id=\"darf-ein-hund-gefrorene-himbeeren-essen\">Darf ein Hund gefrorene Himbeeren essen?<\/h2>\n<p>Ja, Hunde d\u00fcrfen gefrorene Himbeeren essen, allerdings sollten sie<strong> angetaut<\/strong> oder <strong>bereits komplett aufgetaut<\/strong> sein. Im gefrorenen Zustand k\u00f6nnen sie das Zahnfleisch oder die Z\u00e4hne sch\u00e4digen sowie Probleme beim Schlucken verursachen. Leicht angetaut sind sie dagegen ein leckerer Snack, der bei vielen Hunden \u2013 auch gemischt mit etwas Joghurt \u2013 gut ankommt. Gerade im Sommer sind k\u00fchle Himbeeren eine willkommene Erfrischung.<\/p>\n<h2 id=\"was-passiert-wenn-ein-hund-zu-viele-himbeeren-frisst\">Was passiert, wenn ein Hund zu viele Himbeeren frisst?<\/h2>\n<p>Eine zu gro\u00dfe Menge an Himbeeren kann bei Hunden zu <strong>Bauchgrummeln, Bl\u00e4hungen, weichem Kot und unter Umst\u00e4nden auch Erbrechen<\/strong> f\u00fchren. Ausl\u00f6ser hierf\u00fcr sind der <strong>Fruchtzucker<\/strong>, der den Verdauungstrakt belastet und die Ballaststoffe, die leicht abf\u00fchrend wirken. Die Beschwerden sind in der Regel harmlos und sollten am n\u00e4chsten Tag nicht mehr auftreten. Wenn doch \u2013 oder wenn der Allgemeinzustand deines Hundes nicht gut ist \u2013 solltest du deinen <strong>Tierarzt kontaktieren.<\/strong><\/p>\n<h2 id=\"helfen-himbeeren-bei-durchfall\">Helfen Himbeeren bei Durchfall?<\/h2>\n<p>Nein, du solltest nicht zu Himbeeren greifen, wenn dein Hund Durchfall hat. Besser geeignet ist eine <strong>Morosche Karottensuppe<\/strong>, <strong>gekochter K\u00fcrbis, Schonkost in Form von Huhn mit Reis<\/strong> oder ein <strong>magenschonendes Hundefutter<\/strong>. Von Vorteil kann auch sein, ein oder zwei Mahlzeiten ausfallen zu lassen, damit sich der Magen-Darm-Trakt beruhigt. Bei l\u00e4nger anhaltendem Durchfall ist tier\u00e4rztlicher Rat notwendig.<\/p>\n<h2 id=\"was-sollte-ich-beachten-wenn-ich-meinem-hund-himbeeren-gebe\">Was sollte ich beachten, wenn ich meinem Hund Himbeeren gebe?<\/h2>\n<p>Wenn du deinem Hund Himbeeren f\u00fcttern m\u00f6chtest, achte auf folgende Punkte:<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Verwende nur reife, frische oder aufgetaute Himbeeren.<\/li>\n<li>Wasche die Beeren gr\u00fcndlich, um Schmutz, Keime und Pestizide zu entfernen.<\/li>\n<li>Am besten verwendest du nur Bio-Fr\u00fcchte.<\/li>\n<li>Bei jungen oder sehr kleinen Hunden kannst du die Himbeeren halbieren.<\/li>\n<li>Passe die Menge der Himbeeren an die Gr\u00f6\u00dfe deines Hundes an.<\/li>\n<li>Vermeide Himbeerprodukte mit Zuckerzusatz.<\/li>\n<li>Nutze die Fr\u00fcchte nur als gelegentlichen Snack.<\/li>\n<li>Bei Verdauungsproblemen solltest du die Menge reduzieren.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<h2 id=\"fazit\">Fazit<\/h2>\n<p>Himbeeren sind eine <strong>gesunde und schmackhafte Erg\u00e4nzung<\/strong> f\u00fcr die Ern\u00e4hrung eines Hundes. Sie liefern <strong>wertvolle Vitamine und Antioxidantien<\/strong>, sind <strong>kalorienarm<\/strong> und in der Regel <strong>gut vertr\u00e4glich<\/strong>. Vorsicht ist geboten bei Welpen, \u00fcberm\u00e4\u00dfigem Verzehr und bei Hunden mit empfindlichem Magen. Eine zu gro\u00dfe Menge kann zu Verdauungsproblemen f\u00fchren.<\/p>\n<h2 id=\"quellen\">Quellen<\/h2>\n<ul>\n<li>Simon, Swanie (2008). <strong>BARF - Biologisch Artgerechtes Rohes Futter f\u00fcr Hunde<\/strong>. Drei Hunde Nacht<\/li>\n<li>Esch-V\u00f6lkel, Sylvia (2014). <strong>Buntes f\u00fcr den Hund<\/strong>. Kalidor<\/li>\n<li>Dr. Bucksch, Martin (2017). <strong>Gesunde Ern\u00e4hrung f\u00fcr Hunde: Fertigfutter oder selbstgemacht - gesundes Futter f\u00fcr jeden Hund<\/strong>. KOSMOS Verlag<\/li>\n<li>Meyer, Helmut (2016). <strong>Ern\u00e4hrung des Hundes: Grundlagen - F\u00fctterung - Di\u00e4tetik<\/strong>. Enke<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-38425-3\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-38425-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-38425-3-0-0\" class=\"so-panel widget widget_zr_widget_authorprofile panel-first-child panel-last-child\" data-index=\"3\" >\n    <hr>\n    <div class=\"author-profile-container\">\n\n        <img width=\"150\" height=\"150\" src=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/05\/Thomas-Brodmann-und-Johnny-150x150.jpg\" class=\"alignleft size-thumbnail author-profile-image wp-post-image\" alt=\"Thomas Brodmann\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/05\/Thomas-Brodmann-und-Johnny-150x150.jpg 150w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/05\/Thomas-Brodmann-und-Johnny-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\n        <p>\n            <a href=\"https:\/\/www.zooroyal.at\/magazin\/ueber-uns\/redaktion\/thomas-brodmann\/\">Thomas Brodmann<\/a>, Autor & Tierfotograf       <\/p>\n\n        Als freier Journalist und Fotograf ist Thomas auf Haustiere und Wildtiere spezialisiert - mit mittlerweile bereits \u00fcber 20 Jahren Erfahrung. Er schrieb bereits f\u00fcr zahlreiche bekannte Tiermagazine und ver\u00f6ffentlichte 2017 sein Buch \"Unser Hund fit und gesund\", in dem er wertvolle Tipps rund um die Ern\u00e4hrung und Gesundheit von Hunden gibt.\n        \n         <!-- Clearfix f\u00fcr den float -->\n        <div style=\"clear: both;\"><\/div>\n    <\/div>\n    <hr>\n\n<\/div><\/div><\/div><div id=\"pg-38425-4\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-38425-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-38425-4-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898-38425\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-trinkflasche-mit-napf\/1000104530\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Trinkflasche mit Napf\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/58nwte-428dCArz.jpg?host=ct\"\n                alt=\"ZooRoyal Trinkflasche mit Napf\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Trinkflasche mit Napf<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    2.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-trinkflasche-mit-napf\/1000104530\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-wild-6x400g\/1000101589\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Rind + Wild 6x400g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/qip9nv-pe_DGg2L.jpg?host=ct\"\n                alt=\"ZooRoyal Rind + Wild 6x400g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Rind + Wild 6x400g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    9.49 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        3.95 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-wild-6x400g\/1000101589\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-100g\/1000080678\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Mini Burger reich an Rind 100g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/g9ibfl-MRzkD-WE.jpg?host=ct\"\n                alt=\"ZooRoyal Mini Burger reich an Rind 100g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Mini Burger reich an Rind 100g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    1.99 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        19.90 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-100g\/1000080678\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a04a80ebc495\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-trinkflasche-mit-napf\/1000104530\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Trinkflasche mit Napf\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/58nwte-428dCArz.jpg?host=ct\"\n                                    alt=\"ZooRoyal Trinkflasche mit Napf\">\n\n                            <div id=\"swiper-button-next6a04a80ebc495\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04a80ebc495\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Trinkflasche mit Napf<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                2.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-trinkflasche-mit-napf\/1000104530\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-wild-6x400g\/1000101589\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Rind + Wild 6x400g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/qip9nv-pe_DGg2L.jpg?host=ct\"\n                                    alt=\"ZooRoyal Rind + Wild 6x400g\">\n\n                            <div id=\"swiper-button-next6a04a80ebc495\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04a80ebc495\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Rind + Wild 6x400g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                9.49 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    3.95 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-rind-wild-6x400g\/1000101589\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-100g\/1000080678\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Mini Burger reich an Rind 100g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/g9ibfl-MRzkD-WE.jpg?host=ct\"\n                                    alt=\"ZooRoyal Mini Burger reich an Rind 100g\">\n\n                            <div id=\"swiper-button-next6a04a80ebc495\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04a80ebc495\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Mini Burger reich an Rind 100g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                1.99 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    19.90 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/zooroyal-mini-burger-reich-an-rind-100g\/1000080678\/?icid=magproteaser_hunde_ernaehrung-hunde_duerfen-hunde-himbeeren-essen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a04a80ebc495\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a04a80ebc495\",\n                prevEl: \"#swiper-button-prev6a04a80ebc495\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ja, Hunde d\u00fcrfen Himbeeren essen. Die roten Beeren sind sehr gesund und gelten als gut vertr\u00e4glich. Dennoch sollten die Fr\u00fcchte nur gelegentlich als Snack dienen oder eine kleine Erg\u00e4nzung des&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":71,"featured_media":38431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,5],"tags":[91,7036,7127,7125,7073,6660,7078,7126,6666,86,4618,6096,6659,6483],"class_list":["post-38425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung-hunde","category-hunde","tag-barf","tag-barf-fuer-hunde","tag-beeren","tag-duerfen-hunde-himbeeren-essen","tag-fruechte","tag-gesunde-lebensmittel-fuer-hunde","tag-gesundes-obst-fuer-hunde","tag-himbeeren","tag-hund-barfen","tag-hundefutter","tag-obst","tag-obst-fuer-hunde","tag-was-duerfen-hunde-essen","tag-was-duerfen-hunde-nicht-fressen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00fcrfen Hunde Himbeeren essen? Das musst du beachten<\/title>\n<meta name=\"description\" content=\"D\u00fcrfen Hunde Himbeeren essen? Erfahre, wie gesund Himbeeren f\u00fcr Hunde sind, welche Menge erlaubt ist &amp; worauf du bei Welpen achten solltest.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00fcrfen Hunde Himbeeren essen?\" \/>\n<meta property=\"og:description\" content=\"D\u00fcrfen Hunde Himbeeren essen? Erfahre, wie gesund Himbeeren f\u00fcr Hunde sind, welche Menge erlaubt ist &amp; worauf du bei Welpen achten solltest.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T07:47:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T07:49:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/465a6b7bbd4547048048a47bb9bd5012\"},\"headline\":\"D\u00fcrfen Hunde Himbeeren essen?\",\"datePublished\":\"2026-05-13T07:47:57+00:00\",\"dateModified\":\"2026-05-13T07:49:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/\"},\"wordCount\":1066,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg\",\"keywords\":[\"Barf\",\"Barf f\u00fcr Hunde\",\"Beeren\",\"D\u00fcrfen Hunde Himbeeren essen?\",\"Fr\u00fcchte\",\"Gesunde Lebensmittel f\u00fcr Hunde\",\"gesundes Obst f\u00fcr Hunde\",\"Himbeeren\",\"Hund barfen\",\"Hundefutter\",\"obst\",\"Obst f\u00fcr Hunde\",\"Was d\u00fcrfen Hunde essen?\",\"was d\u00fcrfen Hunde nicht fressen\"],\"articleSection\":[\"Ern\u00e4hrung\",\"Hunde Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/\",\"name\":\"D\u00fcrfen Hunde Himbeeren essen? Das musst du beachten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg\",\"datePublished\":\"2026-05-13T07:47:57+00:00\",\"dateModified\":\"2026-05-13T07:49:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/465a6b7bbd4547048048a47bb9bd5012\"},\"description\":\"D\u00fcrfen Hunde Himbeeren essen? Erfahre, wie gesund Himbeeren f\u00fcr Hunde sind, welche Menge erlaubt ist & worauf du bei Welpen achten solltest.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg\",\"width\":760,\"height\":570,\"caption\":\"Hund schnuppert an frischen Himbeeren am Strauch \u2013 d\u00fcrfen Hunde Himbeeren essen?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/ernaehrung-hunde\\\/duerfen-hunde-himbeeren-essen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00fcrfen Hunde Himbeeren essen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/465a6b7bbd4547048048a47bb9bd5012\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g\",\"caption\":\"ZooRoyal\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00fcrfen Hunde Himbeeren essen? Das musst du beachten","description":"D\u00fcrfen Hunde Himbeeren essen? Erfahre, wie gesund Himbeeren f\u00fcr Hunde sind, welche Menge erlaubt ist & worauf du bei Welpen achten solltest.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/","og_locale":"de_DE","og_type":"article","og_title":"D\u00fcrfen Hunde Himbeeren essen?","og_description":"D\u00fcrfen Hunde Himbeeren essen? Erfahre, wie gesund Himbeeren f\u00fcr Hunde sind, welche Menge erlaubt ist & worauf du bei Welpen achten solltest.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2026-05-13T07:47:57+00:00","article_modified_time":"2026-05-13T07:49:01+00:00","og_image":[{"width":760,"height":570,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/465a6b7bbd4547048048a47bb9bd5012"},"headline":"D\u00fcrfen Hunde Himbeeren essen?","datePublished":"2026-05-13T07:47:57+00:00","dateModified":"2026-05-13T07:49:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/"},"wordCount":1066,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg","keywords":["Barf","Barf f\u00fcr Hunde","Beeren","D\u00fcrfen Hunde Himbeeren essen?","Fr\u00fcchte","Gesunde Lebensmittel f\u00fcr Hunde","gesundes Obst f\u00fcr Hunde","Himbeeren","Hund barfen","Hundefutter","obst","Obst f\u00fcr Hunde","Was d\u00fcrfen Hunde essen?","was d\u00fcrfen Hunde nicht fressen"],"articleSection":["Ern\u00e4hrung","Hunde Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/","name":"D\u00fcrfen Hunde Himbeeren essen? Das musst du beachten","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg","datePublished":"2026-05-13T07:47:57+00:00","dateModified":"2026-05-13T07:49:01+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/465a6b7bbd4547048048a47bb9bd5012"},"description":"D\u00fcrfen Hunde Himbeeren essen? Erfahre, wie gesund Himbeeren f\u00fcr Hunde sind, welche Menge erlaubt ist & worauf du bei Welpen achten solltest.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2026\/05\/Duerfen-Hunde-Himbeeren-essen-760x570-1.jpg","width":760,"height":570,"caption":"Hund schnuppert an frischen Himbeeren am Strauch \u2013 d\u00fcrfen Hunde Himbeeren essen?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/ernaehrung-hunde\/duerfen-hunde-himbeeren-essen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"D\u00fcrfen Hunde Himbeeren essen?"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/465a6b7bbd4547048048a47bb9bd5012","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g","caption":"ZooRoyal"}}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/38425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=38425"}],"version-history":[{"count":7,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/38425\/revisions"}],"predecessor-version":[{"id":38433,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/38425\/revisions\/38433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/38431"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=38425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=38425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=38425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}