{"id":31736,"date":"2024-03-08T10:19:29","date_gmt":"2024-03-08T09:19:29","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=31736"},"modified":"2024-03-08T10:19:29","modified_gmt":"2024-03-08T09:19:29","slug":"schmuckhornfrosch","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/","title":{"rendered":"Schmuckhornfrosch"},"content":{"rendered":"<div id=\"pl-31736\" class=\"panel-layout\">\n<div id=\"pg-31736-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-31736-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-31736-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-31738 size-featured-whatever\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781-760x570.jpg\" alt=\"Schmuckhornfrosch\" width=\"760\" height=\"570\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781-760x570.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781-700x525.jpg 700w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781-233x175.jpg 233w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781-175x131.jpg 175w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781-323x242.jpg 323w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><\/p>\n\n<style>\n    .characterGrid {\n        display: grid;\n        grid-template-columns: auto auto auto auto;\n    }\n\n    .characterGrid div {\n        padding: 0.25em;\n    }\n<\/style>\n\n<div class=\"characteristics\">\n    <div class=\"header\">\n        <h2>Schmuckhornfrosch<\/h2>\n        <div class=\"badge\">\n            <i class=\"halflings halflings-ok\"><\/i>         <\/div>\n    <\/div>\n\n    <div width=\"100%\" class=\"characterGrid\">\n\t\t            <div><strong>Name<\/strong><\/div>\n            <div>Schmuckhornfrosch<\/div>\n\t\t            <div><strong>Wissenschaftlicher Name<\/strong><\/div>\n            <div>Ceratophrys<\/div>\n\t\t            <div><strong>Klasse<\/strong><\/div>\n            <div>Amphibien<\/div>\n\t\t            <div><strong>Ordnung<\/strong><\/div>\n            <div>Froschlurche<\/div>\n\t\t            <div><strong>Familie<\/strong><\/div>\n            <div>Hornfr\u00f6sche<\/div>\n\t\t            <div><strong>Lebenserwartung<\/strong><\/div>\n            <div>10-15 Jahre<\/div>\n\t\t            <div><strong>Charakter<\/strong><\/div>\n            <div>Gem\u00fctlich<\/div>\n\t\t            <div><strong>Gr\u00f6\u00dfe\/L\u00e4nge<\/strong><\/div>\n            <div>bis zu 20cm<\/div>\n\t\t            <div><strong>Gewicht<\/strong><\/div>\n            <div>bis zu 300g<\/div>\n\t\t            <div><strong>Herkunft\/Lebensraum<\/strong><\/div>\n            <div>S\u00fcdamerika<\/div>\n\t\t            <div><strong>Merkmale<\/strong><\/div>\n            <div>Horn \u00fcber den Augen, gro\u00dfes Maul<\/div>\n\t\t            <div><strong>K\u00f6rperbau<\/strong><\/div>\n            <div>Kr\u00e4ftig<\/div>\n\t\t            <div><strong>Kopfform<\/strong><\/div>\n            <div>Rund<\/div>\n\t\t            <div><strong>Augen<\/strong><\/div>\n            <div>Gro\u00df, k\u00f6nnen eingezogen werden<\/div>\n\t\t            <div><strong>Pflege<\/strong><\/div>\n            <div>Mittel<\/div>\n\t\t            <div><strong>Geschlechtsreife<\/strong><\/div>\n            <div>2 Jahre<\/div>\n\t\t            <div><strong>Wurfgr\u00f6\u00dfe<\/strong><\/div>\n            <div>bis zu 300 Eier<\/div>\n\t\t            <div><strong>Gesundheit<\/strong><\/div>\n            <div>Robust<\/div>\n\t\t            <div><strong>Ern\u00e4hrung<\/strong><\/div>\n            <div>Insekten, M\u00e4use<\/div>\n\t\t            <div><strong>Besonderheiten<\/strong><\/div>\n            <div>D\u00e4mmerungs- und nachtaktiv<\/div>\n\t\t    <\/div>\n\n    <\/div>\n<!-- \/characteristics --><div class=\"mobile-toc\"><\/div>\n\n<h2 id=\"rassemerkmale-und-erscheinungsbild\">Rassemerkmale und Erscheinungsbild<\/h2>\n<h3 id=\"wie-sieht-ein-schmuckhornfrosch-aus\">Wie sieht ein Schmuckhornfrosch aus?<\/h3>\n<p>Namensgebend sind die <strong>Hornforts&auml;tze<\/strong> &uuml;ber den Augen, einige Arten haben auch ein <strong>Knochenschild am R&uuml;cken<\/strong>. Weiteres Merkmal ist ihr Riesen-Maul, der <strong>Spitzname &ldquo;Ball mit Maul&ldquo;<\/strong> passt wirklich sehr gut. Sie sind kugelrund mit abstehenden Augen, die Augen k&ouml;nnen nicht nur geschlossen sondern auch eingezogen werden. Bei Gefahr ist dann wirklich nur ein runder Ball sichtbar. Sie bei&szlig;en blitzschnell zu, im Maul sind Z&auml;hne und eine gro&szlig;e, ovale, klebrige Zunge, mit der sie die Beute bestens festhalten k&ouml;nnen. Die Beine sind kr&auml;ftig und erm&ouml;glichen es, mit einem Sprung die Beute zu erreichen. Ihre F&auml;rbungen sind einzigartig und wundersch&ouml;n, die Grundfarbe ist meist braun oder gr&uuml;n, es gibt auch Arten mit gelb, blau, orange oder rot.<\/p>\n<p>Der K&ouml;rper ist mit einem fleckigen Muster &uuml;berzogen, &auml;hnlich wie ein Camouflage-Muster. Die Flecken sind meist dunkelbraun und schwarz umrandet, es gibt aber auch gelbe Tiere mit orangenen Flecken, die hell umrandet sind. Sie erreichen eine <strong>Gr&ouml;&szlig;e von 15-22cm<\/strong>, Weibchen werden deutlich gr&ouml;&szlig;er, bei einem Gewicht von bis zu 300g. Die <strong>Lebenserwartung<\/strong> liegt bei etwa <strong>10-15 Jahren<\/strong>, es sind auch &auml;ltere Tiere bekannt.<\/p>\n<p>Das Geschlecht ist bei Jungtieren <strong>nicht zu erkennen<\/strong>, ausgewachsene M&auml;nnchen sind kleiner, bilden Brunftschwielen und haben eine dunkle Kehle. Eine Zucht ist m&ouml;glich, aber sehr schwer, da viele Bedingungen geschaffen werden m&uuml;ssen. Dabei gibt es einiges zu beachten. Geschlechtsreif sind sie mit ca. 2 Jahren und sie legen <a href=\"https:\/\/www.zooroyal.de\/magazin\/terraristik\/inkubationszubehoer\/\"><strong>bis zu 300 Eier<\/strong><\/a>.<\/p>\n<h3 id=\"welche-eigenschaften-hat-ein-schmuckhornfrosch\">Welche Eigenschaften hat ein Schmuckhornfrosch?<\/h3>\n<p>Hornfr&ouml;sche sind <strong>Einzelg&auml;nger<\/strong> und <strong>Ansitzj&auml;ger<\/strong>. Das bedeutet, sie lauern regungslos am Boden auf Beute. Untertags liegen sie im Moos oder leicht eingegraben in der Erde herum. Sie sind <strong>d&auml;mmerungs- und nachtaktiv<\/strong>, also wandern sie nur nachts herum. Oft verharren sie tagelang am selben Fleck, in den anderen N&auml;chten sind sie aktiver und liegen jeden Tag an einem anderen Ort.<br \/>\nWenn du Arbeiten im Terrarium erledigen m&ouml;chtest, f&uuml;ttere ihn vorher, er schnappt nach allem was sich bewegt, auch nach deiner Hand. Da sie Z&auml;hne besitzen kann der Biss schmerzhaft sein.<\/p>\n<h2 id=\"herkunft-und-geschichte\">Herkunft und Geschichte<\/h2>\n<h3 id=\"wo-kommt-der-schmuckhornfrosch-ursprnglich-her\">Wo kommt der Schmuckhornfrosch urspr&uuml;nglich her?<\/h3>\n<p>Heimisch ist er in <strong>S&uuml;damerika, Brasilien, Argentinien und Uruguay<\/strong>. Je nach Herkunft entstanden die unterschiedlichen Farben, die nat&uuml;rlich durch Zucht noch weiter ver&auml;ndert wurden.<\/p>\n<h3 id=\"gibt-es-noch-andere-schmuckhornfrosch-arten\">Gibt es noch andere Schmuckhornfrosch-Arten?<\/h3>\n<p>Unterschieden wird zwischen 8 Schmuckhornfrosch-Arten. Zu den h&auml;ufigsten in der Terrarien-Haltung z&auml;hlt definitiv der <strong>Cranwelli<\/strong>, weit dahinter dann der <strong>Cornuta<\/strong> und der <strong>Ornata<\/strong>. Mittlerweile gibt es auch Kreuzungen der verschiedenen Arten.<\/p>\n<h2 id=\"ernhrung-haltung-und-pflege\">Ern&auml;hrung, Haltung und Pflege<\/h2>\n<h3 id=\"gibt-es-beim-schmuckhornfrosch-rassetypische-krankheiten\">Gibt es beim Schmuckhornfrosch rassetypische Krankheiten?<\/h3>\n<p>Jungtiere sind leider oft von Parasiten befallen, ansonsten sind Schmuckhornfr&ouml;sche nicht extrem anf&auml;llig und z&auml;hlen daher zu den robusten Fr&ouml;schen. Wie bei allen Fr&ouml;schen k&ouml;nnen Infektionen, Pilze, Mangelerscheinungen und W&uuml;rmer auftreten, die oft auf <strong>mangelnde Hygiene, falsche Ern&auml;hrung oder fehlerhafte Haltung<\/strong> zur&uuml;ckzuf&uuml;hren sind. Achte daher immer auf ein <a href=\"\/magazin\/terraristik\/hygiene-im-terrarium\/\">gepflegtes Terrarium<\/a> und beste Bedingungen. F&uuml;ttere hochwertig und beobachte deinen Frosch, um Ver&auml;nderungen schnell zu erkennen.<\/p>\n<h3 id=\"welches-futter-braucht-ein-schmuckhornfrosch\">Welches Futter braucht ein Schmuckhornfrosch?<\/h3>\n<p>Der Schmuckhornfrosch ist ein sehr gieriger <strong>Allesfresser<\/strong>, er bevorzugt aber lebende Insekten, wie Heuschrecken, Grillen und Schaben. Regenw&uuml;rmer und Nacktschnecken mag er auch sehr gerne. Ab und zu soll er auch eiwei&szlig;reiches Futter, wie Mehlw&uuml;rmer, M&auml;use oder Zophobas, bekommen. Das Futter muss regelm&auml;&szlig;ig mit Mineralien, Vitaminen und Kalzium angereichert werden. Jungtiere werden <strong>t&auml;glich gef&uuml;ttert<\/strong>. Ausgewachsenen Tiere neigen zu &Uuml;bergewicht, eine <strong>F&uuml;tterung 2x pro Woche<\/strong> ist daher ausreichend. Achte auf eine abwechslungsreiche und hochwertige F&uuml;tterung.<\/p>\n<h2 id=\"berlegungen-vor-der-anschaffung\">&Uuml;berlegungen vor der Anschaffung<\/h2>\n<h3 id=\"wo-kann-man-einen-schmuckhornfrosch-kaufen\">Wo kann man einen Schmuckhornfrosch kaufen?<\/h3>\n<p>Schmuckhornfr&ouml;sche k&ouml;nnen im <strong>Zoofachhandel<\/strong> oder bei <strong>Z&uuml;chtern<\/strong> gekauft werden. Ab und zu sind auch welche durch private Abgaben oder in der Reptilienauffangstation zu finden. In Online-Fachgesch&auml;ften wirst du auch f&uuml;ndig, achte aber auf einen Express-Tierversand. Achte beim Kauf immer darauf, dass es eine Nachzucht ist.<\/p>\n<h3 id=\"was-brauche-ich-fr-die-haltung-eines-schmuckhornfrosches\">Was brauche ich f&uuml;r die Haltung eines Schmuckhornfrosches?<\/h3>\n<p>Der Schmuckhornfrosch ist ein <strong>Einzelg&auml;nger<\/strong>, du ben&ouml;tigst zur Haltung ein Terrarium mit den Ma&szlig;en 80x40x40cm. Dieses muss mit einer <a href=\"\/magazin\/terraristik\/terrarienbeleuchtung\/\">geeigneten Beleuchtung<\/a>, die eine Temperaturzone von 24-30&deg;C erm&ouml;glicht, ausgestattet sein. Eine Nachtabsenkung auf 21-22&deg;C Zimmertemperatur ist problemlos m&ouml;glich. Die Luftfeuchtigkeit soll immer bei 70-90% liegen. Um dies zu gew&auml;hrleisten, eignet sich am besten eine <strong>Regenanlage<\/strong> oder du spr&uuml;hst das Terrarium mehrmals t&auml;glich von Hand ein. &Uuml;berpr&uuml;fe bitte t&auml;glich die <strong>Temperatur<\/strong> und die <strong>Luftfeuchtigkeit<\/strong>.<\/p>\n<p>Der Boden muss mit einer feinen, grabf&auml;higen, Terrarien-Erde oder einem feinen Kokoshumus, mindestens 10cm dick, bedeckt sein, damit sich der Frosch auch komplett eingraben kann. Den <strong>Bodengrund<\/strong> musst du immer komplett feucht aber nicht nass halten. <strong>Echte Pflanzen<\/strong> d&uuml;rfen auch nicht fehlen, gerne viele davon. F&uuml;r einen <strong>R&uuml;ckzugsort<\/strong> eignet sich eine <strong>H&ouml;hle<\/strong> oder eine <strong>Kokosnussschale<\/strong>. Ein <strong>Wasserbecken<\/strong> darf auch nicht fehlen, aber bitte ein flaches, ohne hohen Rand und mit niederem Wasserstand, ansonsten kann er darin ertrinken. Dann noch Laub und Moos um verschiedene Untergr&uuml;nde zu bieten und fertig ist das Terrarium.<\/p>\n<p>Entferne t&auml;glich Kot- und Futterreste und wechsle das Wasser aus, den Bodengrund solltest du einmal j&auml;hrlich erneuern.<\/p>\n<p>Eine <strong>Trockenruhe im Winter<\/strong> sorgt f&uuml;r eine nat&uuml;rliches Habitat und f&ouml;rdert die Gesundheit deines Frosches.<\/p>\n<h3 id=\"wissenswertes\">Wissenswertes<\/h3>\n<ul>\n<li>Im Englischen wird er wide-mouthed-frog, also Breitmaulfrosch, genannt.<\/li>\n<li>Er ist auch als PAC-MAN Frosch bekannt.<\/li>\n<li>1758 wurde der Hornfrosch bereits beschrieben.<\/li>\n<li>Leider werden ab und zu noch Wildf&auml;nge verkauft, achte daher immer auf Nachzuchten.<\/li>\n<li>K&ouml;nnen bei&szlig;en, durch die Z&auml;hne ist dies sehr schmerzhaft.<\/li>\n<li>Sie neigen zu Kannibalismus, daher immer Einzelhaltung.<\/li>\n<\/ul>\n<hr>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24256 size-medium alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/05\/shaka-animal-300x221.jpg\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/05\/shaka-animal-300x221.jpg 300w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/05\/shaka-animal.jpg 760w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/05\/shaka-animal-323x238.jpg 323w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/05\/shaka-animal-380x280.jpg 380w\" alt=\"Shaka Animal Studio\" width=\"300\" height=\"221\"><a href=\"\/magazin\/zoo-experten\/gastautoren-experten\/shaka-animal-studio\/\">Shaka Animal Studio<\/a>, Jacky und Tobi.<\/strong>&nbsp;Jacky hat die Faszination Reptilien schon vor langer Zeit gepackt. Seit &uuml;ber 15 Jahren h&auml;lt sie Reptilien aller Art. Sie ist gelernte Tierpflegerin und Tiertherapeutin. Sie hat Berufserfahrung sowohl in Zoos als auch bei Tier&auml;rzten. Tobi ist Fotograf und von klein auf begeistert von der Tierwelt. Die Unterwasserwelten sind sein Herzst&uuml;ck, die er schon seit vielen Jahren betreibt. Im Laufe der Zeit entstand zu Hause ein privater Zoo, den sie t&auml;glich voller Liebe gemeinsam versorgen und den sie regelm&auml;&szlig;ig auf ihrem.&nbsp;<a href=\"https:\/\/www.youtube.com\/channel\/UCN5nEqas3flfWm9cIBSigoA\/featured\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Youtube Kanal<\/a>&nbsp;pr&auml;sentieren.<\/p>\n<hr>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pg-31736-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-31736-1-0\" class=\"panel-grid-cell\" data-weight=\"0.5\">\n<div id=\"panel-31736-1-0-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"1\"><\/div>\n<\/div>\n<div id=\"pgc-31736-1-1\" class=\"panel-grid-cell\" data-weight=\"0.5\">\n<div id=\"panel-31736-1-1-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"2\"><\/div>\n<\/div>\n<\/div>\n<div id=\"pg-31736-2\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-31736-2-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-31736-2-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-terra-tec-h2o-5000-ml\/1000109403\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" class=\"article__wrapper--productimage\" title=\"Lucky Reptile Terra-Tec H2O 5000 ml\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/vgvjwm-j_ymQkUW.jpg?host=ct\"\n                alt=\"Lucky Reptile Terra-Tec H2O 5000 ml\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Lucky Reptile                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Lucky Reptile Terra-Tec H2O 5000 ml<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    6.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-terra-tec-h2o-5000-ml\/1000109403\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/variogart-deko-welshoehle-i\/1000075345\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" class=\"article__wrapper--productimage\" title=\"Variogart Deko Welsh\u00f6hle I\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/q7wk3x-gELGOhyo.jpg?host=ct\"\n                alt=\"Variogart Deko Welsh\u00f6hle I\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Variogart                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Variogart Deko Welsh\u00f6hle I<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    11.79 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/variogart-deko-welshoehle-i\/1000075345\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-critter-box-gross-11x19-cm\/1000109428\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" class=\"article__wrapper--productimage\" title=\"Lucky Reptile Critter Box gro\u00df 11x19 cm\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/6vbd8l-5THOTYy1.jpg?host=ct\"\n                alt=\"Lucky Reptile Critter Box gro\u00df 11x19 cm\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Lucky Reptile                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Lucky Reptile Critter Box gro\u00df 11x19 cm<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    12.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-critter-box-gross-11x19-cm\/1000109428\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a03c4ed9c1fe\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-terra-tec-h2o-5000-ml\/1000109403\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" class=\"article__wrapper--productimage\" title=\"Lucky Reptile Terra-Tec H2O 5000 ml\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/vgvjwm-j_ymQkUW.jpg?host=ct\"\n                                    alt=\"Lucky Reptile Terra-Tec H2O 5000 ml\">\n\n                            <div id=\"swiper-button-next6a03c4ed9c1fe\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03c4ed9c1fe\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Lucky Reptile                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Lucky Reptile Terra-Tec H2O 5000 ml<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                6.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-terra-tec-h2o-5000-ml\/1000109403\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/variogart-deko-welshoehle-i\/1000075345\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" class=\"article__wrapper--productimage\" title=\"Variogart Deko Welsh\u00f6hle I\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/q7wk3x-gELGOhyo.jpg?host=ct\"\n                                    alt=\"Variogart Deko Welsh\u00f6hle I\">\n\n                            <div id=\"swiper-button-next6a03c4ed9c1fe\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03c4ed9c1fe\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Variogart                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Variogart Deko Welsh\u00f6hle I<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                11.79 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/variogart-deko-welshoehle-i\/1000075345\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-critter-box-gross-11x19-cm\/1000109428\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" class=\"article__wrapper--productimage\" title=\"Lucky Reptile Critter Box gro\u00df 11x19 cm\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/6vbd8l-5THOTYy1.jpg?host=ct\"\n                                    alt=\"Lucky Reptile Critter Box gro\u00df 11x19 cm\">\n\n                            <div id=\"swiper-button-next6a03c4ed9c1fe\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03c4ed9c1fe\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Lucky Reptile                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Lucky Reptile Critter Box gro\u00df 11x19 cm<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                12.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/lucky-reptile-critter-box-gross-11x19-cm\/1000109428\/?icid=magproteaser_terraristik_terrarienbewohner_schmuckhornfrosch_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a03c4ed9c1fe\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a03c4ed9c1fe\",\n                prevEl: \"#swiper-button-prev6a03c4ed9c1fe\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rassemerkmale und Erscheinungsbild Wie sieht ein Schmuckhornfrosch aus? Namensgebend sind die Hornforts&auml;tze &uuml;ber den Augen, einige Arten haben auch ein Knochenschild am R&uuml;cken. Weiteres Merkmal ist ihr Riesen-Maul, der Spitzname&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":15,"featured_media":31738,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,4],"tags":[300,303,2106,788,5599,4551,832],"class_list":["post-31736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-terrarienbewohner","category-terraristik","tag-amphibien","tag-frosch","tag-froschlurch","tag-rasseportrait","tag-schmuckhornfrosch","tag-steckbrief","tag-terraristik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Schmuckhornfrosch - Pflege, Haltung &amp; Lebensraum | Steckbrief<\/title>\n<meta name=\"description\" content=\"Der Schmuckhornfrosch: leuchtende Farben, markante Muster, kn\u00f6cherne H\u00f6rner und auff\u00e4llige Augen. Hier erf\u00e4hrst du mehr \u00fcber die Rasse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schmuckhornfrosch\" \/>\n<meta property=\"og:description\" content=\"Der Schmuckhornfrosch: leuchtende Farben, markante Muster, kn\u00f6cherne H\u00f6rner und auff\u00e4llige Augen. Hier erf\u00e4hrst du mehr \u00fcber die Rasse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T09:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"headline\":\"Schmuckhornfrosch\",\"datePublished\":\"2024-03-08T09:19:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/\"},\"wordCount\":1186,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Bearbeitet-7781.jpg\",\"keywords\":[\"Amphibien\",\"Frosch\",\"Froschlurch\",\"Rasseportrait\",\"schmuckhornfrosch\",\"steckbrief\",\"Terraristik\"],\"articleSection\":[\"Terrarienbewohner\",\"Terraristik Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/\",\"name\":\"Schmuckhornfrosch - Pflege, Haltung & Lebensraum | Steckbrief\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Bearbeitet-7781.jpg\",\"datePublished\":\"2024-03-08T09:19:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"description\":\"Der Schmuckhornfrosch: leuchtende Farben, markante Muster, kn\u00f6cherne H\u00f6rner und auff\u00e4llige Augen. Hier erf\u00e4hrst du mehr \u00fcber die Rasse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Bearbeitet-7781.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Bearbeitet-7781.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Schmuckhornfrosch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/terraristik\\\/terrarienbewohner\\\/schmuckhornfrosch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schmuckhornfrosch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZooRoyalDE\",\"https:\\\/\\\/x.com\\\/zooroyal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Schmuckhornfrosch - Pflege, Haltung & Lebensraum | Steckbrief","description":"Der Schmuckhornfrosch: leuchtende Farben, markante Muster, kn\u00f6cherne H\u00f6rner und auff\u00e4llige Augen. Hier erf\u00e4hrst du mehr \u00fcber die Rasse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/","og_locale":"de_DE","og_type":"article","og_title":"Schmuckhornfrosch","og_description":"Der Schmuckhornfrosch: leuchtende Farben, markante Muster, kn\u00f6cherne H\u00f6rner und auff\u00e4llige Augen. Hier erf\u00e4hrst du mehr \u00fcber die Rasse.","og_url":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_author":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2024-03-08T09:19:29+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"headline":"Schmuckhornfrosch","datePublished":"2024-03-08T09:19:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/"},"wordCount":1186,"commentCount":2,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781.jpg","keywords":["Amphibien","Frosch","Froschlurch","Rasseportrait","schmuckhornfrosch","steckbrief","Terraristik"],"articleSection":["Terrarienbewohner","Terraristik Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/","url":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/","name":"Schmuckhornfrosch - Pflege, Haltung & Lebensraum | Steckbrief","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781.jpg","datePublished":"2024-03-08T09:19:29+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"description":"Der Schmuckhornfrosch: leuchtende Farben, markante Muster, kn\u00f6cherne H\u00f6rner und auff\u00e4llige Augen. Hier erf\u00e4hrst du mehr \u00fcber die Rasse.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2024\/03\/Bearbeitet-7781.jpg","width":1080,"height":720,"caption":"Schmuckhornfrosch"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/terraristik\/terrarienbewohner\/schmuckhornfrosch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Schmuckhornfrosch"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.facebook.com\/ZooRoyalDE","https:\/\/x.com\/zooroyal"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/31736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=31736"}],"version-history":[{"count":27,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/31736\/revisions"}],"predecessor-version":[{"id":31797,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/31736\/revisions\/31797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/31738"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=31736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=31736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=31736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}