{"id":28250,"date":"2023-06-23T08:20:34","date_gmt":"2023-06-23T06:20:34","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=28250"},"modified":"2024-04-08T14:47:47","modified_gmt":"2024-04-08T12:47:47","slug":"katzen-mythologie","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/","title":{"rendered":"Katzen Mythologie und andere Kulturen"},"content":{"rendered":"<div id=\"pl-28250\" class=\"panel-layout\">\n<div id=\"pg-28250-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-28250-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-28250-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28346\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg\" alt=\"Katzen Mythologie\" width=\"760\" height=\"570\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1-300x225.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1-747x560.jpg 747w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1-700x525.jpg 700w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1-233x175.jpg 233w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1-175x131.jpg 175w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1-323x242.jpg 323w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/p>\n<p>Elegant, geheimnisvoll und unnachahmlich unabh&auml;ngig &ndash; <strong>Katzen<\/strong> sind seit Jahrtausenden an der Seite des Menschen. In vielen <strong>verschiedenen Kulturen<\/strong> haben diese eleganten Raubtiere eine <strong>besondere Rolle<\/strong> eingenommen und beeindruckende Spuren hinterlassen. Die fr&uuml;heste nachgewiesene <strong>Verbindung zwischen Katzen und Menschen<\/strong> reicht bis vor etwa 9500 Jahren zur&uuml;ck. Da finden sich die Anf&auml;nge des Ackerbaus im Nahen Osten, und es war mehr als praktisch, dass die &ndash; damals noch wilden &ndash; Katzen Ratten und M&auml;use vernichteten und dadurch zum Erhalt der Ernte beitrugen. Eine sehr n&uuml;tzliche Ko-existenz! Doch weit &uuml;ber den reinen Nutzen hinaus ist die Anziehungskraft einer Katze zeitlos und reicht von den majest&auml;tischen Tempeln des alten &Auml;gyptens bis hin zu den modernen Wohnzimmern heutiger Katzenliebhaber. Begleite mich in die spannende <strong>Welt der Katzen der Katzen Mythologie<\/strong> und entdecken ihren Stellenwert und ihre Bedeutung in verschiedenen Kulturen rund um den Globus.<\/p>\n<h2 id=\"gypten\">&Auml;gypten<\/h2>\n<p>Die wohl bekannteste historische Beziehung zwischen Katzen und Menschen stammt aus dem alten &Auml;gypten. Hier wurden Katzen als heilige Tiere verehrt und dienten als <strong>Symbol f&uuml;r Fruchtbarkeit, Schutz und Wohlstand<\/strong>. Die G&ouml;ttin Bastet, oft dargestellt als L&ouml;win oder Frau mit Katzenkopf, war eine der wichtigsten <strong>Gottheiten<\/strong> im &auml;gyptischen Pantheon. Katzen wurden so gesch&auml;tzt, dass sie oft mumifiziert und neben ihren Besitzern begraben wurden. Es war sogar gesetzlich verboten, Katzen au&szlig;erhalb &Auml;gyptens zu bringen, um ihre Population zu sch&uuml;tzen.<\/p>\n<h2 id=\"indien\">Indien<\/h2>\n<p>In Indien gibt es verschiedene Mythen und Legenden, die Katzen mit einschlie&szlig;en. Eine der bekanntesten ist die Geschichte von der <strong>G&ouml;ttin Shashthi<\/strong>, die als Besch&uuml;tzerin von Kindern und der Familie gilt. Es wird angenommen, dass Shashthi die Gestalt einer Katze annimmt, um ihre Sch&uuml;tzlinge zu verteidigen. In einigen Teilen Indiens werden<a href=\"\/magazin\/zoo-mix\/schwarze-katzen\/\"><strong> schwarze Katzen<\/strong><\/a> als Gl&uuml;cksbringer angesehen, w&auml;hrend sie in anderen Regionen als Ungl&uuml;cksboten gelten.<\/p>\n<h2 id=\"china-japan\">China\/Japan<\/h2>\n<p>In der chinesischen Kultur symbolisieren Katzen <strong>Gl&uuml;ck, Reichtum und Schutz<\/strong>. Es gibt viele Geschichten &uuml;ber Katzen, die b&ouml;se Geister vertreiben und ihre menschlichen Besitzer besch&uuml;tzen. Die ber&uuml;hmte <strong>Winkekatze (Maneki-Neko)<\/strong> hat ihren Ursprung in Japan. Diese Katzenfigur soll Gl&uuml;ck und Wohlstand anziehen und wird oft in Gesch&auml;ften und Wohnungen aufgestellt. Eine ber&uuml;hmte Legende ist die Geschichte von der Katze, die einem Samurai das Leben rettet, indem sie ihn vor einem Blitzschlag bewahrt. In Japan gibt es sogar eine <strong>&#8222;Katzeninsel&#8220; namens Tashirojima<\/strong>, auf der Katzen in gro&szlig;er Zahl leben und als Gl&uuml;cksbringer gelten.<\/p>\n<h2 id=\"europa\">Europa<\/h2>\n<p>In der irisch-keltischen Mythologie wurde die <a href=\"\/magazin\/katzen\/katzenrassen\/wildkatze\/\">Wildkatze<\/a> bereits verehrt, noch bevor die <a href=\"\/magazin\/katzen\/katzenrassen\/hauskatze\/\">Hauskatze<\/a> durch die R&ouml;mer in unsere germanischen W&auml;lder kam. Fruchtbarkeit, Sch&ouml;nheit, Sinnlichkeit, Eigenst&auml;ndigkeit und das Einfordern von Z&auml;rtlichkeiten waren Eigenschaften, die man der (Wild)Katze zusprach. Sie galt in der Katzen Mythologie als <strong>Symbol der Fruchtbarkeitsg&ouml;ttin Freya<\/strong>, die der Legende nach von vier K&auml;tzinnen aufgezogen wurde. Im mittelalterlichen Europa wurden Katzen oft mit <strong>Hexerei und Aberglauben<\/strong> in Verbindung gebracht. Schwarze Katzen galten als Ungl&uuml;cksbringer und wurden manchmal sogar verfolgt. Diese negativen Vorstellungen &auml;nderten sich jedoch gl&uuml;cklicherweise im Laufe der Zeit.<\/p>\n<h2 id=\"islamische-kultur\">Islamische Kultur<\/h2>\n<p>Im Islam gelten Katzen als <strong>saubere Tiere<\/strong>, die es verdienen, gut behandelt zu werden. Der Prophet Mohammed hatte eine besondere Zuneigung zu Katzen und soll eine seiner Lieblingskatzen namens Muezza besessen haben. Es gibt eine bekannte Legende, in der Mohammed seine Robe opferte, um Muezza nicht zu wecken, als sie darauf schlief. In der islamischen Kultur werden Katzen oft als Geschenke gegeben und gelten als Symbole f&uuml;r <strong>Unabh&auml;ngigkeit und Selbstgen&uuml;gsamkeit<\/strong>.<\/p>\n<h2 id=\"afrikanische-kulturen\">Afrikanische Kulturen<\/h2>\n<p>Die Katze taucht in etlichen Geschichten afrikanischer Mythologien auf. Die Ashanti aus Ghana z.B. glauben, dass Katzen <strong>&uuml;bernat&uuml;rliche Kr&auml;fte<\/strong> besitzen und in der Lage sind, b&ouml;se Geister abzuwehren. In <strong>&Auml;thiopien<\/strong> gibt es Legenden &uuml;ber Katzen, die Krankheiten heilen und ihre menschlichen Besitzer besch&uuml;tzen k&ouml;nnen.<\/p>\n<h2 id=\"mesoamerika\">Mesoamerika<\/h2>\n<p>Insbesondere bei den Maya waren <strong>Jaguar und Ozelot<\/strong> hochgesch&auml;tzte Tiere. Obwohl sie keine domestizierten Katzen sind, wurden sie laut Katzen Mythologie als <strong>m&auml;chtige Symbole und Gottheiten<\/strong> verehrt. Der Jaguar repr&auml;sentiert St&auml;rke, Macht und &Uuml;berlegenheit, w&auml;hrend der Ozelot als Besch&uuml;tzer der Dunkelheit gilt.<\/p>\n<h2 id=\"indonesien\">Indonesien<\/h2>\n<p>Auf den indonesischen Inseln Bali und Java werden Katzen ebenfalls verehrt. Die Balinesen glauben, dass Katzen eine <strong>Verbindung zur spirituellen Welt<\/strong> haben und negative Energien abwehren k&ouml;nnen. Auf Java gibt es eine Legende &uuml;ber eine mystische wei&szlig;e Katze namens <strong>Si Manis Jembatan Ancol<\/strong>, die einer tragischen Liebesgeschichte zugeschrieben wird und angeblich am Ancol-Strand erscheint.<\/p>\n<h2 id=\"sibirische-kultur-russland\">Sibirische Kultur (Russland)<\/h2>\n<p>Die Sibirien haben ebenfalls eine besondere Beziehung zu Katzen. Die <a href=\"\/magazin\/katzen\/katzenrassen\/sibirische-katze\/\">sibirische Katze<\/a>, eine urspr&uuml;ngliche russische Rasse, wurde in der sibirischen Folklore und Katzen Mythologie als <strong>Besch&uuml;tzer des Hauses und der Familie<\/strong> verehrt. Sie wurden gesch&auml;tzt f&uuml;r ihre Jagdf&auml;higkeiten und ihren Beitrag zur Bek&auml;mpfung von Nagetieren in den rauen sibirischen Bedingungen.<\/p>\n<h2 id=\"australische-ureinwohner\">Australische Ureinwohner<\/h2>\n<p>W&auml;hrend Australiens Ureinwohner keine domestizierten Katzen kannten, bevor die europ&auml;ischen Siedler sie einf&uuml;hrten, haben sie eine besondere Beziehung zum einheimischen Beuteltier, dem <strong>Quokka<\/strong>, entwickelt. Obwohl das Quokka kein Katzenartiger ist, hat es gewisse &Auml;hnlichkeiten und wird oft als <strong>&#8222;l&auml;chelnde Katze&#8220;<\/strong> bezeichnet. Quokkas spielen eine Rolle in der Sch&ouml;pfungsgeschichte und den Traumzeitgeschichten der australischen Ureinwohner.<\/p>\n<h2 id=\"katzen-heute\">Katzen heute<\/h2>\n<p>Heute sind <a href=\"\/magazin\/katzen\/katzenrassen\/\">Katzen<\/a><strong> beliebte Haustiere<\/strong> und werden f&uuml;r ihre Unabh&auml;ngigkeit und Sch&ouml;nheit gesch&auml;tzt. Sie bringen Freude und Gl&uuml;ck in unser Leben und bereichern unseren Alltag auf einzigartige Weise. Ob als H&uuml;ter des Hauses oder treuer Begleiter auf unseren Abenteuern. Viele Katzenhalter schw&ouml;ren auch heute noch auf die <strong>besonderen Eigenschaften und mystischen F&auml;higkeiten<\/strong> ihrer Lieblinge. So glauben z.B. einige, dass eine Katze ins Jenseits blicken kann, weil sie manchmal eindringlich etwas anstarrt, wo f&uuml;r unser menschliches Auge nichts sichtbar ist. Doch egal, woran die Einen glauben und die Anderen nicht: Sicher ist, wer l&auml;ngere Zeit mit ihnen zusammenlebt, dem entgeht nicht, dass Katzen eine ganz <strong>besondere Aura<\/strong> verstr&ouml;men und einen ausgleichenden Einfluss auf uns haben.<\/p>\n<hr>\n<p style=\"text-align: left;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-19979 size-thumbnail alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2020\/03\/Mel_Sammy-150x150.jpg\" alt=\"Melanie Roloff\" width=\"150\" height=\"150\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/03\/Mel_Sammy-150x150.jpg 150w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/03\/Mel_Sammy-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><a href=\"\/magazin\/zoo-experten\/gastautoren-experten\/melanie-roloff\/\">Melanie Roloff<\/a><\/strong> ist dreifache Mutter, Ehefrau und Tierbesitzerin. Als leidenschaftliche Yogalehrerin und Hobbyautorin inspiriert sie Menschen mit ihren Geschichten. Gemeinsam mit ihrer Familie und ihren zwei Hunden Phal&eacute;ne Lilly und <a href=\"\/magazin\/hunde\/chihuahua\/\">Chihuahua<\/a> Sammy, lebt sie in Bayern.<\/p>\n<hr><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-28250-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-28250-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-28250-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\">\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Elegant, geheimnisvoll und unnachahmlich unabh&auml;ngig &ndash; Katzen sind seit Jahrtausenden an der Seite des Menschen. In vielen verschiedenen Kulturen haben diese eleganten Raubtiere eine besondere Rolle eingenommen und beeindruckende Spuren&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":71,"featured_media":28346,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[4639,4640,4637,4635,4651,4636,4634,4649,2211,4650,4638,11,4629,4630,4645,4644,4648,4631,4633,4632,4641,4170,4647,4652,4642,4643,4176,4646],"class_list":["post-28250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-katzen","tag-afrika","tag-afrikanische-kultur","tag-aegypten","tag-asien","tag-aethiopien","tag-china","tag-europa","tag-freya","tag-geschichten","tag-islam","tag-islamische-kultur","tag-katze","tag-kultur","tag-kulturen","tag-legende","tag-legenden","tag-maneki-neko","tag-mythen","tag-mythische-katzen","tag-mythologie","tag-russland","tag-schwarze-katze","tag-shashthi","tag-si-manis-jembatan-ancol","tag-sibirien","tag-sibirische-kultur","tag-tiermythen","tag-winkekatze"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Katzen Mythologie - Mythen &amp; Kulturen | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Katzen Mythen &amp; Legenden - Erfahre mehr \u00fcber die Katzen Mythologie in \u00c4gypenten, Europa, Indien, und weiteren verschiedener Kulturen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Katzen Mythologie und andere Kulturen\" \/>\n<meta property=\"og:description\" content=\"Katzen Mythen &amp; Legenden - Erfahre mehr \u00fcber die Katzen Mythologie in \u00c4gypenten, Europa, Indien, und weiteren verschiedener Kulturen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-23T06:20:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T12:47:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/465a6b7bbd4547048048a47bb9bd5012\"},\"headline\":\"Katzen Mythologie und andere Kulturen\",\"datePublished\":\"2023-06-23T06:20:34+00:00\",\"dateModified\":\"2024-04-08T12:47:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/\"},\"wordCount\":1131,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/katzen-mythologie-760x570-1.jpg\",\"keywords\":[\"afrika\",\"afrikanische Kultur\",\"\u00e4gypten\",\"asien\",\"\u00c4thiopien\",\"china\",\"europa\",\"Freya\",\"Geschichten\",\"Islam\",\"islamische kultur\",\"Katze\",\"Kultur\",\"Kulturen\",\"Legende\",\"Legenden\",\"Maneki-Neko\",\"Mythen\",\"mythische Katzen\",\"Mythologie\",\"Russland\",\"Schwarze Katze\",\"Shashthi\",\"Si Manis Jembatan Ancol\",\"Sibirien\",\"sibirische Kultur\",\"Tiermythen\",\"Winkekatze\"],\"articleSection\":[\"Katzen Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/\",\"name\":\"Katzen Mythologie - Mythen & Kulturen | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/katzen-mythologie-760x570-1.jpg\",\"datePublished\":\"2023-06-23T06:20:34+00:00\",\"dateModified\":\"2024-04-08T12:47:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/465a6b7bbd4547048048a47bb9bd5012\"},\"description\":\"Katzen Mythen & Legenden - Erfahre mehr \u00fcber die Katzen Mythologie in \u00c4gypenten, Europa, Indien, und weiteren verschiedener Kulturen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/katzen-mythologie-760x570-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/katzen-mythologie-760x570-1.jpg\",\"width\":760,\"height\":570,\"caption\":\"Katzen Mythologie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/katzen\\\/katzen-mythologie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Katzen Mythologie und andere Kulturen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/465a6b7bbd4547048048a47bb9bd5012\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g\",\"caption\":\"ZooRoyal\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Katzen Mythologie - Mythen & Kulturen | ZooRoyal Magazin","description":"Katzen Mythen & Legenden - Erfahre mehr \u00fcber die Katzen Mythologie in \u00c4gypenten, Europa, Indien, und weiteren verschiedener Kulturen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/","og_locale":"de_DE","og_type":"article","og_title":"Katzen Mythologie und andere Kulturen","og_description":"Katzen Mythen & Legenden - Erfahre mehr \u00fcber die Katzen Mythologie in \u00c4gypenten, Europa, Indien, und weiteren verschiedener Kulturen!","og_url":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2023-06-23T06:20:34+00:00","article_modified_time":"2024-04-08T12:47:47+00:00","og_image":[{"width":760,"height":570,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/465a6b7bbd4547048048a47bb9bd5012"},"headline":"Katzen Mythologie und andere Kulturen","datePublished":"2023-06-23T06:20:34+00:00","dateModified":"2024-04-08T12:47:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/"},"wordCount":1131,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg","keywords":["afrika","afrikanische Kultur","\u00e4gypten","asien","\u00c4thiopien","china","europa","Freya","Geschichten","Islam","islamische kultur","Katze","Kultur","Kulturen","Legende","Legenden","Maneki-Neko","Mythen","mythische Katzen","Mythologie","Russland","Schwarze Katze","Shashthi","Si Manis Jembatan Ancol","Sibirien","sibirische Kultur","Tiermythen","Winkekatze"],"articleSection":["Katzen Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/","url":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/","name":"Katzen Mythologie - Mythen & Kulturen | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg","datePublished":"2023-06-23T06:20:34+00:00","dateModified":"2024-04-08T12:47:47+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/465a6b7bbd4547048048a47bb9bd5012"},"description":"Katzen Mythen & Legenden - Erfahre mehr \u00fcber die Katzen Mythologie in \u00c4gypenten, Europa, Indien, und weiteren verschiedener Kulturen!","breadcrumb":{"@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2023\/06\/katzen-mythologie-760x570-1.jpg","width":760,"height":570,"caption":"Katzen Mythologie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.at\/magazin\/katzen\/katzen-mythologie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Katzen Mythologie und andere Kulturen"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/465a6b7bbd4547048048a47bb9bd5012","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35bd29c111b6ca0a34dc26c6e4219fc5892fbc52ec8d50cd61a17582cc901e1a?s=96&d=blank&r=g","caption":"ZooRoyal"}}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/28250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=28250"}],"version-history":[{"count":6,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/28250\/revisions"}],"predecessor-version":[{"id":32179,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/28250\/revisions\/32179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/28346"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=28250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=28250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=28250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}