{"id":23946,"date":"2021-05-04T14:17:40","date_gmt":"2021-05-04T12:17:40","guid":{"rendered":"http:\/\/www.zooroyal.de\/magazin\/?p=23946"},"modified":"2021-05-04T14:17:40","modified_gmt":"2021-05-04T12:17:40","slug":"welsh-pony","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/pferde\/pferderassen\/welsh-pony\/","title":{"rendered":"Welsh Pony im Rasseportrait"},"content":{"rendered":"<div id=\"pl-23946\" class=\"panel-layout\">\n<div id=\"pg-23946-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-23946-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-23946-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-featured-whatever wp-image-23958\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony-760x570.jpg\" alt=\"Welsh Pony\" width=\"760\" height=\"570\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony-760x570.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony-700x525.jpg 700w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony-233x175.jpg 233w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony-175x131.jpg 175w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony-323x242.jpg 323w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/p>\n<h2 id=\"rassemerkmale-und-erscheinungsbild\">Rassemerkmale und Erscheinungsbild<\/h2>\n<h3 id=\"wie-sieht-ein-welsh-pony-aus\">Wie sieht ein Welsh Pony aus?<\/h3>\n<p>Dieses Pony gibt es in verschiedenen Erscheinungsformen. Es unterscheidet sich im Charakter und im Aussehen und wird in <strong>vier Sektionen (A bis D)<\/strong> und in die Partbred unterteilt. Sektion A beinhaltet das Welsh Mountain Pony, den Urtyp dieser Rasse. Zur Sektion B wird das umgangssprachliche Welsh Pony gez&auml;hlt, auf welches wir hier auch n&auml;her eingehen werden. Allerdings gibt es auch bei der Sektion B verschiedene Typen. Der Welsh Pony-Cob Typ ist in Sektion C eingeteilt. Die gr&ouml;&szlig;ten Typen sind die Welsh Cobs, die der Sektion D angeh&ouml;ren. Bei dem Partbred handelt es sich um Pferde, die keiner Sektion angeh&ouml;ren, allerdings &auml;hneln sie im &Auml;u&szlig;eren einem Welsh-Typ und haben einen Welsh Blutanteil von <strong>mindestens 12,5 %<\/strong>.<\/p>\n<h3 id=\"woran-erkenne-ich-ein-welsh-pony\">Woran erkenne ich ein Welsh Pony?<\/h3>\n<p>In der Sektion B gibt es <strong>zwei verschiedene Typen<\/strong>, zum einen das kompakte Pony und zum anderen das etwas feingliedrigere elegantere Pony. Ansonsten wirkt der Kopf edel, nicht zu lang und mit breiter Stirn. Die Ohren sind klein, die Augen gro&szlig; und wach. Der Hals ist lang und gut angesetzt. Die Schultern sind lang und schr&auml;g. Das Welsh Pony hat einen mittellangen und stark bemuskelten R&uuml;cken.<\/p>\n<h3 id=\"was-ist-das-besondere-an-einem-welsh-pony\">Was ist das Besondere an einem Welsh Pony?<\/h3>\n<p>Die Ponys sind robust, zuverl&auml;ssig und sehr lernf&auml;hig. Freunde dieser Rasse sch&auml;tzen sie nicht nur als <strong>Sportpony<\/strong>, sondern als <strong>Partner f&uuml;r Freizeit und Familie<\/strong>, sie sind oft sehr personenbezogen, vertrauen ihren Bezugspersonen und sind Fremden gegen&uuml;ber ein wenig reserviert. Welsh Ponys sind bekannt f&uuml;r ihre Leistungsbereitschaft und ihr <strong>gutm&uuml;tiges, unerschrockenes Wesen<\/strong>.<\/p>\n<h3 id=\"wie-gro-ist-ein-welsh-pony\">Wie gro&szlig; ist ein Welsh Pony?<\/h3>\n<p>Je nach Sektion hat es ein Stockma&szlig; bis <strong>122 cm (Sektion A)<\/strong>, bis <strong>137 cm (Sektionen B und C)<\/strong> und ab <strong>137 cm (Sektion D)<\/strong>.<\/p>\n<h3 id=\"wie-hoch-ist-die-lebenserwartung-eines-welsh-ponys\">Wie hoch ist die Lebenserwartung eines Welsh Ponys?<\/h3>\n<p>Das Welsh Pony kann <strong>35 Jahre<\/strong> alt werden.<\/p>\n<h3 id=\"welche-fellfarben-gibt-es-beim-welsh-pony\">Welche Fellfarben gibt es beim Welsh Pony?<\/h3>\n<p>Die Welsh Ponys kommen als Braune, F&uuml;chse, Schimmel, Rappen und Falben vor.<\/p>\n<h2 id=\"wesenszge-und-charaktereigenschaften\">Wesensz&uuml;ge und Charaktereigenschaften<\/h2>\n<h3 id=\"sind-welsh-ponys-auch-fr-anfnger-geeignet\">Sind Welsh Ponys auch f&uuml;r Anf&auml;nger geeignet?<\/h3>\n<p>Da es in Sektion B zwei verschiedene Typen gibt, informiere dich vorab, was f&uuml;r dich in Frage kommt. Der eine Typ Pony ist etwas <strong>kompakter<\/strong> und vom Charakter etwas <strong>ruhiger und ausgeglichener<\/strong>. Der andere Typ hingegen hat einen feingliedrigeren K&ouml;rperbau und ist etwas temperamentvoller. Als Anf&auml;nger ist ersteres die vielleicht bessere Variante. Bist du dir unsicher, suche dir Unterst&uuml;tzung bei einem Fachmann.<\/p>\n<h3 id=\"welche-verhalten-und-wesenseigenschaften-zeichnen-ein-welsh-pony-aus\">Welche Verhalten- und Wesenseigenschaften zeichnen ein Welsh Pony aus?<\/h3>\n<p>Die Ponys gelten als gutm&uuml;tig, zuverl&auml;ssig, freundlich, aber auch leistungsstark und, je nach Typ, etwas temperamentvoller.<\/p>\n<h2 id=\"herkunft-geschichte\">Herkunft &amp; Geschichte<\/h2>\n<h3 id=\"wo-kommt-das-welsh-pony-ursprnglich-her\">Wo kommt das Welsh Pony urspr&uuml;nglich her?<\/h3>\n<p>Die Urspr&uuml;nge der verschiedenen Welsh Ponys geht bis zur <strong>Zeit der Kelten<\/strong> zur&uuml;ck. Im Laufe der Geschichte wurden andere Pferderassen, die auf die Insel kamen, mit eingekreuzt. 1901 wurde die WPCS, die <strong>Welsh Pony and Cob Society<\/strong>, gegr&uuml;ndet. Im Jahr 1931 wurden die uns heute bekannten Sektionen festgelegt.<\/p>\n<h3 id=\"wofr-wurden-welsh-ponys-gezchtet\">Wof&uuml;r wurden Welsh Ponys gez&uuml;chtet?<\/h3>\n<p>In den Urspr&uuml;ngen sind die Ponys als <strong>Reitpferde<\/strong> genutzt worden, im 19. Jahrhundert teilweise sogar als <strong>Grubenpferde<\/strong>.<\/p>\n<h2 id=\"pflege-gesundheit-krankheiten\">Pflege, Gesundheit, Krankheiten<\/h2>\n<h3 id=\"worauf-ist-bei-der-pflege-beim-welsh-pony-zu-achten\">Worauf ist bei der Pflege beim Welsh Pony zu achten?<\/h3>\n<p>Es gibt <strong>keine Besonderheiten<\/strong>, auf die du bei dieser Rasse achten musst. Regelm&auml;&szlig;ige Fellpflege, der Besuch des <a href=\"\/magazin\/zoo-experten\/ein-guter-tierarzt\/\">Tierarztes<\/a> sowie das Vorstellen beim Hufschmied geh&ouml;ren bei jedem Pferd und Pony dazu.<\/p>\n<h3 id=\"gibt-es-beim-welsh-pony-rassetypische-krankheiten-oder-erbkrankheiten\">Gibt es beim Welsh Pony rassetypische Krankheiten oder Erbkrankheiten?<\/h3>\n<p>Es gibt keine rassetypischen Krankheiten beim Welsh Pony, sie gelten als <strong>robust und leichtfuttrig<\/strong>. Falsche oder &uuml;berdosierte F&uuml;tterung sowie mangelnde Bewegung k&ouml;nnen zu &Uuml;bergewicht und anderen gesundheitlichen Problemen f&uuml;hren.<\/p>\n<h2 id=\"wissenswertes-ber-die-ernhrung\">Wissenswertes &uuml;ber die Ern&auml;hrung<\/h2>\n<h3 id=\"was-ist-bei-den-ftterungszeiten-und-der-futtermenge-zu-beachten\">Was ist bei den F&uuml;tterungszeiten und der Futtermenge zu beachten?<\/h3>\n<p>Die Ponys lebten einst in einer <strong>rauen und kargen Gegend<\/strong>. Sie sind es eher gewohnt <strong>weniger Futter<\/strong> zu sich zu nehmen. Doch unsere Wiesen sind meist &uuml;ppig und saftig, weshalb f&uuml;r diese Pferde &Uuml;berf&uuml;tterung leicht zu einem gesundheitlichen Problem werden kann. Qualitativ <strong>hochwertiges Heu, magere Weiden und bedarfsgerechtes Mineralfutter<\/strong> sollten stattdessen auf dem Speiseplan stehen. Kraftfutter ist nur nach Bedarf und sportlichem Einsatz notwendig.<\/p>\n<h3 id=\"wie-oft-sollte-das-welsh-pony-gefttert-werden\">Wie oft sollte das Welsh Pony gef&uuml;ttert werden?<\/h3>\n<p>Der F&uuml;tterungsplan deines Pferdes richtet sich nach eurem Alltag. Wird dein Pony im <a href=\"\/magazin\/pferde\/offenstallhaltung\/\">Offenstall<\/a> gehalten und verbringt es viel Zeit auf der Weide, hat es die M&ouml;glichkeit, kontinuierlich und mit wenig Leerlauf im Magen zu fressen. Die Heuf&uuml;tterung sollte &uuml;ber den Tag verteilt erfolgen.<\/p>\n<h2 id=\"aktivitten-mit-dem-welsh-pony\">Aktivit&auml;ten mit dem Welsh Pony<\/h2>\n<h3 id=\"welche-sportarten-sind-fr-das-welsh-pony-geeignet\">Welche Sportarten sind f&uuml;r das Welsh Pony geeignet?<\/h3>\n<p>Du kannst das Welsh Pony sowohl als Reit- als auch als Fahrpony nutzen. Ob es dabei auf Turnieren eingesetzt wird oder als Freitzeitpony, bleibt dir &uuml;berlassen.<\/p>\n<h3 id=\"wie-viel-bewegung-braucht-ein-welsh-pony\">Wie viel Bewegung braucht ein Welsh Pony?<\/h3>\n<p>Jedes Pferd ben&ouml;tigt ausreichend Bewegung. Auch ein Welsh Pony, welches sehr robust gehalten werden kann, ben&ouml;tigt <strong>Bewegung und Besch&auml;ftigung<\/strong>. Geistige und k&ouml;rperliche Auslastung sollten daher auch auf dem Programm stehen.<\/p>\n<h2 id=\"berlegung-vor-der-anschaffung\">&Uuml;berlegung vor der Anschaffung<\/h2>\n<h3 id=\"wo-kann-man-ein-welsh-pony-kaufen\">Wo kann man ein Welsh Pony kaufen?<\/h3>\n<p>Hast du dich f&uuml;r diese Rasse entschieden, &uuml;berlege dir in Ruhe, ob du das Pony vom Z&uuml;chter oder aus Privathand erwerben m&ouml;chtest und ob es ein Fohlen, J&auml;hrling oder adultes Pony sein soll. Beim Z&uuml;chter kannst du viel zum Thema Welsh Pony und dessen Hintergrund, Training und Gesundheit erfahren.<\/p>\n<h3 id=\"wo-kann-man-fr-ein-welsh-pony-eine-reitbeteiligung-finden\">Wo kann man f&uuml;r ein Welsh Pony eine Reitbeteiligung finden?<\/h3>\n<p>Stelle dir zuerst die Frage, was du dir von einer Reitbeteiligung w&uuml;nscht und wer zu dir und deinem Pony passen k&ouml;nnte. Soll es nur zum Reiten oder auch zum Fahren eingesetzt werden? Dein Pony wird sich &uuml;ber jegliche Auslastung freuen. &Uuml;ber Inserate im Internet, Zeitschriften oder andere Kontakte kannst du eine Reitbeteiligung ausfindig machen.<\/p>\n<h2 id=\"erziehung-und-haltung\">Erziehung und Haltung<\/h2>\n<h3 id=\"passt-ein-welsh-pony-zu-mir\">Passt ein Welsh Pony zu mir?<\/h3>\n<p>Suchst du ein Familien- und Freizeitpony, ist das Welsh Pony dein idealer Partner, ob f&uuml;r Kinder oder leichte Erwachsene zum Reiten oder als Fahrpony. Ebenso kannst du mit dieser Rasse <strong>Turniere<\/strong> erfolgreich bestreiten. Mit seiner <strong>Leistungsbereitschaft, Gutm&uuml;tigkeit und Zuverl&auml;ssigkeit<\/strong> wird es mit dir jeden Tag aufs neue meistern und dich erfreuen.<\/p>\n<h3 id=\"wie-halte-ich-ein-welsh-pony\">Wie halte ich ein Welsh Pony?<\/h3>\n<p>Die Ponys gelten als sehr robust und k&ouml;nnen ohne Probleme in der Offenstallhaltung gehalten werden. Allerdings sollte ein Unterstand vorhanden sein, unter den sich die Tiere bei Bedarf stellen k&ouml;nnen. Dieser muss <strong>gen&uuml;gend Raum<\/strong> f&uuml;r die Pferde bieten und vor Regen und Sonne sch&uuml;tzen. Der Boden sollte zudem trocken und sauber sein. Der <strong>Kontakt zu Artgenossen<\/strong> ist sehr wichtig.<\/p>\n<h3 id=\"wieviel-platz-braucht-ein-welsh-pony\">Wieviel Platz braucht ein Welsh Pony?<\/h3>\n<p>Das Welsh Pony ben&ouml;tigt <strong>ausreichend Bewegung<\/strong>. Das bedeutet, reine Boxenhaltung mit wenig Auslauf ist f&uuml;r diese Rasse nicht die richtige Haltungsform. Offenstallhaltung mit Weide oder alternativ einem Paddock, Sandplatz oder &auml;hnlichem sollten zur Verf&uuml;gung stehen. Ebenso ist eine ausreichende Besch&auml;ftigung f&uuml;r diese Rasse wichtig.<\/p>\n<h3 id=\"wie-transportiere-ich-ein-welsh-pony\">Wie transportiere ich ein Welsh Pony?<\/h3>\n<p>Die Rasse ist nicht besonders gro&szlig; und auch nicht sehr schwer. Du kannst es also problemlos in einem <a href=\"\/magazin\/pferde\/anhaengerfahrten-mit-pferd\/\">Pferdeanh&auml;nger<\/a> transportieren.<\/p>\n<h2 id=\"interessantes-wissenswertes-und-extras\">Interessantes, Wissenswertes und Extras<\/h2>\n<h3 id=\"warum-sind-welsh-ponys-so-beliebt\">Warum sind Welsh Ponys so beliebt?<\/h3>\n<p>Die Ponys sind robuste mittelgro&szlig;e Pferde, die gutm&uuml;tig, leistungsbereit und zuverl&auml;ssig sind. Sie sind menschenbezogen, arbeiten gerne und k&ouml;nnen Erstaunliches leisten. Sie sind sehr vielseitig einsetzbar &ndash; es sind Ponys f&uuml;r die ganze Familie.<\/p>\n<hr>\n<p><strong><a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12717 alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg\" alt=\"Kristina\" width=\"300\" height=\"221\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-768x566.jpg 768w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-380x280.jpg 380w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg 905w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Kristina Ziemer-Falke<\/strong> ist zertifizierte Hundetrainerin und Verhaltensberaterin durch die Tier&auml;rztekammer Schleswig-Holstein und das Messerli Forschungsinstitut der Veterin&auml;rmedizinischen Universit&auml;t Wien. Dar&uuml;ber hinaus verf&uuml;gt sie &uuml;ber viele Zusatzausbildungen und Schwerpunkte und ist im Pr&uuml;fungsausschuss der Tier&auml;rztekammer Niedersachsen f&uuml;r die Hundetrainerzertifizierungen.<br \/>\nMit ihrem Mann J&ouml;rg Ziemer gr&uuml;ndete sie das Schulungszentrum <a href=\"https:\/\/www.ziemer-falke.de\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Ziemer &amp; Falke<\/a>, in dem sie seit vielen Jahren mit viel Herz, Leidenschaft und Kompetenz Hundetrainer in ganz Deutschland ausbilden und viele Weiterbildungsangebote anbieten. Viele kennen Kristina au&szlig;erdem als erfolgreiche Autorin von Fachb&uuml;chern f&uuml;r Hundetrainer und Hundehalter sowie aus Artikeln beliebter Hundezeitschriften.<\/p>\n<hr>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pg-23946-1\" class=\"panel-grid panel-no-style\" data-ratio=\"1\" data-ratio-direction=\"right\">\n<div id=\"pgc-23946-1-0\" class=\"panel-grid-cell\" data-weight=\"0.33333333333333\">\n<div id=\"panel-23946-1-0-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"1\"><\/div>\n<\/div>\n<div id=\"pgc-23946-1-1\" class=\"panel-grid-cell\" data-weight=\"0.33333333333333\">\n<div id=\"panel-23946-1-1-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"2\"><\/div>\n<\/div>\n<div id=\"pgc-23946-1-2\" class=\"panel-grid-cell\" data-weight=\"0.33333333333333\">\n<div id=\"panel-23946-1-2-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"3\"><\/div>\n<\/div>\n<\/div>\n<div id=\"pg-23946-2\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-23946-2-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-23946-2-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\">\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rassemerkmale und Erscheinungsbild Wie sieht ein Welsh Pony aus? Dieses Pony gibt es in verschiedenen Erscheinungsformen. Es unterscheidet sich im Charakter und im Aussehen und wird in vier Sektionen (A&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/pferde\/pferderassen\/welsh-pony\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":58,"featured_media":23958,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,2145],"tags":[2326,3773,2230,3814,788,3805,3840],"class_list":["post-23946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pferde","category-pferderassen","tag-dressurpferd","tag-pferderassen","tag-pony","tag-rassepferd","tag-rasseportrait","tag-reitpferd","tag-welsh-pony"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Das Welsh Pony im Rasseportrait | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Ein Welsh Pony ist ein robustes und zuverl\u00e4ssiges Pony, dass sich toll als Sportpony eignet. Mehr \u00fcber diese Pferderasse liest du hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/pferde\/pferderassen\/welsh-pony\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welsh Pony im Rasseportrait\" \/>\n<meta property=\"og:description\" content=\"Ein Welsh Pony ist ein robustes und zuverl\u00e4ssiges Pony, dass sich toll als Sportpony eignet. Mehr \u00fcber diese Pferderasse liest du hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T12:17:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4481\" \/>\n\t<meta property=\"og:image:height\" content=\"2988\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jacqueline Fischer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jacqueline Fischer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/\"},\"author\":{\"name\":\"Jacqueline Fischer\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/810f99afce6c3e05ec146bade163ace0\"},\"headline\":\"Welsh Pony im Rasseportrait\",\"datePublished\":\"2021-05-04T12:17:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/\"},\"wordCount\":1481,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/welsh-pony.jpg\",\"keywords\":[\"Dressurpferd\",\"Pferderassen\",\"Pony\",\"Rassepferd\",\"Rasseportrait\",\"Reitpferd\",\"Welsh Pony\"],\"articleSection\":[\"Pferde Magazin\",\"Pferderassen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/\",\"name\":\"Das Welsh Pony im Rasseportrait | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/welsh-pony.jpg\",\"datePublished\":\"2021-05-04T12:17:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/810f99afce6c3e05ec146bade163ace0\"},\"description\":\"Ein Welsh Pony ist ein robustes und zuverl\u00e4ssiges Pony, dass sich toll als Sportpony eignet. Mehr \u00fcber diese Pferderasse liest du hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/welsh-pony.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/welsh-pony.jpg\",\"width\":4481,\"height\":2988,\"caption\":\"Welsh Pony\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/pferde\\\/pferderassen\\\/welsh-pony\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welsh Pony im Rasseportrait\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/810f99afce6c3e05ec146bade163ace0\",\"name\":\"Jacqueline Fischer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/cropped-favicon_zooroyal-1-96x96.png\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/cropped-favicon_zooroyal-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/cropped-favicon_zooroyal-1-96x96.png\",\"caption\":\"Jacqueline Fischer\"},\"sameAs\":[\"http:\\\/\\\/zooroyal.de\\\/magazin\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Das Welsh Pony im Rasseportrait | ZooRoyal Magazin","description":"Ein Welsh Pony ist ein robustes und zuverl\u00e4ssiges Pony, dass sich toll als Sportpony eignet. Mehr \u00fcber diese Pferderasse liest du hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/pferde\/pferderassen\/welsh-pony\/","og_locale":"de_DE","og_type":"article","og_title":"Welsh Pony im Rasseportrait","og_description":"Ein Welsh Pony ist ein robustes und zuverl\u00e4ssiges Pony, dass sich toll als Sportpony eignet. Mehr \u00fcber diese Pferderasse liest du hier.","og_url":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2021-05-04T12:17:40+00:00","og_image":[{"width":4481,"height":2988,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony.jpg","type":"image\/jpeg"}],"author":"Jacqueline Fischer","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"Jacqueline Fischer","Est. reading time":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/"},"author":{"name":"Jacqueline Fischer","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/810f99afce6c3e05ec146bade163ace0"},"headline":"Welsh Pony im Rasseportrait","datePublished":"2021-05-04T12:17:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/"},"wordCount":1481,"commentCount":2,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony.jpg","keywords":["Dressurpferd","Pferderassen","Pony","Rassepferd","Rasseportrait","Reitpferd","Welsh Pony"],"articleSection":["Pferde Magazin","Pferderassen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/","url":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/","name":"Das Welsh Pony im Rasseportrait | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony.jpg","datePublished":"2021-05-04T12:17:40+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/810f99afce6c3e05ec146bade163ace0"},"description":"Ein Welsh Pony ist ein robustes und zuverl\u00e4ssiges Pony, dass sich toll als Sportpony eignet. Mehr \u00fcber diese Pferderasse liest du hier.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2021\/04\/welsh-pony.jpg","width":4481,"height":2988,"caption":"Welsh Pony"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/pferde\/pferderassen\/welsh-pony\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Welsh Pony im Rasseportrait"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/810f99afce6c3e05ec146bade163ace0","name":"Jacqueline Fischer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/08\/cropped-favicon_zooroyal-1-96x96.png","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/08\/cropped-favicon_zooroyal-1-96x96.png","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/08\/cropped-favicon_zooroyal-1-96x96.png","caption":"Jacqueline Fischer"},"sameAs":["http:\/\/zooroyal.de\/magazin"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/23946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=23946"}],"version-history":[{"count":7,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/23946\/revisions"}],"predecessor-version":[{"id":23963,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/23946\/revisions\/23963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/23958"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=23946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=23946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=23946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}