{"id":20747,"date":"2020-09-16T11:52:29","date_gmt":"2020-09-16T09:52:29","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=20747"},"modified":"2020-09-16T11:52:29","modified_gmt":"2020-09-16T09:52:29","slug":"truemmersuchhund","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/hunde\/truemmersuchhund\/","title":{"rendered":"Tr\u00fcmmersuchhund"},"content":{"rendered":"<div id=\"pl-20747\" class=\"panel-layout\">\n<div id=\"pg-20747-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-20747-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-20747-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20751\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2020\/06\/tr%C3%BCmmersuchhund-min.jpg\" alt=\"Tr&uuml;mmersuchhund\" width=\"4272\" height=\"2848\"><div class=\"mobile-toc\"><\/div><\/p>\n<p>Ein weiterer tierischer Helfer, der den Menschen durch seine ausgezeichnete Nase unterst&uuml;tzt, ist der Tr&uuml;mmersuchhund. Er bringt ganz bestimmte Eigenschaften mit, die ihn bei der Suche nach Versch&uuml;tteten unverzichtbar machen.<\/p>\n<h2 id=\"wann-kommt-der-trmmersuchhund-zum-einsatz\">Wann kommt der Tr&uuml;mmersuchhund zum Einsatz?<\/h2>\n<p>Werden Personen versch&uuml;ttet, beispielsweise bei einem<strong> Erdbeben oder Geb&auml;udeeinst&uuml;rzen oder Soldaten\/Soldatinnen bei einem Einsatz<\/strong>, so ist die erfolgreiche Suche nach ihnen f&uuml;r den Menschen kaum zu bew&auml;ltigen. Die Vermissten sind nicht mehr f&uuml;r das Auge sichtbar. Sie k&ouml;nnen &uuml;berall unter den Ger&ouml;llteilen liegen. Bis sie gefunden werden, kann zu viel Zeit verstrichen sein. <strong>Speziell f&uuml;r diese Situation ausgebildete Suchhunde<\/strong> werden daher beim Aufsp&uuml;ren unterst&uuml;tzend eingesetzt.<\/p>\n<h2 id=\"wie-geht-der-hund-vor\">Wie geht der Hund vor?<\/h2>\n<p>Der Hund arbeitet stets eng mit seinem Hundef&uuml;hrer zusammen. Beide m&uuml;ssen sich bei der Aufgabe immer aufeinander verlassen k&ouml;nnen und ein eingespieltes Team sein. Wird der Hund in ein bestimmtes Gebiet geschickt, beginnt er sofort mit der Suche und setzt dazu aktiv seine Nase ein. Mit seinen <strong>circa 220 Millionen Riechzellen<\/strong> kann der Vierbeiner Ger&uuml;che sehr viel feiner wahrnehmen und dabei differenzieren. Er kann sogar unter den Tr&uuml;mmern unterscheiden, ob dort zum Beispiel nur ein Kleidungsst&uuml;ck einer Person liegt oder aber tats&auml;chlich eine versch&uuml;ttete Person. Ist er sich sicher, jemanden gefunden zu haben, so wird er seinen Fund melden, indem er meist laut bellt, bis sein Hundef&uuml;hrer bei ihm ist und ihm ein Signal gibt bzw. er seine Belohnung erh&auml;lt.<\/p>\n<h2 id=\"die-ausbildung\">Die Ausbildung<\/h2>\n<p>Damit der Tr&uuml;mmersuchhund zuverl&auml;ssig und zielgerichtet sucht, muss er zuvor eine<strong> spezielle Ausbildung<\/strong> durchlaufen haben und dabei die ein oder andere Pr&uuml;fung erfolgreich absolviert haben. W&auml;hrend der Ausbildung lernt der Hund nicht nur spielerisch die Personensuche, sondern auch die genauen Signale seines Halters auszuf&uuml;hren und dabei die ungewohnte Umgebung auszublenden. Ein Tr&uuml;mmersuchhund darf sich weder von vielen anderen Menschen und fremden Ger&uuml;chen ablenken, noch durch den unwegsamen Untergrund verunsichern lassen. Der Suchhund sollte selbstbewusst das wackelige Terrain &uuml;berqueren und sich <strong>nicht durch laute Ger&auml;usche oder andere Suchhunde aus der Ruhe bringen lassen<\/strong>.<\/p>\n<p>Das Training des angehenden Rettungshundes wird immer <strong>spielerisch<\/strong> gestaltet, sodass der Vierbeiner gro&szlig;e Lust auf die gemeinsame Arbeit mit seinem Hundef&uuml;hrer hat und hochmotiviert dabei ist. Findet der Hund bei einer &Uuml;bung die versteckte Person, so hat diese beispielsweise seinen Lieblingsball und wird mit ihm &#8211; nach dem erfolgreichen Anzeigen und Melden &ndash; nat&uuml;rlich auch eine Runde spielen. Auf diese Weise ist die hochkonzentrierte Arbeit f&uuml;r den Hund mit Spa&szlig; und positiven Reizen verbunden und ohne Druck. Damit Hund und Halter sich auch in den stressigen Situationen, gerade den Pr&uuml;fungssituationen, aufeinander verlassen k&ouml;nnen, m&uuml;ssen sie eine enge Beziehung zueinander aufgebaut haben.<\/p>\n<h2 id=\"kann-jeder-hund-trmmersuchhund-werden\">Kann jeder Hund Tr&uuml;mmersuchhund werden?<\/h2>\n<p>Grunds&auml;tzlich kann jeder Vierbeiner zu einem Tr&uuml;mmersuchhund ausgebildet werden. Vorteilhaft w&auml;re unabh&auml;ngig von der Rasse ein<strong> mittelgro&szlig;er Hund<\/strong>, der im Notfall auch &uuml;ber kurze Passagen getragen werden kann. Ist dein Hund aktiv, hat Spa&szlig; an der Arbeit mit dir und l&auml;sst sich f&uuml;r ein Spielzeug oder Leckerli besonders begeistern, bringt er schon die ersten wichtigen Voraussetzungen f&uuml;r die Ausbildung mit. Ist er au&szlig;erdem sehr &bdquo;cool&ldquo; und <strong>bleibt in vielen aufregenden Situationen gelassen<\/strong>, erf&uuml;llt er eine weitere Eigenschaft, die der Rettungshund besitzen sollte. Die meisten Hunde beginnen schon im Welpenalter mit dem Training, weshalb sie an die Umgebungsreize und Untergr&uuml;nde fr&uuml;h herangef&uuml;hrt und gew&ouml;hnt worden sind. Hast du deinen Hund aber ebenfalls gut sozialisiert und ihm in seinem jungen Alter schon Vieles gezeigt, ist das ebenso von Vorteil.<\/p>\n<p>Informiere dich doch einmal in deiner n&auml;heren Umgebung nach einem seri&ouml;sen Verein, der professionelle <a href=\"\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/\" target=\"_blank\" rel=\"noopener noreferrer\">Rettungshunde<\/a> ausbildet und lass dich zu der Sparte Tr&uuml;mmersuche beraten. Vielleicht kannst du bei einer &Uuml;bung erst einmal zusehen oder dich mit deinem Hund vorstellen. Vor Ort wird man dich sicher bestens beraten k&ouml;nnen, welche M&ouml;glichkeiten deinem Vierbeiner und dir zur Verf&uuml;gung stehen. Meist kann am besten w&auml;hrend des Trainings beurteilt werden, ob sich dein Hund als Tr&uuml;mmersuchhund eignet oder nicht. Wenn nicht, dann sei nicht entt&auml;uscht. Die Aufgabe des Tr&uuml;mmersuchhundes ist <strong>&auml;u&szlig;erst anspruchsvoll und verlangt dem Hund und F&uuml;hrer eine Menge ab<\/strong>. Aber vielleicht macht dir ja auch einfach das Training Spa&szlig;, sodass dein Hund und du weiterhin dabei zusammenarbeiten und vor allem zusammenwachsen k&ouml;nnt, ganz ohne Leistungsorientierung und sportliche Wettkampfambitionen. Die Nasenarbeit und die enge Zusammenarbeit mit dir ist eine tolle und artgerechte Auslastung f&uuml;r deinen Vierbeiner.<\/p>\n<hr>\n<p><strong><a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12717 alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg\" alt=\"Kristina\" width=\"300\" height=\"221\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-768x566.jpg 768w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-380x280.jpg 380w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg 905w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Kristina Ziemer-Falke<\/strong> ist zertifizierte Hundetrainerin und Verhaltensberaterin durch die Tier&auml;rztekammer Schleswig-Holstein und das Messerli Forschungsinstitut der Veterin&auml;rmedizinischen Universit&auml;t Wien. Dar&uuml;ber hinaus verf&uuml;gt sie &uuml;ber viele Zusatzausbildungen und Schwerpunkte und ist im Pr&uuml;fungsausschuss der Tier&auml;rztekammer Niedersachsen f&uuml;r die Hundetrainerzertifizierungen.<br \/>\nMit ihrem Mann J&ouml;rg Ziemer gr&uuml;ndete sie das Schulungszentrum <a href=\"https:\/\/www.ziemer-falke.de\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Ziemer &amp; Falke<\/a>, in dem sie seit vielen Jahren mit viel Herz, Leidenschaft und Kompetenz Hundetrainer in ganz Deutschland ausbilden und viele Weiterbildungsangebote anbieten. Viele kennen Kristina au&szlig;erdem als erfolgreiche Autorin von Fachb&uuml;chern f&uuml;r Hundetrainer und Hundehalter sowie aus Artikeln beliebter Hundezeitschriften.<\/p>\n<hr><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-20747-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-20747-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-20747-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/escapure-wild-stangerl-150g\/1000076966\/?icid=magproteaser_hunde_truemmersuchhund_\" class=\"article__wrapper--productimage\" title=\"ESCAPURE Wild Stangerl 150g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/wpxcfo-gBCqXXAu.jpg?host=ct\"\n                alt=\"ESCAPURE Wild Stangerl 150g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Escapure                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ESCAPURE Wild Stangerl 150g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    6.59 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        43.93 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/escapure-wild-stangerl-150g\/1000076966\/?icid=magproteaser_hunde_truemmersuchhund_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/hunter-maulkorb-albury-schwarz-groesse-6\/1000085069\/?icid=magproteaser_hunde_truemmersuchhund_\" class=\"article__wrapper--productimage\" title=\"Hunter Maulkorb Albury schwarz Gr\u00f6\u00dfe 6\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/tnzy8l-Yjjs_7qu.jpg?host=ct\"\n                alt=\"Hunter Maulkorb Albury schwarz Gr\u00f6\u00dfe 6\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Hunter                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Hunter Maulkorb Albury schwarz Gr\u00f6\u00dfe 6<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    28.69 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/hunter-maulkorb-albury-schwarz-groesse-6\/1000085069\/?icid=magproteaser_hunde_truemmersuchhund_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/petlando-outdoor-leine-sicherheitsgriff-3-m-berry-l-300-x-3-cm\/1000110663\/?icid=magproteaser_hunde_truemmersuchhund_\" class=\"article__wrapper--productimage\" title=\"Petlando Outdoor Leine Sicherheitsgriff 3 m berry L - 300 x 3 cm\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/jx8hd9-JPw7-n_i.jpg?host=ct\"\n                alt=\"Petlando Outdoor Leine Sicherheitsgriff 3 m berry L - 300 x 3 cm\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Petlando                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Petlando Outdoor Leine Sicherheitsgriff 3 m berry L - 300 x 3 cm<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    39.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/petlando-outdoor-leine-sicherheitsgriff-3-m-berry-l-300-x-3-cm\/1000110663\/?icid=magproteaser_hunde_truemmersuchhund_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a03d2ce6d3ea\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/escapure-wild-stangerl-150g\/1000076966\/?icid=magproteaser_hunde_truemmersuchhund_\" class=\"article__wrapper--productimage\" title=\"ESCAPURE Wild Stangerl 150g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/wpxcfo-gBCqXXAu.jpg?host=ct\"\n                                    alt=\"ESCAPURE Wild Stangerl 150g\">\n\n                            <div id=\"swiper-button-next6a03d2ce6d3ea\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03d2ce6d3ea\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Escapure                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ESCAPURE Wild Stangerl 150g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                6.59 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    43.93 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/escapure-wild-stangerl-150g\/1000076966\/?icid=magproteaser_hunde_truemmersuchhund_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/hunter-maulkorb-albury-schwarz-groesse-6\/1000085069\/?icid=magproteaser_hunde_truemmersuchhund_\" class=\"article__wrapper--productimage\" title=\"Hunter Maulkorb Albury schwarz Gr\u00f6\u00dfe 6\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/tnzy8l-Yjjs_7qu.jpg?host=ct\"\n                                    alt=\"Hunter Maulkorb Albury schwarz Gr\u00f6\u00dfe 6\">\n\n                            <div id=\"swiper-button-next6a03d2ce6d3ea\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03d2ce6d3ea\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Hunter                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Hunter Maulkorb Albury schwarz Gr\u00f6\u00dfe 6<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                28.69 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/hunter-maulkorb-albury-schwarz-groesse-6\/1000085069\/?icid=magproteaser_hunde_truemmersuchhund_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/petlando-outdoor-leine-sicherheitsgriff-3-m-berry-l-300-x-3-cm\/1000110663\/?icid=magproteaser_hunde_truemmersuchhund_\" class=\"article__wrapper--productimage\" title=\"Petlando Outdoor Leine Sicherheitsgriff 3 m berry L - 300 x 3 cm\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/jx8hd9-JPw7-n_i.jpg?host=ct\"\n                                    alt=\"Petlando Outdoor Leine Sicherheitsgriff 3 m berry L - 300 x 3 cm\">\n\n                            <div id=\"swiper-button-next6a03d2ce6d3ea\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03d2ce6d3ea\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Petlando                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Petlando Outdoor Leine Sicherheitsgriff 3 m berry L - 300 x 3 cm<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                39.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/petlando-outdoor-leine-sicherheitsgriff-3-m-berry-l-300-x-3-cm\/1000110663\/?icid=magproteaser_hunde_truemmersuchhund_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a03d2ce6d3ea\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a03d2ce6d3ea\",\n                prevEl: \"#swiper-button-prev6a03d2ce6d3ea\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ein weiterer tierischer Helfer, der den Menschen durch seine ausgezeichnete Nase unterst&uuml;tzt, ist der Tr&uuml;mmersuchhund. Er bringt ganz bestimmte Eigenschaften mit, die ihn bei der Suche nach Versch&uuml;tteten unverzichtbar machen&#8230;. <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/truemmersuchhund\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":15,"featured_media":20751,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2215,5],"tags":[2208,1747,2258,2262,3152],"class_list":["post-20747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hunde-im-einsatz","category-hunde","tag-hunde-im-einsatz","tag-nasenarbeit","tag-rettungshund","tag-spuerhund","tag-truemmersuchhund"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tr\u00fcmmersuchhund: so findet er Versch\u00fcttete | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Der Tr\u00fcmmersuchhund ist eine wichtige Hilfe bei der Suche von Versch\u00fctteten. Doch wie wird er ausgebildet und was geh\u00f6rt zu seinen Aufgaben?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/truemmersuchhund\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00fcmmersuchhund\" \/>\n<meta property=\"og:description\" content=\"Der Tr\u00fcmmersuchhund ist eine wichtige Hilfe bei der Suche von Versch\u00fctteten. Doch wie wird er ausgebildet und was geh\u00f6rt zu seinen Aufgaben?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-16T09:52:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/06\/tr\u00fcmmersuchhund-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"4272\" \/>\n\t<meta property=\"og:image:height\" content=\"2848\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"headline\":\"Tr\u00fcmmersuchhund\",\"datePublished\":\"2020-09-16T09:52:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/\"},\"wordCount\":973,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/tr\u00fcmmersuchhund-min.jpg\",\"keywords\":[\"Hunde im Einsatz\",\"Nasenarbeit\",\"Rettungshund\",\"Sp\u00fcrhund\",\"tr\u00fcmmersuchhund\"],\"articleSection\":[\"Hunde im Einsatz\",\"Hunde Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/\",\"name\":\"Tr\u00fcmmersuchhund: so findet er Versch\u00fcttete | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/tr\u00fcmmersuchhund-min.jpg\",\"datePublished\":\"2020-09-16T09:52:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"description\":\"Der Tr\u00fcmmersuchhund ist eine wichtige Hilfe bei der Suche von Versch\u00fctteten. Doch wie wird er ausgebildet und was geh\u00f6rt zu seinen Aufgaben?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/tr\u00fcmmersuchhund-min.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/tr\u00fcmmersuchhund-min.jpg\",\"width\":4272,\"height\":2848,\"caption\":\"Tr\u00fcmmersuchhund\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/truemmersuchhund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00fcmmersuchhund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZooRoyalDE\",\"https:\\\/\\\/x.com\\\/zooroyal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tr\u00fcmmersuchhund: so findet er Versch\u00fcttete | ZooRoyal Magazin","description":"Der Tr\u00fcmmersuchhund ist eine wichtige Hilfe bei der Suche von Versch\u00fctteten. Doch wie wird er ausgebildet und was geh\u00f6rt zu seinen Aufgaben?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/hunde\/truemmersuchhund\/","og_locale":"de_DE","og_type":"article","og_title":"Tr\u00fcmmersuchhund","og_description":"Der Tr\u00fcmmersuchhund ist eine wichtige Hilfe bei der Suche von Versch\u00fctteten. Doch wie wird er ausgebildet und was geh\u00f6rt zu seinen Aufgaben?","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_author":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2020-09-16T09:52:29+00:00","og_image":[{"width":4272,"height":2848,"url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/06\/tr\u00fcmmersuchhund-min.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"headline":"Tr\u00fcmmersuchhund","datePublished":"2020-09-16T09:52:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/"},"wordCount":973,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/06\/tr\u00fcmmersuchhund-min.jpg","keywords":["Hunde im Einsatz","Nasenarbeit","Rettungshund","Sp\u00fcrhund","tr\u00fcmmersuchhund"],"articleSection":["Hunde im Einsatz","Hunde Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/","name":"Tr\u00fcmmersuchhund: so findet er Versch\u00fcttete | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/06\/tr\u00fcmmersuchhund-min.jpg","datePublished":"2020-09-16T09:52:29+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"description":"Der Tr\u00fcmmersuchhund ist eine wichtige Hilfe bei der Suche von Versch\u00fctteten. Doch wie wird er ausgebildet und was geh\u00f6rt zu seinen Aufgaben?","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/06\/tr\u00fcmmersuchhund-min.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2020\/06\/tr\u00fcmmersuchhund-min.jpg","width":4272,"height":2848,"caption":"Tr\u00fcmmersuchhund"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/truemmersuchhund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Tr\u00fcmmersuchhund"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.facebook.com\/ZooRoyalDE","https:\/\/x.com\/zooroyal"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/20747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=20747"}],"version-history":[{"count":5,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/20747\/revisions"}],"predecessor-version":[{"id":20945,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/20747\/revisions\/20945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/20751"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=20747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=20747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=20747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}