{"id":17730,"date":"2020-11-18T13:05:53","date_gmt":"2020-11-18T12:05:53","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=17730"},"modified":"2023-06-26T15:48:35","modified_gmt":"2023-06-26T13:48:35","slug":"hunderennen","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderennen\/","title":{"rendered":"Hunderennen: Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?"},"content":{"rendered":"<div id=\"pl-17730\" class=\"panel-layout\">\n<div id=\"pg-17730-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-17730-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-17730-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18079 size-featured-whatever\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-760x570.jpg\" alt=\"Hunderennen\" width=\"760\" height=\"570\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-760x570.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-700x525.jpg 700w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-233x175.jpg 233w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-175x131.jpg 175w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-323x242.jpg 323w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/p>\n<p>Das Hunderennen ist bei uns in Deutschland kein sehr bekannter Hundesport, wie etwa <a href=\"\/magazin\/hunde\/training-hundesport\/die-beliebtesten-hundesportarten\/\" target=\"_blank\" rel=\"noopener noreferrer\">Agility<\/a> oder <a href=\"\/magazin\/hunde\/vermisstensuchhunde\/\">Mantrailing<\/a>. Es gibt aber einige Vereine, die hin und wieder Tagesveranstaltungen stattfinden lassen, bei denen Privatleute mit ihren Hunden an einem reinen Spa&szlig;-Rennen teilnehmen k&ouml;nnen. Hier haben sie auch meist die M&ouml;glichkeit, die &bdquo;Stars&ldquo; des Hunderennens in Aktion zu sehen: Die Windhunde.<\/p>\n<h2 id=\"welche-hunderassen-werden-fr-hunderennen-eingesetzt\">Welche Hunderassen werden f&uuml;r Hunderennen eingesetzt?<\/h2>\n<p>Bekannt f&uuml;r ihre Schnelligkeit und ihren <strong>grazilen K&ouml;rperbau<\/strong>, der ein hohes Tempo und die gewisse Leichtigkeit beim Sprinten erm&ouml;glicht, sind die <strong>Windhund-Rassen<\/strong>. Diese wurden in verschiedenen Gr&ouml;&szlig;en und mit unterschiedlichen Felleigenschaften <strong>f&uuml;r die Hetzjagd gez&uuml;chtet<\/strong>. Der <a href=\"\/magazin\/hunde\/hunderassen\/saluki-im-rasseportrait\/\" target=\"_blank\" rel=\"noopener noreferrer\">Saluki<\/a> ist ein sehr h&uuml;bscher und gro&szlig;er Windhund, welcher l&auml;ngeres Fell an den Ohren und der Rute hat. Er ist enorm schnell und dabei &auml;u&szlig;erst ausdauernd. Der <a href=\"\/magazin\/hunde\/hunderassen\/whippet\/\" target=\"_blank\" rel=\"noopener noreferrer\">Whippet<\/a> ist kurzhaarig und von mittlerer Gr&ouml;&szlig;e. Auch er ist in der Lage, wahnsinnig schnell &uuml;ber die Rennbahn zu schie&szlig;en und <strong>erstaunliche Energie<\/strong> aus seinem zarten, aber muskul&ouml;sen K&ouml;rper zu entwickeln. Heute ist der Whippet ein beliebter Begleithund geworden. Zu den langhaarigen und sogenannten &bdquo;befederten&ldquo; Windhunden geh&ouml;ren neben dem Saluki, der <a href=\"\/magazin\/hunde\/afghanischer-windhund-im-rasseportrait\/\" target=\"_blank\" rel=\"noopener noreferrer\">Afghanische Windhund<\/a> und der <a href=\"\/magazin\/hunde\/hunderassen\/barsoi-im-rasseportraet\/\" target=\"_blank\" rel=\"noopener noreferrer\">Barsoi<\/a>. Auch rauhaarige Windhunde gibt es, n&auml;mlich den <a href=\"\/magazin\/hunde\/deerhound\/\" target=\"_blank\" rel=\"noopener noreferrer\">Deerhound<\/a> und den <a href=\"\/magazin\/hunde\/hunderassen\/irischer-wolfshund\/\" target=\"_blank\" rel=\"noopener noreferrer\">Irischen Wolfshund<\/a>. Kurzhaarig hingegen sind Whippet, Sloughi, Magyar Agar, <a href=\"\/magazin\/hunde\/hunderassen\/italienisches-windspiel-im-rasseportrait\/\" target=\"_blank\" rel=\"noopener noreferrer\">Italienisches Windspiel<\/a>, <a href=\"\/magazin\/hunde\/galgo-espanol\/\" target=\"_blank\" rel=\"noopener noreferrer\">Galgo Espanol<\/a>, <a href=\"\/magazin\/hunde\/azawakh\/\" target=\"_blank\" rel=\"noopener noreferrer\">Azawakh<\/a>, Chart Polski und der schnellste von ihnen allen, der <a href=\"\/magazin\/hunde\/hunderassen\/greyhound\/\" target=\"_blank\" rel=\"noopener noreferrer\">Greyhound<\/a>.<\/p>\n<h2 id=\"was-macht-einen-sprinter-aus\">Was macht einen Sprinter aus?<\/h2>\n<p>Ein Sprinter muss <strong>&uuml;ber eine kurze Distanz m&ouml;glichst schnell rennen<\/strong>. Dabei kommt es also weniger auf die Ausdauer an, sondern mehr auf das Erreichen einer <strong>beeindruckend hohen Geschwindigkeit<\/strong>. Der Greyhound ist Meister dieser Disziplin. Der gro&szlig;e Hund ist &bdquo;typisch Windhund&ldquo; grazil, aber stark bemuskelt. Da er ein <strong>Sichtj&auml;ger<\/strong> ist, macht man sich seinen <a href=\"\/magazin\/hunde\/jagdhunde\/\" target=\"_blank\" rel=\"noopener noreferrer\">Jagdverhalten<\/a> zu Nutze, indem er auf der Rennbahn <strong>einem k&uuml;nstlichen Hasen hinterherjagt<\/strong>, der von einer speziellen Anlage vor ihm hergezogen wird. Hetzt der Hund seiner Beute hinterher, ist er <strong>v&ouml;llig auf diese fokussiert<\/strong> und sprintet was das Zeug h&auml;lt, bis er im Ziel seine Beute schlie&szlig;lich als <strong>Belohnung<\/strong> bekommt. Dieses Jagdverhalten steckt im Windhund und heutzutage d&uuml;rfen auch die als Familienhund gehaltenen Vierbeiner, diesen ab und an auf der Rennbahn eines Vereins ausleben.<\/p>\n<h2 id=\"hunderennen-fluch-und-segen\">Hunderennen &ndash; Fluch und Segen<\/h2>\n<p>Bei uns werden eher selten Hunderennen veranstaltet und wenn, dann sollte doch <strong>sehr verantwortungsvoll<\/strong> damit umgegangen und immer zum Wohle der Tiere gehandelt werden. Viele Windhundvereine haben die entsprechenden Bahnen vor Ort mit k&uuml;nstlichen Hasen etc. ausgestattet. Rassefans erfreuen sich an dem <strong>anmutigen Anblick<\/strong> eines sprintenden Windhundes, der seinem Hobby nachgeht. Diese Hunde haben <strong>gro&szlig;en Spa&szlig;<\/strong> daran und freuen sich, sich auspowern zu k&ouml;nnen, um danach den Abend aber auch wieder als Couchpotato zu verbringen und selig zu schlummern. So, wie der Retriever Talent bei der Apportierarbeit zeigt, der Deutsch Drahthaar gerne mit Herrchen zur Jagd geht oder der H&uuml;tehund hervorragend an Schafen arbeitet, so steckt dem Windhund das Rennen bzw. die Sichtjagd einfach <strong>im Blut<\/strong>.<\/p>\n<p>In anderen L&auml;ndern kommt es aber auch vor, dass man man stattdessen leider ein <strong>Riesengesch&auml;ft<\/strong> aus dem Talent der freundlichen, eleganten Hunde macht und geht <strong>mit einer ganz anderen Absicht<\/strong> vor. Renngesch&auml;fte boomen nach wie vor,- es werden <strong>Wetten<\/strong> &uuml;ber den Ausgang eines Wettkampfes abgeschlossen, sodass die Hunde einem entsprechend <strong>gro&szlig;en Druck<\/strong> ausgesetzt sind, Leistung zu bringen und das ausgesetzte <strong>Preisgeld<\/strong> einzufahren. Tiere die zu langsam, verletzt oder schlicht ungeeignet sind, werden entsprechend <strong>ausrangiert<\/strong>. Haben diese Hunde Gl&uuml;ck, so werden sie von einer der sich engagierenden Tierschutzorganisationen aufgenommen, die sich genau solcher Vierbeiner annimmt, sie versorgt und weiter in ein sicheres, liebendes Zuhause vermittelt. Hier gehen die Hunde ihrer Leidenschaft nicht als freudebringendes Hobby, sondern als <strong>ernste und harte Pflicht<\/strong> nach.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17781 size-full\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/10\/sprinter-hunderennen.jpg\" alt=\"Sprinter HUnderennen\" width=\"4335\" height=\"2245\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter-hunderennen.jpg 4335w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter-hunderennen-300x155.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter-hunderennen-768x398.jpg 768w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter-hunderennen-760x394.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter-hunderennen-323x167.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter-hunderennen-1140x590.jpg 1140w\" sizes=\"auto, (max-width: 4335px) 100vw, 4335px\" \/><\/p>\n<h2 id=\"knnen-nur-windhunde-an-rennen-teilnehmen\">K&ouml;nnen nur Windhunde an Rennen teilnehmen?<\/h2>\n<p>Es gibt immer wieder Renntage in ganz Deutschland und den Nachbarl&auml;ndern, an denen jeder eingeladen wird, an einem Hunderennen teilzunehmen oder als Besucher vorbeizukommen. Dabei tritt nat&uuml;rlich nicht der kleine Chihuahua gegen einen langbeinigen Ridgeback an, sondern es wird in Gr&ouml;&szlig;e und auch in Hunderassen unterschieden, um die Rennen fairer zu gestalten. Tats&auml;chlich gibt es auch meist kleine Preise oder Urkunden zu gewinnen.<br \/>\nHast du Lust, mit deinem Vierbeiner einmal teilzunehmen, so ist es v&ouml;llig egal, welcher Rasse dein Hund angeh&ouml;rt oder ob ihr ein Rennen schon mal ausprobiert habt. Wenn er gesund ist und sich nicht von dem Trubel vor Ort stressen l&auml;sst, so werdet ihr sicher viel Spa&szlig; haben! Hunde einer Gruppe starten einzeln &uuml;ber eine bestimmte Distanz, bei der die Zeit gemessen wird. Sp&auml;ter werden diese verglichen und der schnellste Hund hat nat&uuml;rlich gewonnen. Als Motivation, schnell zu laufen, werden bei den Spa&szlig;rennen keine Hasen verwendet, sondern Herrchen\/Frauchen l&auml;uft &uuml;ber die Bahn voran, w&auml;hrend der Vierbeiner am Start noch festgehalten wird und darf schlie&szlig;lich hinterhereilen, sobald &bdquo;sein&ldquo; Mensch am Ziel nach ihm ruft. Meist starten auch die Windhunde in einem Rennen und beeindrucken dabei so manchen Zuschauer mit ihrem Feuereifer.<\/p>\n<hr>\n<p><strong><a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12717 alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg\" alt=\"Kristina\" width=\"300\" height=\"221\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-768x566.jpg 768w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-380x280.jpg 380w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg 905w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Kristina Ziemer-Falke<\/strong> ist zertifizierte Hundetrainerin und Verhaltensberaterin durch die Tier&auml;rztekammer Schleswig-Holstein und das Messerli Forschungsinstitut der Veterin&auml;rmedizinischen Universit&auml;t Wien. Dar&uuml;ber hinaus verf&uuml;gt sie &uuml;ber viele Zusatzausbildungen und Schwerpunkte und ist im Pr&uuml;fungsausschuss der Tier&auml;rztekammer Niedersachsen f&uuml;r die Hundetrainerzertifizierungen.<br \/>\nMit ihrem Mann J&ouml;rg Ziemer gr&uuml;ndete sie das Schulungszentrum <a href=\"https:\/\/www.ziemer-falke.de\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Ziemer &amp; Falke<\/a>, in dem sie seit vielen Jahren mit viel Herz, Leidenschaft und Kompetenz Hundetrainer in ganz Deutschland ausbilden und viele Weiterbildungsangebote anbieten. Viele kennen Kristina au&szlig;erdem als erfolgreiche Autorin von Fachb&uuml;chern f&uuml;r Hundetrainer und Hundehalter sowie aus Artikeln beliebter Hundezeitschriften.<\/p>\n<hr><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-17730-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-17730-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-17730-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/annyx-brustgeschirr-fun-goldgloeckchen-m\/1000107742\/?icid=magproteaser_hunde_hunderennen_\" class=\"article__wrapper--productimage\" title=\"annyx Brustgeschirr Fun goldgl\u00f6ckchen M\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/wjnkgc-ZnVDedWg.jpg?host=ct\"\n                alt=\"annyx Brustgeschirr Fun goldgl\u00f6ckchen M\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    annyx                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">annyx Brustgeschirr Fun goldgl\u00f6ckchen M<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    44.49 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/annyx-brustgeschirr-fun-goldgloeckchen-m\/1000107742\/?icid=magproteaser_hunde_hunderennen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunderennen_\" class=\"article__wrapper--productimage\" title=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/1daly6-_uaDnJkz.jpg?host=ct\"\n                alt=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Muzzle Flex Maulkorb schwarz L-XL<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    19.19 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunderennen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/hunter-schleppleine-convenience-schwarz-20-1200\/1000109356\/?icid=magproteaser_hunde_hunderennen_\" class=\"article__wrapper--productimage\" title=\"Hunter Schleppleine Convenience schwarz 20\/1200\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/1iji3m-VyhgQ61w.jpg?host=ct\"\n                alt=\"Hunter Schleppleine Convenience schwarz 20\/1200\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Hunter                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Hunter Schleppleine Convenience schwarz 20\/1200<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    36.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/hunter-schleppleine-convenience-schwarz-20-1200\/1000109356\/?icid=magproteaser_hunde_hunderennen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a03db87543ae\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/annyx-brustgeschirr-fun-goldgloeckchen-m\/1000107742\/?icid=magproteaser_hunde_hunderennen_\" class=\"article__wrapper--productimage\" title=\"annyx Brustgeschirr Fun goldgl\u00f6ckchen M\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/wjnkgc-ZnVDedWg.jpg?host=ct\"\n                                    alt=\"annyx Brustgeschirr Fun goldgl\u00f6ckchen M\">\n\n                            <div id=\"swiper-button-next6a03db87543ae\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03db87543ae\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                annyx                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">annyx Brustgeschirr Fun goldgl\u00f6ckchen M<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                44.49 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/annyx-brustgeschirr-fun-goldgloeckchen-m\/1000107742\/?icid=magproteaser_hunde_hunderennen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunderennen_\" class=\"article__wrapper--productimage\" title=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/1daly6-_uaDnJkz.jpg?host=ct\"\n                                    alt=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\">\n\n                            <div id=\"swiper-button-next6a03db87543ae\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03db87543ae\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Muzzle Flex Maulkorb schwarz L-XL<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                19.19 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunderennen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/hunter-schleppleine-convenience-schwarz-20-1200\/1000109356\/?icid=magproteaser_hunde_hunderennen_\" class=\"article__wrapper--productimage\" title=\"Hunter Schleppleine Convenience schwarz 20\/1200\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/1iji3m-VyhgQ61w.jpg?host=ct\"\n                                    alt=\"Hunter Schleppleine Convenience schwarz 20\/1200\">\n\n                            <div id=\"swiper-button-next6a03db87543ae\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a03db87543ae\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Hunter                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Hunter Schleppleine Convenience schwarz 20\/1200<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                36.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/hunter-schleppleine-convenience-schwarz-20-1200\/1000109356\/?icid=magproteaser_hunde_hunderennen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a03db87543ae\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a03db87543ae\",\n                prevEl: \"#swiper-button-prev6a03db87543ae\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Das Hunderennen ist bei uns in Deutschland kein sehr bekannter Hundesport, wie etwa Agility oder Mantrailing. Es gibt aber einige Vereine, die hin und wieder Tagesveranstaltungen stattfinden lassen, bei denen&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderennen\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":45,"featured_media":18079,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2215,5],"tags":[2761,2768,2762,2769,2763,2767,1798,2760,126,1073,2766,1229,2765,1952,2764,2770,2759,1460,1231],"class_list":["post-17730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hunde-im-einsatz","category-hunde","tag-afghanischer-windhund","tag-asawakh","tag-barsoi","tag-chart-polski","tag-deerhound","tag-galgo-espanol","tag-greyhound","tag-hunderennen","tag-hundesport","tag-irischer-wolfshund","tag-italienisches-windspiel","tag-jagdhund","tag-magyar-agar","tag-saluki","tag-sloughi","tag-sprinter","tag-sprinter-hunderennen","tag-whippet","tag-windhund"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hunderennen - Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?<\/title>\n<meta name=\"description\" content=\"Hunderennen: Ein Spa\u00df f\u00fcr Mensch und Tier oder Tierqu\u00e4lerei f\u00fcr den Sprinter? Alle wichtigen Informationen zu dem Thema findest du hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderennen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hunderennen: Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?\" \/>\n<meta property=\"og:description\" content=\"Hunderennen: Ein Spa\u00df f\u00fcr Mensch und Tier oder Tierqu\u00e4lerei f\u00fcr den Sprinter? Alle wichtigen Informationen zu dem Thema findest du hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-18T12:05:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T13:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-760x507.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kristina Ziemer-Falke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kristina Ziemer-Falke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/\"},\"author\":{\"name\":\"Kristina Ziemer-Falke\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/278fd41e5e1019ad63bd3faa61c71d98\"},\"headline\":\"Hunderennen: Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?\",\"datePublished\":\"2020-11-18T12:05:53+00:00\",\"dateModified\":\"2023-06-26T13:48:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/\"},\"wordCount\":1046,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/sprinter_hunderennen.jpg\",\"keywords\":[\"Afghanischer Windhund\",\"Asawakh\",\"Barsoi\",\"Chart Polski\",\"Deerhound\",\"Galgo Espanol\",\"Greyhound\",\"Hunderennen\",\"Hundesport\",\"Irischer Wolfshund\",\"Italienisches Windspiel\",\"jagdhund\",\"Magyar Agar\",\"Saluki\",\"Sloughi\",\"Sprinter\",\"Sprinter Hunderennen\",\"Whippet\",\"windhund\"],\"articleSection\":[\"Hunde im Einsatz\",\"Hunde Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/\",\"name\":\"Hunderennen - Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/sprinter_hunderennen.jpg\",\"datePublished\":\"2020-11-18T12:05:53+00:00\",\"dateModified\":\"2023-06-26T13:48:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/278fd41e5e1019ad63bd3faa61c71d98\"},\"description\":\"Hunderennen: Ein Spa\u00df f\u00fcr Mensch und Tier oder Tierqu\u00e4lerei f\u00fcr den Sprinter? Alle wichtigen Informationen zu dem Thema findest du hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/sprinter_hunderennen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/sprinter_hunderennen.jpg\",\"width\":4630,\"height\":3087,\"caption\":\"Hunderennen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunderennen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hunderennen: Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/278fd41e5e1019ad63bd3faa61c71d98\",\"name\":\"Kristina Ziemer-Falke\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kristina_Ziemer_Falke-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kristina_Ziemer_Falke-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kristina_Ziemer_Falke-1-96x96.jpg\",\"caption\":\"Kristina Ziemer-Falke\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hunderennen - Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?","description":"Hunderennen: Ein Spa\u00df f\u00fcr Mensch und Tier oder Tierqu\u00e4lerei f\u00fcr den Sprinter? Alle wichtigen Informationen zu dem Thema findest du hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunderennen\/","og_locale":"de_DE","og_type":"article","og_title":"Hunderennen: Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?","og_description":"Hunderennen: Ein Spa\u00df f\u00fcr Mensch und Tier oder Tierqu\u00e4lerei f\u00fcr den Sprinter? Alle wichtigen Informationen zu dem Thema findest du hier.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2020-11-18T12:05:53+00:00","article_modified_time":"2023-06-26T13:48:35+00:00","og_image":[{"width":760,"height":507,"url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen-760x507.jpg","type":"image\/jpeg"}],"author":"Kristina Ziemer-Falke","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"Kristina Ziemer-Falke","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/"},"author":{"name":"Kristina Ziemer-Falke","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/278fd41e5e1019ad63bd3faa61c71d98"},"headline":"Hunderennen: Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?","datePublished":"2020-11-18T12:05:53+00:00","dateModified":"2023-06-26T13:48:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/"},"wordCount":1046,"commentCount":2,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen.jpg","keywords":["Afghanischer Windhund","Asawakh","Barsoi","Chart Polski","Deerhound","Galgo Espanol","Greyhound","Hunderennen","Hundesport","Irischer Wolfshund","Italienisches Windspiel","jagdhund","Magyar Agar","Saluki","Sloughi","Sprinter","Sprinter Hunderennen","Whippet","windhund"],"articleSection":["Hunde im Einsatz","Hunde Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/","name":"Hunderennen - Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen.jpg","datePublished":"2020-11-18T12:05:53+00:00","dateModified":"2023-06-26T13:48:35+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/278fd41e5e1019ad63bd3faa61c71d98"},"description":"Hunderennen: Ein Spa\u00df f\u00fcr Mensch und Tier oder Tierqu\u00e4lerei f\u00fcr den Sprinter? Alle wichtigen Informationen zu dem Thema findest du hier.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/10\/sprinter_hunderennen.jpg","width":4630,"height":3087,"caption":"Hunderennen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderennen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Hunderennen: Spa\u00df oder Qu\u00e4lerei f\u00fcr die Sprinter?"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/278fd41e5e1019ad63bd3faa61c71d98","name":"Kristina Ziemer-Falke","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-96x96.jpg","url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-96x96.jpg","contentUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-96x96.jpg","caption":"Kristina Ziemer-Falke"}}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/17730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=17730"}],"version-history":[{"count":14,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/17730\/revisions"}],"predecessor-version":[{"id":22656,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/17730\/revisions\/22656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/18079"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=17730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=17730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=17730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}