{"id":16571,"date":"2019-04-04T15:40:17","date_gmt":"2019-04-04T13:40:17","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=16571"},"modified":"2026-06-17T10:39:06","modified_gmt":"2026-06-17T08:39:06","slug":"rettungshunde","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/","title":{"rendered":"Rettungshunde"},"content":{"rendered":"<div id=\"pl-16571\"  class=\"panel-layout\" ><div id=\"pg-16571-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-16571-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-16571-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 id=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-16623 size-full\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg\" alt=\"Hund mit Rettungsgeschirr l\u00e4uft neben Einsatzkr\u00e4ften \u00fcber eine Wiese.\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/h2>\n<h2 id=\"die-geschichte\">Die Geschichte<\/h2>\n<p>Das klassische Bild der Rettungshunde hat sich in den Jahren deutlich ver\u00e4ndert. Viele kennen die Bilder eines Bernhardiners mit seinem F\u00e4sschen um den Hals, auf dem ein Rotes Kreuz gezeichnet ist.<\/p>\n<p>Die Geschichte sagt, dass der Hund \u201eBarry\u201c, zwischen 1800 und 1812 \u00fcber 40 Menschen das Leben gerettet haben soll. Barry war kein <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/bernhardiner\/\">Bernhardiner<\/a>, wie wir diese im heutigen Sinne kennen, aber er war schon ein stattlicher Kerl, der vermutlich zwischen 40 und 50 kg auf die Waage brachte. Dass er immer ein F\u00e4sschen mit Alkohol bei sich trug, ist aber wohl eher erfunden. Richtig ist allerdings, dass Barry und auch andere Hunde einheimischen Bergf\u00fchrern den Weg wiesen, wenn dieser verschneit war und auch durch\u2018s Bellen auf verungl\u00fcckte und ersch\u00f6pfte Reisende aufmerksam machte.<\/p>\n<p>Walt Disney Studios haben sich \u00fcbrigens auch mit Barry besch\u00e4ftigt und so entstand 1977 der Film \u201eBarry, der Bernhardiner\u201c. Und wenn du einmal in Frankreich unterwegs bist, steht bei Paris in Asni\u00e8res-sur-Seine ein Denkmal zu Ehren von Barry.<\/p>\n<h2 id=\"heute\">Heute<\/h2>\n<p>Machen wir einen Sprung von damals in unsere heutige Zeit und schauen uns einmal an, welche vielf\u00e4ltigen Aufgaben uns unsere Hunde heute im Bereich der Rettung von Menschen abnehmen.<\/p>\n<p>Bevor wir uns ein paar ihrer Aufgaben aber genauer anschauen, k\u00f6nnen wir sagen, dass unsere <strong>Rettungshunde<\/strong> diese Arbeit nur so genial machen k\u00f6nnen, weil sie einfach au\u00dferordentlich gut riechen k\u00f6nnen. Sie unterst\u00fctzen den Menschen bei dem jeweiligen Einsatz so enorm, dass sie ein relativ gro\u00dfes Gebiet viel schneller absuchen k\u00f6nnen, als wenn dies nur von Menschen gemacht wird. Selbst die Technik kann in bestimmten Bereichen keinen Rettungshund ersetzen. So wird immer darauf geachtet, dass es ein Zusammenspiel zwischen allen verf\u00fcgbaren Kr\u00e4ften und Mitteln bleibt.<\/p>\n<p>Da Hund und Mensch als Team in Eins\u00e4tzen k\u00f6rperlich, aber auch geistig stark gefordert werden, wird in der Ausbildung nat\u00fcrlich auf einiges geachtet.<\/p>\n<h2 id=\"rettungshunde-ausbilden-voraussetzungen\">Rettungshunde ausbilden: Voraussetzungen<\/h2>\n<p>Nicht jeder Hund muss f\u00fcr seinen speziellen Einsatz alles k\u00f6nnen, aber <strong>Grundvoraussetzungen<\/strong> sind:<\/p>\n<ul>\n<li>starke Nerven,<\/li>\n<li>ein ausgeglichenes Wesen<\/li>\n<li>und gesundheitliche Fitness.<\/li>\n<\/ul>\n<p>Dies gilt im \u00dcbrigen nat\u00fcrlich auch f\u00fcr den Hundef\u00fchrer. Neben einem sehr <strong>regelm\u00e4\u00dfigen Training<\/strong> sollte der Mensch auch einen gro\u00dfen Teamgeist mitbringen und nat\u00fcrlich k\u00f6rperliche Kondition.<\/p>\n<p>Egal bei welchem Wetter, ein ausgebildetes <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hund-mensch-team\/\">Mensch-Hund-Team<\/a> ist bei einem Einsatz immer zu Stelle. Vergessen darf man nicht: Unsere Rettungshundef\u00fchrer arbeiten ehrenamtlich und stecken viel Zeit und Geld in die Ausbildung und Eins\u00e4tze. Oft suchen und finden die Rettungshelfer nachts einen Menschen und sitzen dann morgens verschlafen im B\u00fcro.<\/p>\n<h2 id=\"schwerpunkte-der-rettungshundearbeit\">Schwerpunkte der Rettungshundearbeit<\/h2>\n<p>So unterschiedlich die Gel\u00e4nde, Gegebenheiten und Einsatzanforderungen sind, so unterschiedlich sind die verschiedenen Schwerpunkte unserer Rettungshunde.<\/p>\n<ul>\n<li>Bei einer\u00a0<strong>Wasserrettung\u00a0<\/strong>bringt der Rettungshund einen Ertrinkenden wieder ans Ufer.<\/li>\n<li>Die<strong> Wasserortung<\/strong> ist hingegen eine Form der Leichensuche. Von einem Boot aus erschn\u00fcffelt der Rettungshund menschliche Ger\u00fcche. Hat der Hund diesen in seiner Nase, macht er sich bemerkbar. Der Mensch kann dann Taucher an der Fundstelle hinabschicken.<\/li>\n<\/ul>\n<h2 id=\"vom-wasser-in-die-berge\">Vom Wasser in die Berge<\/h2>\n<ul>\n<li>Bei Schnee und Eis kommen unsere<strong> Lawinenhunde<\/strong> zum Einsatz. Trotz einiger technischer Hilfsmittel ist der Hund manchmal die einzige und dann auch beste M\u00f6glichkeit, Menschen unter Schneemassen zu orten. Die meisten dieser Rettungshundeteams geh\u00f6ren direkt der Bergwacht an, die in den Wintermonaten einen t\u00e4glichen Bereitschaftsdienst vorh\u00e4lt.<\/li>\n<li>Die meisten Rettungshunde sind im Bereich der <strong>Fl\u00e4chen- und Tr\u00fcmmersuche<\/strong>\u00a0im Einsatz. Bei der Fl\u00e4chensuche ist es oft eine Suche nach \u00e4lteren oder sehr jungen Menschen, die in gro\u00dfen Wald- oder Flurgebieten vermutet werden. Die Hunde haben gelernt, dass es sich f\u00fcr Sie lohnt, einen menschlichen Geruch zu wittern, zu verfolgen und dann anzuzeigen. Danach kann sein menschlicher Teampartner hinzukommen, um die gefundene Person zu bergen.<\/li>\n<li>Nach einem Erdbeben suchen unsere <strong>Tr\u00fcmmerhunde<\/strong>\u00a0nach menschlichen Ger\u00fcchen unter den meterdicken Schichten aus Ger\u00f6ll. Neben der eingesetzten Technik sind die Rettungshunde eine gro\u00dfe Bereicherung, da sie sich sicher auf den unwegsamen Tr\u00fcmmern fortbewegen und gleichzeitig menschliche Ger\u00fcche filtern. So kann hier gezielt eine Bergung stattfinden.<\/li>\n<\/ul>\n<p>Es g\u00e4be noch mehr Beispiele f\u00fcr den Einsatz unserer treuen Vierbeiner mit der <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/wie-hunde-gerueche-wahrnehmen\/\">Super-Nase<\/a>. Schauen wir unseren Hunden mal genauer ins Gesicht, werden wir sehen, dass die Nase doch irgendwie immer leicht in Bewegung ist. Kein Wunder, dass sie die Arbeit damit einfach perfektioniert haben.<\/p>\n<p>Was f\u00fcr ein gro\u00dfes Gl\u00fcck, dass unsere treuen Kameraden mit uns zusammen ein so tolles Team abgeben, dass man so anderen Menschen das Leben retten kann.<\/p>\n<p>Ein Dank an alle ehrenamtlichen Menschen, die diese Verantwortung auf sich nehmen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-16571-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-16571-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-16571-1-0-0\" class=\"so-panel widget widget_zr_widget_authorprofile panel-first-child panel-last-child\" data-index=\"1\" >\n    <hr>\n    <div class=\"author-profile-container\">\n\n        <img width=\"150\" height=\"150\" src=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-150x150.jpg\" class=\"alignleft size-thumbnail author-profile-image wp-post-image\" alt=\"Kristina Ziemer-Falke\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-150x150.jpg 150w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-60x60.jpg 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>\n        <p>\n            <a href=\"https:\/\/www.zooroyal.at\/magazin\/ueber-uns\/redaktion\/kristina-ziemer-falke\/\">Kristina Ziemer-Falke<\/a>, Hundetrainerin & Verhaltensberaterin       <\/p>\n\n        Gemeinsam mit ihrem Mann J\u00f6rg Ziemer betreibt sie das Schulungszentrum Ziemer & Falke, in dem sie seit vielen Jahren mit Herz, Leidenschaft und Kompetenz Hundetrainer in ganz Deutschland ausbilden und viele Weiterbildungsangebote anbieten. Kristina verf\u00fcgt \u00fcber eine Ausbildung zur Tierheilpraktikerin und Ern\u00e4hrungsberaterin f\u00fcr Hunde und einen Sachkundenachweis im Arzneimittelgesetz. Dar\u00fcber hinaus sitzt sie im Pr\u00fcfungsausschuss der Tier\u00e4rztekammer Niedersachsen f\u00fcr die Hundetrainerzertifizierungen und ist erfolgreich als Autorin von Fachb\u00fcchern und f\u00fcr Hundezeitschriften.  \n        \n         <!-- Clearfix f\u00fcr den float -->\n        <div style=\"clear: both;\"><\/div>\n    <\/div>\n    <hr>\n\n<\/div><\/div><\/div><div id=\"pg-16571-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-16571-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-16571-2-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898-16571\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" class=\"article__wrapper--productimage\" title=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/1daly6-_uaDnJkz.jpg?host=ct\"\n                alt=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Muzzle Flex Maulkorb schwarz L-XL<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    19.19 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/wolters-k2-tauprogramm-moxonleine-sepia-rosa-180-cm-x-0-9-cm\/1000107158\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" class=\"article__wrapper--productimage\" title=\"Wolters K2-Tauprogramm Moxonleine sepia rosa 180 cm x 0,9 cm\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/hn8wuc-YaQjTgrw.jpg?host=ct\"\n                alt=\"Wolters K2-Tauprogramm Moxonleine sepia rosa 180 cm x 0,9 cm\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Wolters Cat&amp;Dog                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Wolters K2-Tauprogramm Moxonleine sepia rosa 180 cm x 0,9 cm<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    19.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/wolters-k2-tauprogramm-moxonleine-sepia-rosa-180-cm-x-0-9-cm\/1000107158\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/escapure-rinderschulterblaetter-3x400g\/1000080281\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" class=\"article__wrapper--productimage\" title=\"ESCAPURE Rinderschulterbl\u00e4tter 3x400g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/fy7pet-DmI86YUQ.jpg?host=ct\"\n                alt=\"ESCAPURE Rinderschulterbl\u00e4tter 3x400g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Escapure                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ESCAPURE Rinderschulterbl\u00e4tter 3x400g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    24.29 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        20.24 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/escapure-rinderschulterblaetter-3x400g\/1000080281\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a981e907d7c0\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" class=\"article__wrapper--productimage\" title=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/1daly6-_uaDnJkz.jpg?host=ct\"\n                                    alt=\"Trixie Muzzle Flex Maulkorb schwarz L-XL\">\n\n                            <div id=\"swiper-button-next6a981e907d7c0\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a981e907d7c0\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Muzzle Flex Maulkorb schwarz L-XL<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                19.19 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-muzzle-flex-maulkorb-schwarz-l-xl\/1000058566\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/wolters-k2-tauprogramm-moxonleine-sepia-rosa-180-cm-x-0-9-cm\/1000107158\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" class=\"article__wrapper--productimage\" title=\"Wolters K2-Tauprogramm Moxonleine sepia rosa 180 cm x 0,9 cm\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/hn8wuc-YaQjTgrw.jpg?host=ct\"\n                                    alt=\"Wolters K2-Tauprogramm Moxonleine sepia rosa 180 cm x 0,9 cm\">\n\n                            <div id=\"swiper-button-next6a981e907d7c0\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a981e907d7c0\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Wolters Cat&amp;Dog                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Wolters K2-Tauprogramm Moxonleine sepia rosa 180 cm x 0,9 cm<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                19.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/wolters-k2-tauprogramm-moxonleine-sepia-rosa-180-cm-x-0-9-cm\/1000107158\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/escapure-rinderschulterblaetter-3x400g\/1000080281\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" class=\"article__wrapper--productimage\" title=\"ESCAPURE Rinderschulterbl\u00e4tter 3x400g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/fy7pet-DmI86YUQ.jpg?host=ct\"\n                                    alt=\"ESCAPURE Rinderschulterbl\u00e4tter 3x400g\">\n\n                            <div id=\"swiper-button-next6a981e907d7c0\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a981e907d7c0\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Escapure                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ESCAPURE Rinderschulterbl\u00e4tter 3x400g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                24.29 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    20.24 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/escapure-rinderschulterblaetter-3x400g\/1000080281\/?icid=magproteaser_hunde_hunde-im-einsatz_rettungshunde_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a981e907d7c0\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a981e907d7c0\",\n                prevEl: \"#swiper-button-prev6a981e907d7c0\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Geschichte Das klassische Bild der Rettungshunde hat sich in den Jahren deutlich ver\u00e4ndert. Viele kennen die Bilder eines Bernhardiners mit seinem F\u00e4sschen um den Hals, auf dem ein Rotes&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":15,"featured_media":16623,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2215,5],"tags":[2476,1149,2260,7192,2583,2581,2258,2582],"class_list":["post-16571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hunde-im-einsatz","category-hunde","tag-arbeitshunde","tag-bernhardiner","tag-hund-im-einsatz","tag-hunderettung","tag-lawinenhunde","tag-rettunghunde","tag-rettungshund","tag-truemmerhunde"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rettungshunde: Ihre Geschichte, Ausbildung &amp; Einsatzgebiete<\/title>\n<meta name=\"description\" content=\"Bernhardiner sind bekannte Rettungshunde mit einer Super-Nase. Erfahre hier mehr \u00fcber die Schwerpunkte der vierbeinigen Einsatzhelfer.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rettungshunde\" \/>\n<meta property=\"og:description\" content=\"Bernhardiner sind bekannte Rettungshunde mit einer Super-Nase. Erfahre hier mehr \u00fcber die Schwerpunkte der vierbeinigen Einsatzhelfer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-04T13:40:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T08:39:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"headline\":\"Rettungshunde\",\"datePublished\":\"2019-04-04T13:40:17+00:00\",\"dateModified\":\"2026-06-17T08:39:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/\"},\"wordCount\":782,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/rettungshunde-760x560.jpg\",\"keywords\":[\"Arbeitshunde\",\"Bernhardiner\",\"Hund im Einsatz\",\"Hunderettung\",\"Lawinenhunde\",\"Rettunghunde\",\"Rettungshund\",\"Tr\u00fcmmerhunde\"],\"articleSection\":[\"Hunde im Einsatz\",\"Hunde Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/\",\"name\":\"Rettungshunde: Ihre Geschichte, Ausbildung & Einsatzgebiete\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/rettungshunde-760x560.jpg\",\"datePublished\":\"2019-04-04T13:40:17+00:00\",\"dateModified\":\"2026-06-17T08:39:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"description\":\"Bernhardiner sind bekannte Rettungshunde mit einer Super-Nase. Erfahre hier mehr \u00fcber die Schwerpunkte der vierbeinigen Einsatzhelfer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/rettungshunde-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/rettungshunde-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"Hund mit Rettungsgeschirr l\u00e4uft neben Einsatzkr\u00e4ften \u00fcber eine Wiese.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-im-einsatz\\\/rettungshunde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rettungshunde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZooRoyalDE\",\"https:\\\/\\\/x.com\\\/zooroyal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rettungshunde: Ihre Geschichte, Ausbildung & Einsatzgebiete","description":"Bernhardiner sind bekannte Rettungshunde mit einer Super-Nase. Erfahre hier mehr \u00fcber die Schwerpunkte der vierbeinigen Einsatzhelfer.","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Rettungshunde","og_description":"Bernhardiner sind bekannte Rettungshunde mit einer Super-Nase. Erfahre hier mehr \u00fcber die Schwerpunkte der vierbeinigen Einsatzhelfer.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_author":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2019-04-04T13:40:17+00:00","article_modified_time":"2026-06-17T08:39:06+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"headline":"Rettungshunde","datePublished":"2019-04-04T13:40:17+00:00","dateModified":"2026-06-17T08:39:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/"},"wordCount":782,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg","keywords":["Arbeitshunde","Bernhardiner","Hund im Einsatz","Hunderettung","Lawinenhunde","Rettunghunde","Rettungshund","Tr\u00fcmmerhunde"],"articleSection":["Hunde im Einsatz","Hunde Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/","name":"Rettungshunde: Ihre Geschichte, Ausbildung & Einsatzgebiete","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg","datePublished":"2019-04-04T13:40:17+00:00","dateModified":"2026-06-17T08:39:06+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"description":"Bernhardiner sind bekannte Rettungshunde mit einer Super-Nase. Erfahre hier mehr \u00fcber die Schwerpunkte der vierbeinigen Einsatzhelfer.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/03\/rettungshunde-760x560.jpg","width":760,"height":560,"caption":"Hund mit Rettungsgeschirr l\u00e4uft neben Einsatzkr\u00e4ften \u00fcber eine Wiese."},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-im-einsatz\/rettungshunde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Rettungshunde"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.facebook.com\/ZooRoyalDE","https:\/\/x.com\/zooroyal"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/16571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=16571"}],"version-history":[{"count":19,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/16571\/revisions"}],"predecessor-version":[{"id":38989,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/16571\/revisions\/38989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/16623"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=16571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=16571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=16571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}