{"id":12563,"date":"2018-04-11T13:29:06","date_gmt":"2018-04-11T11:29:06","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=12563"},"modified":"2018-04-11T13:29:06","modified_gmt":"2018-04-11T11:29:06","slug":"star","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/vogel\/wildvoegel\/star\/","title":{"rendered":"Star &#8211; Vogel des Jahres 2018"},"content":{"rendered":"<div id=\"pl-12563\" class=\"panel-layout\">\n<div id=\"pg-12563-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-12563-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-12563-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12564\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg\" alt=\"Star Vogel\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/a>Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein K&uuml;nstler, er imitiert andere Vogelstimmen und Ger&auml;usche.<\/p>\n<p>Er ist Kindern und Erwachsenen gleicherma&szlig;en bekannt, weil es ihn schon sehr lange gibt und er weit verbreitet ist. Dennoch z&auml;hlt er zu den bedrohten Tierarten, weshalb er zum Vogel des Jahres 2018 gek&uuml;rt wurde. Die Rede ist vom gemeinen Star. Der mittelgro&szlig;e, dunkel gefiederte Singvogel mit den metallisch-gr&uuml;nen und purpurfarbenen Einschl&uuml;ssen ist f&uuml;r seinen geschw&auml;tzigen Gesang bekannt, mit dem er uns nahezu das gesamte Jahr unterh&auml;lt. Jeden Herbst sammeln sich die Stare, um den <a href=\"\/magazin\/vogel\/stunde-der-wintervoegel\/\">Winter<\/a> im w&auml;rmeren S&uuml;den zu verbringen. Dann bilden sie riesige Wolken, die sie in atemberaubenden Formationen &uuml;ber den Himmel bewegen. Doch die zunehmende Industrialisierung in der Landwirtschaft raubt ihnen Lebensraum und Nahrungsquellen. Um ihnen zu helfen und sie zu sch&uuml;tzen, braucht es nicht viel. Was auch du tun kannst, erf&auml;hrst du in diesem Beitrag.<\/p>\n<h2 id=\"wissenswertes-ber-den-star\">Wissenswertes &uuml;ber den Star<\/h2>\n<p>Der Star z&auml;hlt zur Gattung der Sperlingsv&ouml;gel. Sein lateinischer oder wissenschaftlicher Name lautet &#8222;Sturnus vulgaris&#8220;. Er ist eher von mittelgro&szlig;er Statur, in etwa vergleichbar mit der Gr&ouml;&szlig;e einer Amsel, verf&uuml;gt aber &uuml;ber einen k&uuml;rzeren Schwanz. Die Weibchen sind meist etwas zierlicher als m&auml;nnliche Stare. Etwa 20 Zentimeter misst ein Star und wiegt zwischen 75 und 82 Gramm.<\/p>\n<p>Stare wechseln zweimal im Jahr das Gefieder. So kannst du beobachten, dass insbesondere die M&auml;nnchen w&auml;hrend der Brutzeit im Fr&uuml;hjahr ihr Prachtkleid tragen, das in unz&auml;hligen Farben schimmert, bei denen Gr&uuml;n und Purpur &uuml;berwiegen. Es wirkt, als w&auml;re ihr Gefieder mit unz&auml;hligen Perlen bestickt. Ihre langen, dunklen Federn der Fl&uuml;gel sind zudem mit wei&szlig;en bis hellbeigefarbenen Spitzen versehen, die weithin leuchten. Der gelbe Schnabel wechselt seine auff&auml;llige Farbe im Schlichtkleid von Herbst und Winter hin zu Schwarz. Im gleichen Ma&szlig;e verblassen die Farben des Prachtkleides w&auml;hrend der kalten Jahreszeit, um im n&auml;chsten Fr&uuml;hjahr wieder neu zu erstrahlen. Auch Jungstare tragen ihr farbenfrohes Gefieder erstmals im n&auml;chsten Fr&uuml;hling. Tats&auml;chlich k&ouml;nnte man denken, es handelt sich um zwei unterschiedliche Vogelarten.<\/p>\n<h2 id=\"stare-sind-meister-der-imitation\">Stare sind Meister der Imitation<\/h2>\n<p>Einen Star an seinem Gesang zu erkennen, ist gar nicht so einfach. Denn der S&auml;nger ist in der Lage, eine Vielzahl von Tierstimmen und Ger&auml;uschen t&auml;uschend echt nachzuahmen. Er bellt wie ein <a href=\"\/magazin\/hunde\/\">Hund<\/a>, bl&ouml;kt wie ein Lamm, ahmt den Jagdschrei des M&auml;usebussards nach oder schimpft wie eine Amsel. Der Star imitiert auch perfekt Alarmanlagen von H&auml;usern oder Autos. Auch Polizeisirenen spottet er. Wenn du am Waldrand spazieren gehst und dein Handy klingelt, kann es sein, dass niemand dran ist und in Wirklichkeit ein Star das Ger&auml;usch zum Verwechseln &auml;hnlich vorgetragen hat.<\/p>\n<p>Stare sind in der Lage, unterschiedlich laut und in wechselnden Tonfolgen zu singen und zu rufen. Ihre Schn&auml;bel bewegen sich dabei nur m&auml;&szlig;ig, weshalb sie auch als Bauchredner durchgehen k&ouml;nnten. Dar&uuml;ber hinaus pfeifen und zischeln sie und wechseln mit gepressten und schnalzenden T&ouml;nen ab. Nicht selten wirkt ihr Gesang wie eine geschw&auml;tzige Unterhaltung zweier Personen.<\/p>\n<h2 id=\"bei-den-staren-baut-das-mnnchen-das-nest\">Bei den Staren baut das M&auml;nnchen das Nest<\/h2>\n<p>Manche Stare leben monogam mit einem Partner zusammen, oft wechselt das Weibchen aber auch das Partnertier. In der Regel br&uuml;ten sie zweimal im Jahr. Ideale Nistpl&auml;tze sind Dachgauben oder Dachvorspr&uuml;nge, etwa bei Wohnh&auml;usern, Stallungen oder Scheunen. Auch Nistk&auml;sten akzeptieren die Meisters&auml;nger zur Aufzucht ihrer Nachkommen. Gerne wird alles adaptiert, was ausreichend Schutz bietet und einen nicht zu kleinen Eingang hat.<\/p>\n<p>Das Nest oder die H&ouml;hle wird dann zun&auml;chst vom M&auml;nnchen vorbereitet und mit grobem Ast- und Blattwerk ausgestattet. F&uuml;r die Feinarbeit ist dann das Weibchen zust&auml;ndig, die das Nest mit Halmen und Gr&auml;sern weich auspolstert. Sechs bis acht Eier legt die Starin pro Brut, die dann innerhalb von circa 12 Tagen ausgebr&uuml;tet werden. Anschlie&szlig;end schafft das Elternpaar gemeinsam das Futter f&uuml;r die Kleinen heran. Meist ist die Brutzeit gegen Ende Juli abgeschlossen und die Jungstare verlassen das Nest.<\/p>\n<h2 id=\"lebensraum-vom-ursprnglichen-waldbewohner-zum-feldsiedler\">Lebensraum &ndash; vom urspr&uuml;nglichen Waldbewohner zum Feldsiedler<\/h2>\n<p>Der Star ist in ganz Deutschland weit verbreitet. Fr&uuml;her siedelten Stare meist in der N&auml;he von Waldlichtungen oder in Waldrandbereichen. Mehr und mehr sind sie inzwischen eher in l&auml;ndlichen Gebieten anzutreffen, die von Menschen bewirtschaftet werden. In Nordsachsen und Sachsen-Anhalt ist die h&ouml;chste Population anzutreffen, aber auch in obstreichen Bundesl&auml;ndern wie in Baden-W&uuml;rttemberg. F&uuml;r seine Nachzucht ben&ouml;tigt er hohe B&auml;ume oder Geb&auml;ude&uuml;berst&auml;nde, die ihm gute <a href=\"\/magazin\/vogel\/baus-dir-selbst-vogelhaeuschen-piepmatz\/\">Nistm&ouml;glichkeiten<\/a> bieten. Dar&uuml;ber hinaus lieben Stare offene Fl&auml;chen mit niedriger Vegetation zur Nahrungssuche. Mit Weidetieren verbindet sie eine besondere Kooperation. Sie befreien Schafe, Pferde oder K&uuml;he von l&auml;stigen Fliegen und Zecken. Insbesondere im Sommer kannst du oft beobachten, dass Stare auf Weidetieren sitzen und von ihnen geduldet werden.<\/p>\n<h2 id=\"nahrung-des-stars\">Nahrung des Stars<\/h2>\n<p>Wiesen und abgeerntete Felder sind die idealen Nahrungsgebiete f&uuml;r den Star. Hier sucht er nach Insekten, Schnecken und W&uuml;rmern. Zudem ern&auml;hrt er sich von Strauchbeeren, die am Feldrand wachsen, macht den Obstbauern Fr&uuml;chte wie Kirschen oder Weintrauben abspenstig und bedient sich bei S&auml;mereien. Aufgrund der eher milden Winter in Deutschland bleiben viele Stare das ganze Jahr &uuml;ber bei uns. In Herbst und Winter ern&auml;hren sie sich daher vielfach von N&uuml;ssen oder Streu- und Fettfutter.<\/p>\n<h2 id=\"starschwrme-ein-einzigartiges-naturschauspiel\">Starschw&auml;rme &ndash; ein einzigartiges Naturschauspiel<\/h2>\n<p>Stare sind nicht nur begnadete S&auml;nger, sie sind auch wahre Luftakrobaten. Der Fl&uuml;gelschlag des Stars ist schnell und kr&auml;ftig. Dadurch legt er nicht nur ein hohes Tempo vor, er ist auch sehr wendig. Beeindruckend sind die riesigen Schw&auml;rme, die sich im Herbst zusammenfinden. Stare bilden imposante Wolkenformationen, die zuweilen mehr als 100.000 Tiere umfassen. Dann zeigt sich ein einzigartiges Naturschauspiel am Himmel, das du miterleben kannst. Die Stare wechseln in schnellem Tempo ihre Richtung, fliegen synchron, schlagen Wellen und halten dabei immer ihre Position im Schwarm. Alles ohne jemals zusammenzusto&szlig;en. Sie orientieren sich dabei an den Artgenossen in ihrem direkten Umfeld und k&ouml;nnen innerhalb von Sekundenbruchteilen auf Richtungs&auml;nderungen reagieren. Die Formation bietet jedem einzelnen Vogel Sicherheit vor Angreifern aus der Luft, gemeinsam sind sie stark auf ihrem Weg nach S&uuml;d- und Westeuropa. Bis zu 2.000 Kilometer legen die Stare auf diese Weise zur&uuml;ck, bis sie im Fr&uuml;hjahr zur&uuml;ckkehren.<\/p>\n<h2 id=\"hilfe-fr-den-star\">Hilfe f&uuml;r den Star<\/h2>\n<p>Der Star ist in der Roten Liste der gef&auml;hrdeten Tierarten eingetragen, weil sein <a href=\"\/magazin\/vogel\/zahl-der-voegel-geht-zurueck\/\">Bestand<\/a> in den letzten Jahren immer weiter zur&uuml;ckgegangen ist. Verantwortlich daf&uuml;r zeichnet die zunehmende Industrialisierung in der Landwirtschaft, die Verwendung von Pestiziden sowie eine ver&auml;nderte Nutztierhaltung. Obwohl der Star seine Anpassungsf&auml;higkeit unter Beweis gestellt hat, fehlt es ihm an Nahrung, Lebensraum und Brutm&ouml;glichkeiten. Hier kann der Mensch helfen.<\/p>\n<p>Der Star ern&auml;hrt sich von Insekten und diese sind &uuml;berall dort zu finden, wo Tiere in der Natur weiden k&ouml;nnen und wo es nat&uuml;rliche Gr&uuml;nfl&auml;chen mit einem vielf&auml;ltigen Bl&uuml;tenbestand gibt. Dem Star kannst du aktiv helfen, indem du im Garten auch einen Bereich f&uuml;r Insekten anlegst. Dar&uuml;ber hinaus kannst du Nistk&auml;sten f&uuml;r Stare aufh&auml;ngen, die sie gerne f&uuml;r ihre Nachzucht annehmen werden.<\/p>\n<h3 id=\"fazit\">Fazit<\/h3>\n<p>Noch ist der Star fl&auml;chendeckend zu finden, doch der Bestand des bekannten Stimmenimitators und Formationsk&uuml;nstlers ist r&uuml;ckl&auml;ufig. Du kannst aktiv etwas dagegen unternehmen, indem du ihm neuen Lebensraum und <a href=\"\/magazin\/vogel\/wildvoegel-ganzjahresfuetterung-sinnvoll\/\">Nahrungsquellen<\/a> anbietest. Damit der Vogel des Jahres 2018 auch in Zukunft noch das Klingeln deines Handys nachmachen kann.<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-12563-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-12563-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-12563-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/dobar-deko-vogelhaus-welcome\/1000100557\/?icid=magproteaser_vogel_wildvoegel_star_\" class=\"article__wrapper--productimage\" title=\"&quot;Dobar Deko-Vogelhaus &quot;&quot;Welcome&quot;&quot;&quot;\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/bkwqc2-7MePa1eS.jpg?host=ct\"\n                alt=\"&quot;Dobar Deko-Vogelhaus &quot;&quot;Welcome&quot;&quot;&quot;\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    dobar wildlife                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">&quot;Dobar Deko-Vogelhaus &quot;&quot;Welcome&quot;&quot;&quot;<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    21.19 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/dobar-deko-vogelhaus-welcome\/1000100557\/?icid=magproteaser_vogel_wildvoegel_star_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-sommer-muesli-2-5kg\/1000080640\/?icid=magproteaser_vogel_wildvoegel_star_\" class=\"article__wrapper--productimage\" title=\"Erdtmann&#039;s Sommer-M\u00fcsli 2,5kg\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/epox8j-KCDvzWHv.jpg?host=ct\"\n                alt=\"Erdtmann&#039;s Sommer-M\u00fcsli 2,5kg\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Erdtmann&#039;s                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Erdtmann&#039;s Sommer-M\u00fcsli 2,5kg<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    6.79 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        2.72 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-sommer-muesli-2-5kg\/1000080640\/?icid=magproteaser_vogel_wildvoegel_star_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-nistkasten-fuer-sittiche\/1000033207\/?icid=magproteaser_vogel_wildvoegel_star_\" class=\"article__wrapper--productimage\" title=\"Trixie Nistkasten f\u00fcr Sittiche\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/jljg0n-wrRzMum_.jpg?host=ct\"\n                alt=\"Trixie Nistkasten f\u00fcr Sittiche\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Nistkasten f\u00fcr Sittiche<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    7.19 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-nistkasten-fuer-sittiche\/1000033207\/?icid=magproteaser_vogel_wildvoegel_star_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a04ed40e0b10\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/dobar-deko-vogelhaus-welcome\/1000100557\/?icid=magproteaser_vogel_wildvoegel_star_\" class=\"article__wrapper--productimage\" title=\"&quot;Dobar Deko-Vogelhaus &quot;&quot;Welcome&quot;&quot;&quot;\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/bkwqc2-7MePa1eS.jpg?host=ct\"\n                                    alt=\"&quot;Dobar Deko-Vogelhaus &quot;&quot;Welcome&quot;&quot;&quot;\">\n\n                            <div id=\"swiper-button-next6a04ed40e0b10\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04ed40e0b10\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                dobar wildlife                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">&quot;Dobar Deko-Vogelhaus &quot;&quot;Welcome&quot;&quot;&quot;<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                21.19 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/dobar-deko-vogelhaus-welcome\/1000100557\/?icid=magproteaser_vogel_wildvoegel_star_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-sommer-muesli-2-5kg\/1000080640\/?icid=magproteaser_vogel_wildvoegel_star_\" class=\"article__wrapper--productimage\" title=\"Erdtmann&#039;s Sommer-M\u00fcsli 2,5kg\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/epox8j-KCDvzWHv.jpg?host=ct\"\n                                    alt=\"Erdtmann&#039;s Sommer-M\u00fcsli 2,5kg\">\n\n                            <div id=\"swiper-button-next6a04ed40e0b10\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04ed40e0b10\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Erdtmann&#039;s                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Erdtmann&#039;s Sommer-M\u00fcsli 2,5kg<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                6.79 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    2.72 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/erdtmann-s-sommer-muesli-2-5kg\/1000080640\/?icid=magproteaser_vogel_wildvoegel_star_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-nistkasten-fuer-sittiche\/1000033207\/?icid=magproteaser_vogel_wildvoegel_star_\" class=\"article__wrapper--productimage\" title=\"Trixie Nistkasten f\u00fcr Sittiche\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/jljg0n-wrRzMum_.jpg?host=ct\"\n                                    alt=\"Trixie Nistkasten f\u00fcr Sittiche\">\n\n                            <div id=\"swiper-button-next6a04ed40e0b10\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04ed40e0b10\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Nistkasten f\u00fcr Sittiche<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                7.19 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-nistkasten-fuer-sittiche\/1000033207\/?icid=magproteaser_vogel_wildvoegel_star_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a04ed40e0b10\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a04ed40e0b10\",\n                prevEl: \"#swiper-button-prev6a04ed40e0b10\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein K&uuml;nstler, er imitiert andere Vogelstimmen und Ger&auml;usche. Er ist Kindern und&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/vogel\/wildvoegel\/star\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":35,"featured_media":12564,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,50],"tags":[2066,2067,2068,2069,1959],"class_list":["post-12563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vogel","category-wildvoegel","tag-star-vogel","tag-stare","tag-starschwaerme","tag-vogelstimmen","tag-wildvoegel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Star - Vogel des Jahres 2018 | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein richtiger K\u00fcnstler.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/vogel\/wildvoegel\/star\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Star - Vogel des Jahres 2018\" \/>\n<meta property=\"og:description\" content=\"Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein richtiger K\u00fcnstler.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-11T11:29:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/2d4f21e50479b72c19f7f67436e3dcf2\"},\"headline\":\"Star &#8211; Vogel des Jahres 2018\",\"datePublished\":\"2018-04-11T11:29:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/\"},\"wordCount\":1431,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Star-760x560.jpg\",\"keywords\":[\"Star Vogel\",\"Stare\",\"Starschw\u00e4rme\",\"Vogelstimmen\",\"wildv\u00f6gel\"],\"articleSection\":[\"Vogel Magazin\",\"Wildv\u00f6gel\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/\",\"name\":\"Star - Vogel des Jahres 2018 | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Star-760x560.jpg\",\"datePublished\":\"2018-04-11T11:29:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/2d4f21e50479b72c19f7f67436e3dcf2\"},\"description\":\"Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein richtiger K\u00fcnstler.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Star-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Star-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"Star Vogel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/vogel\\\/wildvoegel\\\/star\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Star &#8211; Vogel des Jahres 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/2d4f21e50479b72c19f7f67436e3dcf2\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_35_1558596332-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_35_1558596332-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_35_1558596332-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.zooroyal.de\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Star - Vogel des Jahres 2018 | ZooRoyal Magazin","description":"Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein richtiger K\u00fcnstler.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/vogel\/wildvoegel\/star\/","og_locale":"de_DE","og_type":"article","og_title":"Star - Vogel des Jahres 2018","og_description":"Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein richtiger K\u00fcnstler.","og_url":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2018-04-11T11:29:06+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/2d4f21e50479b72c19f7f67436e3dcf2"},"headline":"Star &#8211; Vogel des Jahres 2018","datePublished":"2018-04-11T11:29:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/"},"wordCount":1431,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg","keywords":["Star Vogel","Stare","Starschw\u00e4rme","Vogelstimmen","wildv\u00f6gel"],"articleSection":["Vogel Magazin","Wildv\u00f6gel"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/","url":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/","name":"Star - Vogel des Jahres 2018 | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg","datePublished":"2018-04-11T11:29:06+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/2d4f21e50479b72c19f7f67436e3dcf2"},"description":"Der Star ist Vogel des Jahres 2018. Eindrucksvoll sind die gigantischen Zugformationen im Herbst. Zudem ist der Star ein richtiger K\u00fcnstler.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2018\/03\/Star-760x560.jpg","width":760,"height":560,"caption":"Star Vogel"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/vogel\/wildvoegel\/star\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Star &#8211; Vogel des Jahres 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/2d4f21e50479b72c19f7f67436e3dcf2","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_35_1558596332-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_35_1558596332-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_35_1558596332-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.zooroyal.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/12563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=12563"}],"version-history":[{"count":3,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/12563\/revisions"}],"predecessor-version":[{"id":12644,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/12563\/revisions\/12644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/12564"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=12563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=12563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=12563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}