{"id":1183,"date":"2015-02-16T16:07:38","date_gmt":"2015-02-16T14:07:38","guid":{"rendered":"https:\/\/www.zooroyal.de\/ratgeber\/?p=1183"},"modified":"2017-11-22T17:10:20","modified_gmt":"2017-11-22T16:10:20","slug":"hunde-iq-scharfsinnige-vierbeiner","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/","title":{"rendered":"Hunde-IQ: Scharfsinnige Vierbeiner"},"content":{"rendered":"<div id=\"pl-1183\" class=\"panel-layout\">\n<div id=\"pg-1183-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-1183-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-1183-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5359\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg\" alt=\"Hunde-IQ\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/a>Der Hunde-IQ wurde lange untersch&auml;tzt. Doch viele Hundebesitzer sind sich einig, ihre Vierbeiner sind nicht nur treu, sondern auch scharfsinnig. Was Intelligenz bei Hunden genau bedeutet, wie diese sich &auml;u&szlig;ert und welche Rassen besonders pfiffig sind, erf&auml;hrst du hier.<\/p>\n<p><!--more--><\/p>\n<p><a class=\"link_button_ratgeber\" href=\"\/hund\/hundespielzeug\/intelligenzspielzeug\/\">Zum Intelligenzspielzeug-Sortiment<\/a><\/p>\n<h2 id=\"groes-intelligenz-potenzial\">Gro&szlig;es Intelligenz-Potenzial<\/h2>\n<p>Sp&auml;testens seit &bdquo;Lassie&ldquo;, &bdquo;Kommissar Rex&ldquo; oder &bdquo;Scott und Huutsch&ldquo; wissen wir, Hunde sind weitaus aufgeweckter, als ihr Ruf. Im Alltag helfen sie Behinderten, erschn&uuml;ffeln Diabetes, sind beim Zoll als Drogenhunde im Einsatz oder zeigen Blinden den rechten Weg. Doch wie &auml;u&szlig;ert sich die Intelligenz unserer Fellnasen &uuml;berhaupt? Die Hundeintelligenz kann in vier verschiedenen Intelligenztypen unterteilt werden:<\/p>\n<ul>\n<li>Die instinktive Intelligenz (ererbte F&auml;higkeiten)<\/li>\n<li>Die adaptive Intelligenz (erlernte F&auml;higkeiten)<\/li>\n<li>Die Arbeits- und die Gehorsamsintelligenz (Gehorsam)<\/li>\n<\/ul>\n<p>Nat&uuml;rlich ist der beste Freund des Menschen nicht so hochbegabt wie Marie Curie, Albert Einstein oder Max Planck. Doch auch der IQ unserer Fellnasen kann sich sehen lassen. Der amerikanische Hundeforscher und Psychologe Stanley Coren ermittelte 2008 im Rahmen einer breiten Studie ein Rassen-Intelligenz-Ranking. F&uuml;r die Ermittlung der Intelligenz hat Coren die Arbeits- und Gehorsamsintelligenz der Tiere getestet und bewertet.<\/p>\n<p><em><strong>Das Ergebnis<\/strong><\/em>: Hunden kann immerhin eine mentale F&auml;higkeit von zwei- bis zweieinhalb-j&auml;hrigen Kindern zugeschrieben werden.<\/p>\n<p>Doch nicht alle Hunde sind gleich schlau. Die Intelligenz der verschiedenen <a href=\"\/magazin\/hunde\/hunderassen\/\">Hunderassen<\/a> unterscheidet sich erheblich voneinander. Und wann ist ein Hund klug? Pfiffige Exemplare finden beispielsweise den k&uuml;rzesten und einfachsten Weg zu ihrem Ziel und sind dazu in der Lage, einfachste Mechaniken &ndash; wie zum Beispiel eine T&uuml;rklinke &ndash; zu bedienen. Dar&uuml;ber hinaus k&ouml;nnen Hunde W&ouml;rter wie &bdquo;sitz&ldquo;, &bdquo;platz&ldquo;, &bdquo;bleib&ldquo; etc. und deren Bedeutung unterscheiden. Durchschnittlich verstehen Hunde circa 150 W&ouml;rter. Besonders Intelligent Hunde haben einen &bdquo;Wortschatz&ldquo; von bis zu 250 W&ouml;rtern.<\/p>\n<h2 id=\"intelligenz-bestien-rassen-im-vergleich\">Intelligenz-Bestien: Rassen im Vergleich<\/h2>\n<p>Allen voran geht der <a href=\"\/magazin\/hunde\/border-collie\/\">Border Collie <\/a>als Sieger der Rangliste hervor und sichert sich so seinen Ruf als intelligentester und aufmerksamster Hund. Platz zwei geht an den <a href=\"\/magazin\/hunde\/hunderassen\/pudel\/\">Pudel<\/a>. Pudel gelten als sehr lebhaft. Einst wurden sie zur Jagd im Wasser genutzt. Hiervon leitet sich auch ihr Name ab, welcher im Altdeutschen &bdquo;puddeln&ldquo; &ndash; im Wasser planschen, bedeutet. Sie sind nicht nur besonders loyale und treue Weggef&auml;hrten, dar&uuml;ber hinaus zeichnen sie sich durch ihre hohe Lern- und Dressurf&auml;higkeit ab.<\/p>\n<p>Platz drei heimst sich der <a href=\"\/magazin\/hunde\/hunderassen\/deutscher-schaeferhund\/\">Deutsche Sch&auml;ferhund<\/a> ein. Seine Intelligenz, Nervenst&auml;rke und sein ausgeglichener Charakter machen ihn zu einem idealen Polizei- und Wachhund. <a href=\"\/magazin\/hunde\/hunderassen\/golden-retriever\/\">Golden Retriever<\/a> sind nicht nur besonders familienbezogene Hunde, sie sind zudem noch au&szlig;erordentlich pfiffig. Der Apportiermeister belegt beim Ranking Platz vier. Platz f&uuml;nf geht an den <a href=\"\/magazin\/hunde\/hunderassen\/dobermann\/\">Dobermann<\/a>. Neben dem Deutschen Sch&auml;ferhund, ist auch er ein beliebter tierischer Helfer der Polizei und des Zolls. Auch als Rettungshund wird er immer wieder gerne eingesetzt. Sein Wesen ist ausgeglichen. Doberm&auml;nner sind friedfertige Familienhunde, welche in Gefahrensituationen dennoch durchgreifen und genau wissen, was zu tun ist.<\/p>\n<p>Und wer sind die Verlierer? Den letzten Platz belegt laut Coren der Afghanische Windhund. Seine Erziehung wird durch seine Eigenwilligkeit erschwert. Hundebesitzer sollten bei der Erziehung von Afghanischen Windhunden besonders viel Geduld mitbringen. Doch auch bei Basenji kann die Erziehung zur Geduldsprobe werden. Die Tiere sind besonders temperamentvoll und dickk&ouml;pfig, was mitunter auch auf Kosten ihrer Lernbereitschaft geht.<\/p>\n<p>Auch die <a href=\"\/magazin\/hunde\/hunderassen\/bulldog\/\">Englische Bulldogge<\/a> ist laut Ranking nur unterdurchschnittlich intelligent. Die Tiere wurden urspr&uuml;nglich als Kampfhunde gez&uuml;chtet. Infolgedessen &ndash; auch wenn sie oftmals ruhig und gem&uuml;tlich wirken &ndash; k&ouml;nnen sie, wenn man sie reizt oder sie sich angegriffen f&uuml;hlen, schnell aggressive Tendenzen entwickeln. Auch der <a href=\"\/magazin\/hunde\/hunderassen\/chow-chow\/\">Chow Chow <\/a>sowie der &nbsp;sind nur im unteren Bereich des Rankings zu finden.<\/p>\n<h2 id=\"hunde-iq-trainieren\">Hunde-IQ trainieren<\/h2>\n<p>Ohne eine individuelle F&ouml;rderung kann dein Hund sein Potenzial nicht g&auml;nzlich aussch&ouml;pfen. Umso wichtiger ist es, dass du deinen Vierbeiner f&ouml;rderst und ihn geistig fit h&auml;ltst. Auch wenn einige Hunderassen schneller lernen als andere, eine individuelle F&ouml;rderung, durch kleine t&auml;gliche Aufgaben machen Hunde gl&uuml;cklich und st&auml;rken die <a href=\"\/magazin\/hunde\/zu-zweit\/\">Hund-Mensch-Beziehung<\/a>.<\/p>\n<p>Du kannst deinen Hund auf zwei Arten besch&auml;ftigen. Bei der &uuml;blichen Methode bildest du deine Fellnase auf ein bestimmtes <a href=\"\/magazin\/hunde\/training-hundesport\/clickertraining\/\">Lernziel<\/a>, wie beispielsweise &bdquo;Sitz&ldquo; oder &bdquo;Platz&ldquo; aus. Eine weitere M&ouml;glichkeit der individuellen F&ouml;rderung sind Probleml&ouml;sungsaufgaben. Hierbei wird dein Hund vor ein Problem gestellt, welches er selbstst&auml;ndig l&ouml;sen muss. Diese Wahl des Trainings erm&ouml;glicht es dir, deinen Hund besser beurteilen zu k&ouml;nnen. Schnell wirst du den Charakter deines Hundes besser einsch&auml;tzen k&ouml;nnen. Wie kreativ ist er? Wie geht er mit Konflikten um? Ist er selbstbewusst oder unsicher? Versuche die Aufgabenstellungen zu variieren, so stellst du sicher, dass dein Vierbeiner nicht durch erlernte Muster zum Ziel oder zur L&ouml;sung kommt, sondern immer wieder neue Strategien anwenden muss. Die folgenden Anregungen k&ouml;nnen dir dabei helfen, die Talente deines tierischen Lieblings zu entdecken und zu f&ouml;rdern.<\/p>\n<h3 id=\"verstecken-spielen\">Verstecken spielen<\/h3>\n<p>Lasse von einem Freund das Lieblingsspielzeug vor den Augen des Hundes verschwinden. Anschlie&szlig;end kommst du in den Raum und regst deinen Hund dazu an, sein Spielzeug zu suchen. Ein aufgeweckter Vierbeiner wird dich zu seinem Spielzeug f&uuml;hren und dich auf das Versteck aufmerksam machen.<\/p>\n<h3 id=\"leckerli-zeit\">Leckerli-Zeit<\/h3>\n<p>Baue zwei <a href=\"\/hund\/hundefutter\/hundesnacks\/\">Leckerli<\/a> T&uuml;rme. Einer der beiden H&auml;ufchen sollte h&ouml;her sein. Ein pfiffiger Hund wird den Unterschied sofort bemerken und sich zielgerichtet auf die gr&ouml;&szlig;ere Leckerli Ration st&uuml;rzen.<\/p>\n<h3 id=\"htchenspiel\">H&uuml;tchenspiel<\/h3>\n<p>Fast jeder hat schon mal vom H&uuml;tchenspiel geh&ouml;rt. Auch mit deinem Hund kannst du es spielen. Nehme drei H&uuml;tchen zur Hand und verstecke unter einem H&uuml;tchen das Lieblingsleckerli deines Hundes. Nun verschiebst du die H&uuml;tchen. Hat dein Hund das richtige H&uuml;tchen mit dem Leckerli ausfindig gemacht?<\/p>\n<h3 id=\"mbel-spiel\">M&ouml;bel-Spiel<\/h3>\n<p>Schicke deinen Hund aus dem Raum und verschiebe in seiner Abwesenheit die M&ouml;bel. Lasse deinen Hund wieder in den Raum und beobachte seine Reaktion. Wenn dein Hund die Unterschiede wahrnimmt und schn&uuml;ffelnd durch den Raum geht, ist er besonders aufmerksam.<\/p>\n<h3 id=\"gedchtnistraining\">Ged&auml;chtnistraining<\/h3>\n<p>Wenn dein Hund gerne <a href=\"\/hund\/hundespielzeug\/apportieren-werfen\/\">apportiert<\/a>, ist dieses Spiel genau richtig. Gehe mit deinem Hund raus und werfe ein Spielzeug von ihm. Gib ihm zu verstehen, dass er nicht nachlaufen darf. Gehe denselben Weg zur&uuml;ck und beobachte was passiert. Wird er sich an sein Spielzeug erinnern?<\/p>\n<h2 id=\"individuelle-charaktere\">Individuelle Charaktere<\/h2>\n<p>Sollte dein Hund nicht zu den Gewinnern des Rassen-Intelligenz-Ranking geh&ouml;ren, so sei nicht entmutigt. Das Ranking bildet nur Tendenzen ab. Wie bei Menschen auch, lernen auch Hunde &ndash; unabh&auml;ngig von der Rasse &ndash; unterschiedlich schnell. Ein individuelles Training f&ouml;rdert nicht nur die positive Beziehung zwischen Hund und Halter, sondern beugt auch Unterforderung und Langeweile vor.<\/p>\n<p>&nbsp;<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-1183-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-1183-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-1183-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-ente-latex-spielzeug-13cm\/1000041073\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" class=\"article__wrapper--productimage\" title=\"Trixie Ente - Latex-Spielzeug 13cm\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/feyqh4-nEoal-vb.jpg?host=ct\"\n                alt=\"Trixie Ente - Latex-Spielzeug 13cm\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Ente - Latex-Spielzeug 13cm<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    3.89 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-ente-latex-spielzeug-13cm\/1000041073\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/dokas-kau-spirale-mit-entenbrust-3-st-4x110g\/1000075481\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" class=\"article__wrapper--productimage\" title=\"Dokas Kau-Spirale mit Entenbrust 3 St. 4x110g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/g3f3o2-L5YNS5Lc.jpg?host=ct\"\n                alt=\"Dokas Kau-Spirale mit Entenbrust 3 St. 4x110g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Dokas                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Dokas Kau-Spirale mit Entenbrust 3 St. 4x110g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    16.99 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        38.61 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/dokas-kau-spirale-mit-entenbrust-3-st-4x110g\/1000075481\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/pedigree-ranchos-jerkies-mit-rind-180g\/1000107176\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" class=\"article__wrapper--productimage\" title=\"PEDIGREE Ranchos Jerkies mit Rind 180g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/dae2qt-eDnYWXFe.jpg?host=ct\"\n                alt=\"PEDIGREE Ranchos Jerkies mit Rind 180g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Pedigree                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">PEDIGREE Ranchos Jerkies mit Rind 180g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    5.39 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        29.94 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/pedigree-ranchos-jerkies-mit-rind-180g\/1000107176\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a040a63902ff\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-ente-latex-spielzeug-13cm\/1000041073\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" class=\"article__wrapper--productimage\" title=\"Trixie Ente - Latex-Spielzeug 13cm\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/feyqh4-nEoal-vb.jpg?host=ct\"\n                                    alt=\"Trixie Ente - Latex-Spielzeug 13cm\">\n\n                            <div id=\"swiper-button-next6a040a63902ff\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a040a63902ff\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Ente - Latex-Spielzeug 13cm<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                3.89 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-ente-latex-spielzeug-13cm\/1000041073\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/dokas-kau-spirale-mit-entenbrust-3-st-4x110g\/1000075481\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" class=\"article__wrapper--productimage\" title=\"Dokas Kau-Spirale mit Entenbrust 3 St. 4x110g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/g3f3o2-L5YNS5Lc.jpg?host=ct\"\n                                    alt=\"Dokas Kau-Spirale mit Entenbrust 3 St. 4x110g\">\n\n                            <div id=\"swiper-button-next6a040a63902ff\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a040a63902ff\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Dokas                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Dokas Kau-Spirale mit Entenbrust 3 St. 4x110g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                16.99 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    38.61 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/dokas-kau-spirale-mit-entenbrust-3-st-4x110g\/1000075481\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/pedigree-ranchos-jerkies-mit-rind-180g\/1000107176\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" class=\"article__wrapper--productimage\" title=\"PEDIGREE Ranchos Jerkies mit Rind 180g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/dae2qt-eDnYWXFe.jpg?host=ct\"\n                                    alt=\"PEDIGREE Ranchos Jerkies mit Rind 180g\">\n\n                            <div id=\"swiper-button-next6a040a63902ff\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a040a63902ff\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Pedigree                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">PEDIGREE Ranchos Jerkies mit Rind 180g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                5.39 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    29.94 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/pedigree-ranchos-jerkies-mit-rind-180g\/1000107176\/?icid=magproteaser_hunde_hunde-iq-scharfsinnige-vierbeiner_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a040a63902ff\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a040a63902ff\",\n                prevEl: \"#swiper-button-prev6a040a63902ff\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Der Hunde-IQ wurde lange untersch&auml;tzt. Doch viele Hundebesitzer sind sich einig, ihre Vierbeiner sind nicht nur treu, sondern auch scharfsinnig. Was Intelligenz bei Hunden genau bedeutet, wie diese sich &auml;u&szlig;ert&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":15,"featured_media":5359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,5,21],"tags":[395,396,406,397,407],"class_list":["post-1183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erziehung","category-hunde","category-training-hundesport","tag-hunde-iq","tag-hundeintelligenz","tag-hunderassen","tag-intelligenz","tag-stanley-coren"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hunde-IQ: Scharfsinnige Vierbeiner | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Das Intelligenz-Ranking von Stanley Coren beweist: der Hunde-IQ ist h\u00f6her als angenommen. Welche Rasse besonders schlau ist, liest du hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hunde-IQ: Scharfsinnige Vierbeiner\" \/>\n<meta property=\"og:description\" content=\"Das Intelligenz-Ranking von Stanley Coren beweist: der Hunde-IQ ist h\u00f6her als angenommen. Welche Rasse besonders schlau ist, liest du hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-16T14:07:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-22T16:10:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"headline\":\"Hunde-IQ: Scharfsinnige Vierbeiner\",\"datePublished\":\"2015-02-16T14:07:38+00:00\",\"dateModified\":\"2017-11-22T16:10:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/\"},\"wordCount\":1207,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/hunde-iq-760x560.jpg\",\"keywords\":[\"Hunde-IQ\",\"Hundeintelligenz\",\"Hunderassen\",\"Intelligenz\",\"Stanley Coren\"],\"articleSection\":[\"Erziehung\",\"Hunde Magazin\",\"Training &amp; Hundesport\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/\",\"name\":\"Hunde-IQ: Scharfsinnige Vierbeiner | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/hunde-iq-760x560.jpg\",\"datePublished\":\"2015-02-16T14:07:38+00:00\",\"dateModified\":\"2017-11-22T16:10:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"description\":\"Das Intelligenz-Ranking von Stanley Coren beweist: der Hunde-IQ ist h\u00f6her als angenommen. Welche Rasse besonders schlau ist, liest du hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/hunde-iq-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/hunde-iq-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"Hunde-IQ\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hunde-iq-scharfsinnige-vierbeiner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hunde-IQ: Scharfsinnige Vierbeiner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZooRoyalDE\",\"https:\\\/\\\/x.com\\\/zooroyal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hunde-IQ: Scharfsinnige Vierbeiner | ZooRoyal Magazin","description":"Das Intelligenz-Ranking von Stanley Coren beweist: der Hunde-IQ ist h\u00f6her als angenommen. Welche Rasse besonders schlau ist, liest du hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/","og_locale":"de_DE","og_type":"article","og_title":"Hunde-IQ: Scharfsinnige Vierbeiner","og_description":"Das Intelligenz-Ranking von Stanley Coren beweist: der Hunde-IQ ist h\u00f6her als angenommen. Welche Rasse besonders schlau ist, liest du hier.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_author":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2015-02-16T14:07:38+00:00","article_modified_time":"2017-11-22T16:10:20+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"headline":"Hunde-IQ: Scharfsinnige Vierbeiner","datePublished":"2015-02-16T14:07:38+00:00","dateModified":"2017-11-22T16:10:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/"},"wordCount":1207,"commentCount":1,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg","keywords":["Hunde-IQ","Hundeintelligenz","Hunderassen","Intelligenz","Stanley Coren"],"articleSection":["Erziehung","Hunde Magazin","Training &amp; Hundesport"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/","name":"Hunde-IQ: Scharfsinnige Vierbeiner | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg","datePublished":"2015-02-16T14:07:38+00:00","dateModified":"2017-11-22T16:10:20+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"description":"Das Intelligenz-Ranking von Stanley Coren beweist: der Hunde-IQ ist h\u00f6her als angenommen. Welche Rasse besonders schlau ist, liest du hier.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/hunde-iq-760x560.jpg","width":760,"height":560,"caption":"Hunde-IQ"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunde-iq-scharfsinnige-vierbeiner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Hunde-IQ: Scharfsinnige Vierbeiner"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.facebook.com\/ZooRoyalDE","https:\/\/x.com\/zooroyal"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/1183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=1183"}],"version-history":[{"count":17,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/1183\/revisions"}],"predecessor-version":[{"id":10857,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/1183\/revisions\/10857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/5359"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=1183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=1183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=1183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}