{"id":1146,"date":"2015-02-11T15:16:10","date_gmt":"2015-02-11T13:16:10","guid":{"rendered":"https:\/\/www.zooroyal.de\/ratgeber\/?p=1146"},"modified":"2018-11-28T09:12:32","modified_gmt":"2018-11-28T08:12:32","slug":"wenn-katzen-kratzen","status":"publish","type":"post","link":"https:\/\/www.zooroyal.at\/magazin\/katzen\/wenn-katzen-kratzen\/","title":{"rendered":"Was tun wenn Katzen kratzen?"},"content":{"rendered":"<div id=\"pl-1146\" class=\"panel-layout\">\n<div id=\"pg-1146-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-1146-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-1146-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5664\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg\" alt=\"Wenn Katzen kratzen\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg 760w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/a>Katzen sind Samtpfoten &ndash; leise und leichtf&uuml;&szlig;ig tigern sie umher. Doch sie k&ouml;nnen auch anders: ihre scharfen Krallen wetzen sie mit Vorliebe am Mobiliar. Wie du deine Katze an einen Kratzbaum gew&ouml;hnst und deine Einrichtung rettest, erf&auml;hrst du hier.<!--more--><\/p>\n<h2 id=\"funktion-der-krallen-im-alltag\">Funktion der Krallen im Alltag<\/h2>\n<p>Als Raubtiere und geborene J&auml;ger sind Katzen nat&uuml;rlich auf ihre Krallen angewiesen. Mit diesen gebogenen Jagdwerkzeugen k&ouml;nnen sie ihre Beute nicht nur fangen, sondern auch festhalten. Du hast deine Katze doch bestimmt schon einmal mit einer Maus spielen sehen. Genau hier kommen diese Werkzeuge zum Einsatz. Auch im Kampf mit potentiellen Feinden k&ouml;nnen die Krallen wichtige Unterschiede zwischen Sieger und Verlierer machen. Katzenkinder nutzen das schnelle Treten mit den Hinterbeinen auch bereits im Spiel mit Herrchen, Frauchen und Artgenossen. Des Weiteren kommen die Krallen beim Klettern zum Einsatz. Wer mal eine Katze hat blitzschnell auf einen Baum flitzen sehen, der kann sich ann&auml;hernd vorstellen, wie scharf und stark sie sein m&uuml;ssen.<\/p>\n<h2 id=\"kratzende-katze-in-deinem-zuhause\">Kratzende Katze in deinem Zuhause<\/h2>\n<p>Die Krallen und das Kratzen w&uuml;rden deiner Katze also in der <a href=\"\/magazin\/katzen\/katzenrassen\/wildkatze\/\">freien Wildbahn<\/a> zum &Uuml;berleben dienen. Du fragst dich, warum sie das aber dann auch in deinem Zuhause machen muss, wo es doch gar keine Gefahr gibt? Erst einmal kann man der Katze nat&uuml;rlich nicht ihre Triebe abgew&ouml;hnen und zweitens hat das Kratzen auch noch einige weitere Gr&uuml;nde. So ist das Kratzen n&auml;mlich auch eine echte Sch&ouml;nheitskur f&uuml;r die Samtpfote. Durch das Kratzen schleift sie die oberen Krallenschichten, Dreck und Schmutz ab und k&uuml;mmert sich somit um Sch&ouml;nheit und <a href=\"\/magazin\/katzen\/katzenkrankheiten\/\">Gesundheit<\/a>. Die Krallen der Hinterpfoten werden von ihr &uuml;brigens mit den Z&auml;hnen gereinigt.<\/p>\n<p>Ein weiterer Grund ist das Revierverhalten deines Lieblings. Katzen geben beim Kratzen Pheromone aus ihren Fu&szlig;ballen ab, die nur andere Katzen wahrnehmen k&ouml;nnen. Diese Lockstoffe oder auch Duftmarkierungen haben keine gro&szlig;e Reichweite und halten sich auch nicht lange. Deshalb kratzen Katzen auch oft immer wieder am selben Baum. Sie sagen somit &bdquo;Hier ist mein Revier, halte dich fern!&ldquo; Das Kratzen ist also auch Imponiergehabe.<\/p>\n<p>Das will sie nat&uuml;rlich auch in ihrer Wohnung deutlich machen. Die Kratzspuren zeigen deutlich, wer hier der Boss ist. Es geh&ouml;rt f&uuml;r die Katze zum Komfort und macht ihr nebenbei auch einfach Spa&szlig;. Auch genie&szlig;en die Katzen es, wenn man ihnen dabei zusieht. Deshalb kratzen sie immer an gut sichtbaren Stellen, in der N&auml;he von <a href=\"\/katze\/katzenschlafplaetze\/\">Schlaf- und Ruhepl&auml;tzen<\/a> oder dort, wo sie sich mit anderen Katzen trifft. Kratzt die Katze in der Anwesenheit von Menschen, so demonstriert sie, wie wichtig sie ist und zeigt dadurch ihre individuelle Pers&ouml;nlichkeit. Man sollte sich also durchaus auch geehrt f&uuml;hlen. Unter Umst&auml;nden kann auch Langeweile der Grund f&uuml;r das Kratzen sein. Stelle sicher, dass deine Katze ausreichend Besch&auml;ftigungsm&ouml;glichkeiten hat, um das Kratzen zu vermeiden.<\/p>\n<h2 id=\"abhilfe-schaffen\">Abhilfe schaffen<\/h2>\n<p>Im vergangenen Abschnitt hast du gelernt, dass das Kratzen zum Verhaltensrepertoire der Katzen geh&ouml;rt. Trotzdem ist es nat&uuml;rlich &auml;u&szlig;erst &auml;rgerlich, wenn die neue Polstergarnitur und die Tapete zerkratzt sind. Es sieht unsch&ouml;n aus und wird unter Umst&auml;nden sehr teuer. Wie kann man also Abhilfe schaffen? Zieht eine Katze ein, sollte man m&ouml;glichst sofort einen <a href=\"\/magazin\/katzen\/kratzbaum-tipps-zum-kauf\/\">Kratzbaum<\/a> anbieten. Kratzb&auml;ume gibt es in s&auml;mtlichen Farben, Formen und Gr&ouml;&szlig;en. F&uuml;r welchen du dich entscheidest, bleibt nat&uuml;rlich ganz dir &uuml;berlassen. Er sollte allerdings gen&uuml;gend M&ouml;glichkeiten zum Kratzen bieten. Oft sind auch mit Sisal umwickelte Kratzst&auml;mme integriert, auch sogenannte <a href=\"\/katze\/kratzmoebel\/kratzbretter-kratzwellen\/\">Kratzbretter<\/a> k&ouml;nnen dabei sein. Was zu beachten ist: Der Kratzbaum sollte mindestens so hoch sein, wie die Katze lang ist, da Katzen es lieben, sich beim Kratzen komplett zu strecken. Sollte man sich gegen einen Kratzbaum entscheiden, so k&ouml;nnte man es auch mit einem gro&szlig;en Ast aus der Natur versuchen.<\/p>\n<p>Oft kommt es vor, dass die Katze den Kratzbaum anfangs ignoriert. Vielleicht versteht sie seine Funktion nicht oder bevorzugt doch lieber den neuen Sessel? Dies k&ouml;nnte damit zu begr&uuml;nden sein, dass der Kratzbaum an der falschen Stelle steht. Wie oben bereits erw&auml;hnt, liebt die Katze es, sich w&auml;hrend des Kratzens zu pr&auml;sentieren. Deshalb sollte der Kratzbaum auch m&ouml;glichst zentral platziert sein. Du k&ouml;nntest auch eine Schnur oder ein Spielzeug daran befestigen und ihr beim Spielen zuschauen. Sch&auml;rft sie sich dann in der einen Situation am Baum die Krallen, so solltest du sie mit Leckerlis belohnen! Sie wird es sich f&uuml;r das n&auml;chste Mal merken. Erwischt du sie dabei, dass sie die Sch&ouml;nheitspflege wieder am Sofa betreiben will, so schnappe sie dir und trage sie zum Baum. Mit der Zeit wird sie es verstehen. Ein weiterer Trick w&auml;re, die ungewollten Kratzpl&auml;tze mit kleinen &bdquo;Fallen&ldquo; auszustatten. F&auml;llt bei Ber&uuml;hrung beispielsweise eine leere, aber ger&auml;uschvolle Blechdose hinab, so wird sich deine Katze beim n&auml;chsten Mal genau &uuml;berlegen, ob sie diese Ger&auml;uschkulisse noch einmal erleben m&ouml;chte.<\/p>\n<p>Manche Katzen kratzen hingegen einfach lieber auf dem Boden. Solltest du also beobachten, dass sie die Krallen &uuml;ber den Boden zieht, so kaufe ihr doch ein Kratzbrett. Das kann man auf den Boden legen und die Samtpfote zerst&ouml;rt weder Teppich noch Dielen.<\/p>\n<h2 id=\"ein-wichtiger-unterschied\">Ein wichtiger Unterschied<\/h2>\n<p>Ein ganz wichtiger Unterschied muss auch zwischen Kratzen und dem sogenannten Treteln gemacht werden, um eine ungerechte Behandlung deines Lieblings zu vermeiden. Springt die Katze auf deinen Scho&szlig; und f&auml;ngt an auf dir herumzutreteln, so kann das manchmal auch mit Kralleneinsatz kombiniert sein. Sie meint es aber nicht b&ouml;se: Ganz im Gegenteil! Es ist ein echter Liebesbeweis! Es handelt sich bei diesem Verhalten um den sogenannten Milchtritt, den Kitten einsetzen, wenn sie am Bauch der Mutter Milch trinken. Durch das &bdquo;Treteln&ldquo; regen sie den Milchfluss an. Setzt die Katze das bei dir ein, so sagt sie dir damit, dass sie sich bei dir wohlf&uuml;hlt!<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-1146-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-1146-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-1146-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/d-d-home-phil-napfunterlage-beige-35-x-20-x-1-cm\/1000109789\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" class=\"article__wrapper--productimage\" title=\"DundD Home Phil Napfunterlage beige 35 x 20 x 1 cm\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/w5wtor-8d_tCZ1h.jpg?host=ct\"\n                alt=\"DundD Home Phil Napfunterlage beige 35 x 20 x 1 cm\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    D&amp;D                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">DundD Home Phil Napfunterlage beige 35 x 20 x 1 cm<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    6.69 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/d-d-home-phil-napfunterlage-beige-35-x-20-x-1-cm\/1000109789\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-pfotenpflege-spray-50-ml\/1000014081\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" class=\"article__wrapper--productimage\" title=\"Trixie Pfotenpflege-Spray 50 ml\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/x3lnuc-H860N16y.jpg?host=ct\"\n                alt=\"Trixie Pfotenpflege-Spray 50 ml\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Trixie                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Pfotenpflege-Spray 50 ml<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    3.49 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        69.80 \u20ac \/ 1 l                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-pfotenpflege-spray-50-ml\/1000014081\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.at\/p\/felisept-ohrpflege-finger-pads-fuer-katzen-50-stueck\/1000107478\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" class=\"article__wrapper--productimage\" title=\"Felisept Ohrpflege Finger-Pads f\u00fcr Katzen 50 St\u00fcck\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/taypuf-ASQwTzAC.jpg?host=ct\"\n                alt=\"Felisept Ohrpflege Finger-Pads f\u00fcr Katzen 50 St\u00fcck\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Felisept                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Felisept Ohrpflege Finger-Pads f\u00fcr Katzen 50 St\u00fcck<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    10.69 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/felisept-ohrpflege-finger-pads-fuer-katzen-50-stueck\/1000107478\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a04fc55f30e6\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/d-d-home-phil-napfunterlage-beige-35-x-20-x-1-cm\/1000109789\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" class=\"article__wrapper--productimage\" title=\"DundD Home Phil Napfunterlage beige 35 x 20 x 1 cm\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/w5wtor-8d_tCZ1h.jpg?host=ct\"\n                                    alt=\"DundD Home Phil Napfunterlage beige 35 x 20 x 1 cm\">\n\n                            <div id=\"swiper-button-next6a04fc55f30e6\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04fc55f30e6\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                D&amp;D                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">DundD Home Phil Napfunterlage beige 35 x 20 x 1 cm<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                6.69 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/d-d-home-phil-napfunterlage-beige-35-x-20-x-1-cm\/1000109789\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/trixie-pfotenpflege-spray-50-ml\/1000014081\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" class=\"article__wrapper--productimage\" title=\"Trixie Pfotenpflege-Spray 50 ml\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/x3lnuc-H860N16y.jpg?host=ct\"\n                                    alt=\"Trixie Pfotenpflege-Spray 50 ml\">\n\n                            <div id=\"swiper-button-next6a04fc55f30e6\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04fc55f30e6\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Trixie                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Trixie Pfotenpflege-Spray 50 ml<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                3.49 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    69.80 \u20ac \/ 1 l                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/trixie-pfotenpflege-spray-50-ml\/1000014081\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.at\/p\/felisept-ohrpflege-finger-pads-fuer-katzen-50-stueck\/1000107478\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" class=\"article__wrapper--productimage\" title=\"Felisept Ohrpflege Finger-Pads f\u00fcr Katzen 50 St\u00fcck\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/taypuf-ASQwTzAC.jpg?host=ct\"\n                                    alt=\"Felisept Ohrpflege Finger-Pads f\u00fcr Katzen 50 St\u00fcck\">\n\n                            <div id=\"swiper-button-next6a04fc55f30e6\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04fc55f30e6\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Felisept                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Felisept Ohrpflege Finger-Pads f\u00fcr Katzen 50 St\u00fcck<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                10.69 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.at\/p\/felisept-ohrpflege-finger-pads-fuer-katzen-50-stueck\/1000107478\/?icid=magproteaser_katzen_wenn-katzen-kratzen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a04fc55f30e6\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a04fc55f30e6\",\n                prevEl: \"#swiper-button-prev6a04fc55f30e6\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Katzen sind Samtpfoten &ndash; leise und leichtf&uuml;&szlig;ig tigern sie umher. Doch sie k&ouml;nnen auch anders: ihre scharfen Krallen wetzen sie mit Vorliebe am Mobiliar. Wie du deine Katze an einen&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.at\/magazin\/katzen\/wenn-katzen-kratzen\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":15,"featured_media":5664,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,6],"tags":[465,380,475,381,85],"class_list":["post-1146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit-pflege-katzen","category-katzen","tag-katzenerziehung","tag-kratzbaum","tag-kratzmoebel","tag-kratzspuren","tag-pfotenpflege"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Was tun wenn Katzen kratzen? | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Was kann man tun, wenn Katzen kratzen, ihre Krallen an den M\u00f6beln wetzen? Alles was du \u00fcbers Kratzen und Treteln wissen musst, hier bei uns..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/katzen\/wenn-katzen-kratzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was tun wenn Katzen kratzen?\" \/>\n<meta property=\"og:description\" content=\"Was kann man tun, wenn Katzen kratzen, ihre Krallen an den M\u00f6beln wetzen? Alles was du \u00fcbers Kratzen und Treteln wissen musst, hier bei uns..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-11T13:16:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-28T08:12:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"headline\":\"Was tun wenn Katzen kratzen?\",\"datePublished\":\"2015-02-11T13:16:10+00:00\",\"dateModified\":\"2018-11-28T08:12:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/\"},\"wordCount\":1094,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/wenn-katzen-kratzen-760x560.jpg\",\"keywords\":[\"Katzenerziehung\",\"Kratzbaum\",\"Kratzm\u00f6bel\",\"Kratzspuren\",\"Pfotenpflege\"],\"articleSection\":[\"Gesundheit &amp; Pflege\",\"Katzen Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/\",\"name\":\"Was tun wenn Katzen kratzen? | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/wenn-katzen-kratzen-760x560.jpg\",\"datePublished\":\"2015-02-11T13:16:10+00:00\",\"dateModified\":\"2018-11-28T08:12:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\"},\"description\":\"Was kann man tun, wenn Katzen kratzen, ihre Krallen an den M\u00f6beln wetzen? Alles was du \u00fcbers Kratzen und Treteln wissen musst, hier bei uns..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/wenn-katzen-kratzen-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.at\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/wenn-katzen-kratzen-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"Wenn Katzen kratzen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/katzen\\\/wenn-katzen-kratzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was tun wenn Katzen kratzen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/a02f14b2930e16b6bbee4836c661c922\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_15_1558596452-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ZooRoyalDE\",\"https:\\\/\\\/x.com\\\/zooroyal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Was tun wenn Katzen kratzen? | ZooRoyal Magazin","description":"Was kann man tun, wenn Katzen kratzen, ihre Krallen an den M\u00f6beln wetzen? Alles was du \u00fcbers Kratzen und Treteln wissen musst, hier bei uns..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/katzen\/wenn-katzen-kratzen\/","og_locale":"de_DE","og_type":"article","og_title":"Was tun wenn Katzen kratzen?","og_description":"Was kann man tun, wenn Katzen kratzen, ihre Krallen an den M\u00f6beln wetzen? Alles was du \u00fcbers Kratzen und Treteln wissen musst, hier bei uns..","og_url":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_author":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2015-02-11T13:16:10+00:00","article_modified_time":"2018-11-28T08:12:32+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"headline":"Was tun wenn Katzen kratzen?","datePublished":"2015-02-11T13:16:10+00:00","dateModified":"2018-11-28T08:12:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/"},"wordCount":1094,"commentCount":2,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg","keywords":["Katzenerziehung","Kratzbaum","Kratzm\u00f6bel","Kratzspuren","Pfotenpflege"],"articleSection":["Gesundheit &amp; Pflege","Katzen Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/","url":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/","name":"Was tun wenn Katzen kratzen? | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg","datePublished":"2015-02-11T13:16:10+00:00","dateModified":"2018-11-28T08:12:32+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922"},"description":"Was kann man tun, wenn Katzen kratzen, ihre Krallen an den M\u00f6beln wetzen? Alles was du \u00fcbers Kratzen und Treteln wissen musst, hier bei uns..","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#primaryimage","url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2015\/02\/wenn-katzen-kratzen-760x560.jpg","width":760,"height":560,"caption":"Wenn Katzen kratzen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/katzen\/wenn-katzen-kratzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Was tun wenn Katzen kratzen?"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/a02f14b2930e16b6bbee4836c661c922","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_15_1558596452-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.facebook.com\/ZooRoyalDE","https:\/\/x.com\/zooroyal"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/1146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/comments?post=1146"}],"version-history":[{"count":15,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/1146\/revisions"}],"predecessor-version":[{"id":15121,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts\/1146\/revisions\/15121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media\/5664"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/media?parent=1146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories?post=1146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/tags?post=1146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}