{"id":6464,"count":8,"description":"","link":"https:\/\/www.zooroyal.at\/magazin\/wildtiere\/bienen-insekten\/","name":"Bienen und Insekten","slug":"bienen-insekten","taxonomy":"category","parent":6447,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bienen und Insekten: Infos, Tipps und Tricks<\/title>\n<meta name=\"description\" content=\"Zu den Wildtieren im Garten geh\u00f6ren auch Bienen und Insekten. Erfahre alles, dar\u00fcber wie du sie unterst\u00fctzen kannst und was Bienen zum Leben brauchen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.at\/magazin\/wildtiere\/bienen-insekten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienen und Insekten Archive\" \/>\n<meta property=\"og:description\" content=\"Zu den Wildtieren im Garten geh\u00f6ren auch Bienen und Insekten. Erfahre alles, dar\u00fcber wie du sie unterst\u00fctzen kannst und was Bienen zum Leben brauchen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/wildtiere\/bienen-insekten\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wildtiere\\\/bienen-insekten\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wildtiere\\\/bienen-insekten\\\/\",\"name\":\"Bienen und Insekten: Infos, Tipps und Tricks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"description\":\"Zu den Wildtieren im Garten geh\u00f6ren auch Bienen und Insekten. Erfahre alles, dar\u00fcber wie du sie unterst\u00fctzen kannst und was Bienen zum Leben brauchen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wildtiere\\\/bienen-insekten\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wildtiere\\\/bienen-insekten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wildtiere\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wildtiere\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bienen und Insekten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bienen und Insekten: Infos, Tipps und Tricks","description":"Zu den Wildtieren im Garten geh\u00f6ren auch Bienen und Insekten. Erfahre alles, dar\u00fcber wie du sie unterst\u00fctzen kannst und was Bienen zum Leben brauchen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.at\/magazin\/wildtiere\/bienen-insekten\/","og_locale":"de_DE","og_type":"article","og_title":"Bienen und Insekten Archive","og_description":"Zu den Wildtieren im Garten geh\u00f6ren auch Bienen und Insekten. Erfahre alles, dar\u00fcber wie du sie unterst\u00fctzen kannst und was Bienen zum Leben brauchen.","og_url":"https:\/\/www.zooroyal.de\/magazin\/wildtiere\/bienen-insekten\/","og_site_name":"ZooRoyal Magazin","twitter_card":"summary_large_image","twitter_site":"@zooroyal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.zooroyal.de\/magazin\/wildtiere\/bienen-insekten\/","url":"https:\/\/www.zooroyal.de\/magazin\/wildtiere\/bienen-insekten\/","name":"Bienen und Insekten: Infos, Tipps und Tricks","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"description":"Zu den Wildtieren im Garten geh\u00f6ren auch Bienen und Insekten. Erfahre alles, dar\u00fcber wie du sie unterst\u00fctzen kannst und was Bienen zum Leben brauchen.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/wildtiere\/bienen-insekten\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/wildtiere\/bienen-insekten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Wildtiere","item":"https:\/\/www.zooroyal.de\/magazin\/wildtiere\/"},{"@type":"ListItem","position":3,"name":"Bienen und Insekten"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories\/6464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/categories\/6447"}],"wp:post_type":[{"href":"https:\/\/www.zooroyal.at\/magazin\/wp-json\/wp\/v2\/posts?categories=6464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}